{"id":36532,"date":"2026-09-02T06:00:05","date_gmt":"2026-09-01T23:00:05","guid":{"rendered":"https:\/\/www.naewna.com\/n\/?p=36532"},"modified":"2026-09-01T12:47:31","modified_gmt":"2026-09-01T05:47:31","slug":"%e0%b8%a0%e0%b8%b9%e0%b9%82%e0%b8%84%e0%b8%a5%e0%b8%99-%e0%b8%aa%e0%b8%9b%e0%b8%b2%e0%b8%9e%e0%b8%a3%e0%b8%b5%e0%b9%80%e0%b8%a1%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a1%e0%b8%ab%e0%b8%99","status":"publish","type":"post","link":"https:\/\/www.naewna.com\/n\/national-news\/36532\/","title":{"rendered":"\u201c\u0e20\u0e39\u0e42\u0e04\u0e25\u0e19\u201d \u0e2a\u0e1b\u0e32\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27\u0e43\u0e19\u0e41\u0e21\u0e48\u0e2e\u0e48\u0e2d\u0e07\u0e2a\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e19\u0e31\u0e01\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e44\u0e21\u0e48\u0e04\u0e27\u0e23\u0e1e\u0e25\u0e32\u0e14"},"content":{"rendered":"\r\n<div class=\"vce-row-container\" data-vce-boxed-width=\"true\">\r\n<div id=\"el-13185f58\" class=\"vce-row vce-row--col-gap-30 vce-row-equal-height vce-row-content--top\" data-vce-do-apply=\"all el-13185f58\">\r\n<div class=\"vce-row-content\" data-vce-element-content=\"true\">\r\n<div id=\"el-d800e1cd\" class=\"vce-col vce-col--md-auto vce-col--xs-1 vce-col--xs-last vce-col--xs-first vce-col--sm-last vce-col--sm-first vce-col--md-last vce-col--lg-last vce-col--xl-last vce-col--md-first vce-col--lg-first vce-col--xl-first\">\r\n<div class=\"vce-col-inner\" data-vce-do-apply=\"border margin background  el-d800e1cd\">\r\n<div class=\"vce-col-content\" data-vce-element-content=\"true\" data-vce-do-apply=\"padding el-d800e1cd\">\r\n<div class=\"vce-single-image-container vce-single-image--align-left\">\r\n<div id=\"el-01af1b8d\" class=\"vce vce-single-image-wrapper\" data-vce-do-apply=\"all el-01af1b8d\">\r\n<figure>\r\n<div class=\"vce-single-image-figure-inner\" style=\"width: 1024px;\">\r\n<div class=\"vce-single-image-inner vce-single-image--absolute\" style=\"width: 100%; padding-bottom: 56.25%;\"><img loading=\"lazy\" decoding=\"async\" class=\"vce-single-image\" title=\"\u0e20\u0e39\u0e42\u0e04\u0e25\u0e19\" src=\"https:\/\/storage-wp.naewna.com\/2026\/09\/\u0e20\u0e39\u0e42\u0e04\u0e25\u0e19.jpg\" alt=\"\" width=\"1024\" height=\"576\" data-img-src=\"https:\/\/storage-wp.naewna.com\/2026\/09\/\u0e20\u0e39\u0e42\u0e04\u0e25\u0e19.jpg\" data-attachment-id=\"36533\" \/><\/div>\r\n<\/div>\r\n<figcaption hidden=\"\"><\/figcaption>\r\n<\/figure>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n\r\n<div class=\"vce-row-container\" data-vce-boxed-width=\"true\">\r\n<div id=\"el-93766873\" class=\"vce-row vce-row--col-gap-30 vce-row-equal-height vce-row-content--top\" data-vce-do-apply=\"all el-93766873\">\r\n<div class=\"vce-row-content\" data-vce-element-content=\"true\">\r\n<div id=\"el-6e69f99c\" class=\"vce-col vce-col--md-auto vce-col--xs-1 vce-col--xs-last vce-col--xs-first vce-col--sm-last vce-col--sm-first vce-col--md-last vce-col--lg-last vce-col--xl-last vce-col--md-first vce-col--lg-first vce-col--xl-first\">\r\n<div class=\"vce-col-inner\" data-vce-do-apply=\"border margin background  el-6e69f99c\">\r\n<div class=\"vce-col-content\" data-vce-element-content=\"true\" data-vce-do-apply=\"padding el-6e69f99c\">\r\n<div class=\"vce-text-block\">\r\n<div id=\"el-7d65fdff\" class=\"vce-text-block-wrapper vce\" data-vce-do-apply=\"all el-7d65fdff\">\r\n<p>\u0e1c\u0e39\u0e49\u0e2a\u0e37\u0e48\u0e2d\u0e02\u0e48\u0e32\u0e27\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e27\u0e48\u0e32 \u0e19\u0e32\u0e22\u0e20\u0e32\u0e19\u0e38\u0e40\u0e14\u0e0a\u00a0\u0e44\u0e0a\u0e22\u0e2a\u0e01\u0e39\u0e25 \u0e19\u0e32\u0e22\u0e01\u0e2a\u0e21\u0e32\u0e04\u0e21\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e2a\u0e20\u0e32\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e41\u0e21\u0e48\u0e2e\u0e48\u0e2d\u0e07\u0e2a\u0e2d\u0e19 \u0e19\u0e33\u0e2d\u0e34\u0e19\u0e1f\u0e39\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e0b\u0e2d\u0e23\u0e4c \u0e41\u0e25\u0e30 \u0e1a\u0e25\u0e47\u0e2d\u0e01\u0e40\u0e01\u0e2d\u0e23\u0e4c\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e41\u0e21\u0e48\u0e2e\u0e48\u0e2d\u0e07\u0e2a\u0e2d\u0e19 \u0e21\u0e32\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e20\u0e39\u0e42\u0e04\u0e25\u0e19 \u0e41\u0e2b\u0e25\u0e48\u0e07\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e2a\u0e1b\u0e32 \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21 \u0e2b\u0e19\u0e36\u0e48\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27\u0e43\u0e19\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e41\u0e21\u0e48\u0e2e\u0e48\u0e2d\u0e07\u0e2a\u0e2d\u0e19 \u0e17\u0e35\u0e48\u0e19\u0e31\u0e01\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e43\u0e19\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e41\u0e21\u0e48\u0e2e\u0e48\u0e2d\u0e07\u0e2a\u0e2d\u0e19 \u0e44\u0e21\u0e48\u0e04\u0e27\u0e23\u0e1e\u0e25\u0e32\u0e14 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e1c\u0e48\u0e32\u0e19\u0e17\u0e35\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e23\u0e31\u0e01\u0e44\u0e17\u0e22\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e37\u0e48\u0e2d\u0e14\u0e31\u0e07 \u0e19\u0e31\u0e01\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e08\u0e30\u0e44\u0e14\u0e49\u0e21\u0e32\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a \u0e41\u0e2b\u0e25\u0e48\u0e07\u0e42\u0e04\u0e25\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e0a\u0e37\u0e48\u0e2d\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19\u0e2a\u0e32\u0e21\u0e02\u0e2d\u0e07\u0e42\u0e25\u0e01 \u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48\u0e41\u0e21\u0e48\u0e2e\u0e48\u0e2d\u0e07\u0e2a\u0e2d\u0e19\u0e19\u0e35\u0e49<\/p>\r\n<p>\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e20\u0e39\u0e42\u0e04\u0e25\u0e19\u0e1a\u0e2d\u0e01\u0e27\u0e48\u0e32 \u0e15\u0e23\u0e07\u0e19\u0e35\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e2d\u0e01\u0e42\u0e04\u0e25\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e21\u0e02\u0e2d\u0e07 \u0e20\u0e39\u0e42\u0e04\u0e25\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e15\u0e31\u0e27 \u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e08\u0e30\u0e44\u0e14\u0e49\u0e1e\u0e2d\u0e01\u0e42\u0e04\u0e25\u0e19\u0e17\u0e31\u0e49\u0e07\u0e15\u0e31\u0e27 \u0e19\u0e27\u0e14 \u0e2a\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e41\u0e0a\u0e48\u0e2d\u0e48\u0e32\u0e07\u0e19\u0e49\u0e33\u0e41\u0e23\u0e48\u0e2a\u0e48\u0e27\u0e19\u0e15\u0e31\u0e27 \u0e43\u0e0a\u0e49\u0e40\u0e27\u0e25\u0e32\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 2 \u0e0a\u0e31\u0e48\u0e27 \u0e42\u0e21\u0e07 \u0e0b\u0e36\u0e48\u0e07\u0e23\u0e32\u0e04\u0e32\u0e23\u0e27\u0e21\u0e17\u0e38\u0e01\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e41\u0e25\u0e49\u0e27\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e41\u0e04\u0e48 1,400 \u0e1a\u0e32\u0e17\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e21\u0e35\u0e0a\u0e38\u0e14\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e43\u0e2b\u0e49\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 \u0e17\u0e48\u0e32\u0e19\u0e08\u0e30\u0e44\u0e14\u0e49\u0e1c\u0e48\u0e2d\u0e19\u0e04\u0e25\u0e32\u0e22\u0e41\u0e25\u0e30\u0e44\u0e14\u0e49\u0e04\u0e27\u0e32\u0e21\u0e0a\u0e38\u0e48\u0e21\u0e0a\u0e37\u0e49\u0e19\u0e08\u0e32\u0e01\u0e42\u0e04\u0e25\u0e19\u0e41\u0e25\u0e30\u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14<\/p>\r\n<p>\u0e19\u0e32\u0e22\u0e20\u0e32\u0e19\u0e38\u0e40\u0e14\u0e0a\u00a0 \u0e44\u0e0a\u0e22\u0e2a\u0e01\u0e39\u0e25 \u0e19\u0e32\u0e22\u0e01\u0e2a\u0e21\u0e32\u0e04\u0e21\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e2a\u0e20\u0e32\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e41\u0e21\u0e48\u0e2e\u0e48\u0e2d\u0e07\u0e2a\u0e2d\u0e19 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32 \u0e41\u0e2b\u0e25\u0e48\u0e07\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e20\u0e39\u0e42\u0e04\u0e25\u0e19\u0e41\u0e2b\u0e48\u0e07\u0e19\u0e35\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27\u0e43\u0e19\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e41\u0e21\u0e48\u0e2e\u0e48\u0e2d\u0e07\u0e2a\u0e2d\u0e19 \u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e2d\u0e01\u0e42\u0e04\u0e25\u0e19\u0e19\u0e27\u0e14\u0e2b\u0e19\u0e49\u0e32\u0e02\u0e31\u0e14\u0e2b\u0e19\u0e49\u0e32 \u0e41\u0e0a\u0e48\u0e40\u0e17\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e22\u0e31\u0e07\u0e21\u0e35\u0e19\u0e49\u0e33\u0e41\u0e23\u0e48\u0e43\u0e2b\u0e49\u0e19\u0e31\u0e01\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e44\u0e14\u0e49 \u0e41\u0e0a\u0e48 \u0e41\u0e1a\u0e1a\u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e47\u0e01\u0e2b\u0e49\u0e2d\u0e07\u0e43\u0e2b\u0e0d\u0e48 \u0e2b\u0e23\u0e37\u0e2d \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21 \u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e15\u0e31\u0e27\u0e43\u0e19\u0e23\u0e32\u0e04\u0e32\u0e17\u0e35\u0e48\u0e08\u0e31\u0e1a\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e41\u0e25\u0e30\u0e22\u0e48\u0e2d\u0e21\u0e40\u0e22\u0e32<\/p>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n\n","protected":false},"excerpt":{"rendered":"<p>\u0e1c\u0e39\u0e49\u0e2a\u0e37\u0e48\u0e2d\u0e02\u0e48\u0e32\u0e27\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e27\u0e48\u0e32 \u0e19\u0e32\u0e22\u0e20\u0e32\u0e19\u0e38\u0e40\u0e14\u0e0a\u00a0\u0e44\u0e0a\u0e22\u0e2a\u0e01\u0e39\u0e25 \u0e19\u0e32\u0e22\u0e01\u0e2a\u0e21\u0e32\u0e04\u0e21\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[337,9],"tags":[],"class_list":["post-36532","post","type-post","status-publish","format-standard","hentry","category-region-news","category-national-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u201c\u0e20\u0e39\u0e42\u0e04\u0e25\u0e19\u201d \u0e2a\u0e1b\u0e32\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27\u0e43\u0e19\u0e41\u0e21\u0e48\u0e2e\u0e48\u0e2d\u0e07\u0e2a\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e19\u0e31\u0e01\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e44\u0e21\u0e48\u0e04\u0e27\u0e23\u0e1e\u0e25\u0e32\u0e14 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.naewna.com\/n\/national-news\/36532\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201c\u0e20\u0e39\u0e42\u0e04\u0e25\u0e19\u201d \u0e2a\u0e1b\u0e32\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27\u0e43\u0e19\u0e41\u0e21\u0e48\u0e2e\u0e48\u0e2d\u0e07\u0e2a\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e19\u0e31\u0e01\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e44\u0e21\u0e48\u0e04\u0e27\u0e23\u0e1e\u0e25\u0e32\u0e14\" \/>\n<meta property=\"og:description\" content=\"\u0e1c\u0e39\u0e49\u0e2a\u0e37\u0e48\u0e2d\u0e02\u0e48\u0e32\u0e27\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e27\u0e48\u0e32 \u0e19\u0e32\u0e22\u0e20\u0e32\u0e19\u0e38\u0e40\u0e14\u0e0a\u00a0\u0e44\u0e0a\u0e22\u0e2a\u0e01\u0e39\u0e25 \u0e19\u0e32\u0e22\u0e01\u0e2a\u0e21\u0e32\u0e04\u0e21\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.naewna.com\/n\/national-news\/36532\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NaewnaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2026-09-01T23:00:05+00:00\" \/>\n<meta name=\"author\" content=\"\u0e41\u0e08\u0e47\u0e04 \u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@naewna_news\" \/>\n<meta name=\"twitter:site\" content=\"@naewna_news\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u0e41\u0e08\u0e47\u0e04 \u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 \u0e19\u0e32\u0e17\u0e35\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/national-news\\\/36532\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/national-news\\\/36532\\\/\"},\"author\":{\"name\":\"\u0e41\u0e08\u0e47\u0e04 \u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#\\\/schema\\\/person\\\/4700fa0b0309acc5a9f8e2fa76d01c21\"},\"headline\":\"\u201c\u0e20\u0e39\u0e42\u0e04\u0e25\u0e19\u201d \u0e2a\u0e1b\u0e32\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27\u0e43\u0e19\u0e41\u0e21\u0e48\u0e2e\u0e48\u0e2d\u0e07\u0e2a\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e19\u0e31\u0e01\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e44\u0e21\u0e48\u0e04\u0e27\u0e23\u0e1e\u0e25\u0e32\u0e14\",\"datePublished\":\"2026-09-01T23:00:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/national-news\\\/36532\\\/\"},\"wordCount\":0,\"articleSection\":[\"\u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04\",\"\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\"],\"inLanguage\":\"th\",\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/national-news\\\/36532\\\/\",\"url\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/national-news\\\/36532\\\/\",\"name\":\"\u201c\u0e20\u0e39\u0e42\u0e04\u0e25\u0e19\u201d \u0e2a\u0e1b\u0e32\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27\u0e43\u0e19\u0e41\u0e21\u0e48\u0e2e\u0e48\u0e2d\u0e07\u0e2a\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e19\u0e31\u0e01\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e44\u0e21\u0e48\u0e04\u0e27\u0e23\u0e1e\u0e25\u0e32\u0e14 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#website\"},\"datePublished\":\"2026-09-01T23:00:05+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#\\\/schema\\\/person\\\/4700fa0b0309acc5a9f8e2fa76d01c21\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/national-news\\\/36532\\\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.naewna.com\\\/n\\\/national-news\\\/36532\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/national-news\\\/36532\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201c\u0e20\u0e39\u0e42\u0e04\u0e25\u0e19\u201d \u0e2a\u0e1b\u0e32\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27\u0e43\u0e19\u0e41\u0e21\u0e48\u0e2e\u0e48\u0e2d\u0e07\u0e2a\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e19\u0e31\u0e01\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e44\u0e21\u0e48\u0e04\u0e27\u0e23\u0e1e\u0e25\u0e32\u0e14\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#website\",\"url\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/\",\"name\":\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#\\\/schema\\\/person\\\/4700fa0b0309acc5a9f8e2fa76d01c21\",\"name\":\"\u0e41\u0e08\u0e47\u0e04 \u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/922d162a25f5a039dc17925d1092d2c27350104c33ce240ec8a9d989352001b0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/922d162a25f5a039dc17925d1092d2c27350104c33ce240ec8a9d989352001b0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/922d162a25f5a039dc17925d1092d2c27350104c33ce240ec8a9d989352001b0?s=96&d=mm&r=g\",\"caption\":\"\u0e41\u0e08\u0e47\u0e04 \u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04\"},\"url\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/author\\\/jack_065\\\/\"}]}<\/script>\n<meta property=\"article:section\" content=\"\u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04\" \/>\n<meta property=\"article:section\" content=\"\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u201c\u0e20\u0e39\u0e42\u0e04\u0e25\u0e19\u201d \u0e2a\u0e1b\u0e32\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27\u0e43\u0e19\u0e41\u0e21\u0e48\u0e2e\u0e48\u0e2d\u0e07\u0e2a\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e19\u0e31\u0e01\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e44\u0e21\u0e48\u0e04\u0e27\u0e23\u0e1e\u0e25\u0e32\u0e14 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.naewna.com\/n\/national-news\/36532\/","og_locale":"th_TH","og_type":"article","og_title":"\u201c\u0e20\u0e39\u0e42\u0e04\u0e25\u0e19\u201d \u0e2a\u0e1b\u0e32\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27\u0e43\u0e19\u0e41\u0e21\u0e48\u0e2e\u0e48\u0e2d\u0e07\u0e2a\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e19\u0e31\u0e01\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e44\u0e21\u0e48\u0e04\u0e27\u0e23\u0e1e\u0e25\u0e32\u0e14","og_description":"\u0e1c\u0e39\u0e49\u0e2a\u0e37\u0e48\u0e2d\u0e02\u0e48\u0e32\u0e27\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e27\u0e48\u0e32 \u0e19\u0e32\u0e22\u0e20\u0e32\u0e19\u0e38\u0e40\u0e14\u0e0a\u00a0\u0e44\u0e0a\u0e22\u0e2a\u0e01\u0e39\u0e25 \u0e19\u0e32\u0e22\u0e01\u0e2a\u0e21\u0e32\u0e04\u0e21\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 [&hellip;]","og_url":"https:\/\/www.naewna.com\/n\/national-news\/36532\/","og_site_name":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32","article_publisher":"https:\/\/www.facebook.com\/NaewnaOnline","article_published_time":"2026-09-01T23:00:05+00:00","author":"\u0e41\u0e08\u0e47\u0e04 \u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04","twitter_card":"summary_large_image","twitter_creator":"@naewna_news","twitter_site":"@naewna_news","twitter_misc":{"Written by":"\u0e41\u0e08\u0e47\u0e04 \u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04","Est. reading time":"1 \u0e19\u0e32\u0e17\u0e35"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.naewna.com\/n\/national-news\/36532\/#article","isPartOf":{"@id":"https:\/\/www.naewna.com\/n\/national-news\/36532\/"},"author":{"name":"\u0e41\u0e08\u0e47\u0e04 \u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04","@id":"https:\/\/www.naewna.com\/n\/#\/schema\/person\/4700fa0b0309acc5a9f8e2fa76d01c21"},"headline":"\u201c\u0e20\u0e39\u0e42\u0e04\u0e25\u0e19\u201d \u0e2a\u0e1b\u0e32\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27\u0e43\u0e19\u0e41\u0e21\u0e48\u0e2e\u0e48\u0e2d\u0e07\u0e2a\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e19\u0e31\u0e01\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e44\u0e21\u0e48\u0e04\u0e27\u0e23\u0e1e\u0e25\u0e32\u0e14","datePublished":"2026-09-01T23:00:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.naewna.com\/n\/national-news\/36532\/"},"wordCount":0,"articleSection":["\u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04","\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28"],"inLanguage":"th","copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/www.naewna.com\/n\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.naewna.com\/n\/national-news\/36532\/","url":"https:\/\/www.naewna.com\/n\/national-news\/36532\/","name":"\u201c\u0e20\u0e39\u0e42\u0e04\u0e25\u0e19\u201d \u0e2a\u0e1b\u0e32\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27\u0e43\u0e19\u0e41\u0e21\u0e48\u0e2e\u0e48\u0e2d\u0e07\u0e2a\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e19\u0e31\u0e01\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e44\u0e21\u0e48\u0e04\u0e27\u0e23\u0e1e\u0e25\u0e32\u0e14 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32","isPartOf":{"@id":"https:\/\/www.naewna.com\/n\/#website"},"datePublished":"2026-09-01T23:00:05+00:00","author":{"@id":"https:\/\/www.naewna.com\/n\/#\/schema\/person\/4700fa0b0309acc5a9f8e2fa76d01c21"},"breadcrumb":{"@id":"https:\/\/www.naewna.com\/n\/national-news\/36532\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.naewna.com\/n\/national-news\/36532\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.naewna.com\/n\/national-news\/36532\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.naewna.com\/n\/"},{"@type":"ListItem","position":2,"name":"\u201c\u0e20\u0e39\u0e42\u0e04\u0e25\u0e19\u201d \u0e2a\u0e1b\u0e32\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27\u0e43\u0e19\u0e41\u0e21\u0e48\u0e2e\u0e48\u0e2d\u0e07\u0e2a\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e19\u0e31\u0e01\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e44\u0e21\u0e48\u0e04\u0e27\u0e23\u0e1e\u0e25\u0e32\u0e14"}]},{"@type":"WebSite","@id":"https:\/\/www.naewna.com\/n\/#website","url":"https:\/\/www.naewna.com\/n\/","name":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.naewna.com\/n\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"},{"@type":"Person","@id":"https:\/\/www.naewna.com\/n\/#\/schema\/person\/4700fa0b0309acc5a9f8e2fa76d01c21","name":"\u0e41\u0e08\u0e47\u0e04 \u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04","image":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/secure.gravatar.com\/avatar\/922d162a25f5a039dc17925d1092d2c27350104c33ce240ec8a9d989352001b0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/922d162a25f5a039dc17925d1092d2c27350104c33ce240ec8a9d989352001b0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/922d162a25f5a039dc17925d1092d2c27350104c33ce240ec8a9d989352001b0?s=96&d=mm&r=g","caption":"\u0e41\u0e08\u0e47\u0e04 \u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04"},"url":"https:\/\/www.naewna.com\/n\/author\/jack_065\/"}]}},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/posts\/36532","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/comments?post=36532"}],"version-history":[{"count":2,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/posts\/36532\/revisions"}],"predecessor-version":[{"id":36538,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/posts\/36532\/revisions\/36538"}],"wp:attachment":[{"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/media?parent=36532"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/categories?post=36532"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/tags?post=36532"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}