{"id":38405,"date":"2026-09-02T10:53:27","date_gmt":"2026-09-02T03:53:27","guid":{"rendered":"https:\/\/www.naewna.com\/n\/?p=38405"},"modified":"2026-09-02T10:53:28","modified_gmt":"2026-09-02T03:53:28","slug":"%e0%b9%80%e0%b8%9b%e0%b8%b4%e0%b8%94%e0%b8%9b%e0%b8%8f%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9e%e0%b8%b4%e0%b8%97%e0%b8%b1%e0%b8%81%e0%b8%a9%e0%b9%8c%e0%b8%84","status":"publish","type":"post","link":"https:\/\/www.naewna.com\/n\/national-news\/region-news\/38405\/","title":{"rendered":"\u0e40\u0e1b\u0e34\u0e14\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e17\u0e31\u0e01\u0e29\u0e4c\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c! \u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e2f \u0e23\u0e48\u0e27\u0e21\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e25\u0e38\u0e22\u0e15\u0e23\u0e27\u0e08\u0e23\u0e16\u0e44\u0e1f\u0e2a\u0e32\u0e22\u0e43\u0e15\u0e49-\u0e14\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e1a\u0e01 \u0e22\u0e36\u0e14\u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48\u0e40\u0e16\u0e37\u0e48\u0e2d\u0e19-\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e40\u0e19\u0e21-\u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e23\u0e27\u0e21 4.37 \u0e25\u0e49\u0e32\u0e19"},"content":{"rendered":"<div class=\"vce-row-container\" data-vce-boxed-width=\"true\"><div class=\"vce-row vce-row--col-gap-30 vce-row-equal-height vce-row-content--top\" id=\"el-041510eb\" data-vce-do-apply=\"all el-041510eb\"><div class=\"vce-row-content\" data-vce-element-content=\"true\"><div class=\"vce-col vce-col--md-auto vce-col--xs-1 vce-col--xs-last vce-col--xs-first vce-col--sm-last vce-col--sm-first vce-col--md-last vce-col--lg-last vce-col--xl-last vce-col--md-first vce-col--lg-first vce-col--xl-first\" id=\"el-78f1e7b5\"><div class=\"vce-col-inner\" data-vce-do-apply=\"border margin background  el-78f1e7b5\"><div class=\"vce-col-content\" data-vce-element-content=\"true\" data-vce-do-apply=\"padding el-78f1e7b5\"><div class=\"vce-text-block\"><div class=\"vce-text-block-wrapper vce\" id=\"el-bf645ba2\" data-vce-do-apply=\"all el-bf645ba2\"><h2>\u0e40\u0e1b\u0e34\u0e14\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e17\u0e31\u0e01\u0e29\u0e4c\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c! \u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e2f \u0e2a\u0e19\u0e18\u0e34\u0e01\u0e33\u0e25\u0e31\u0e07\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e25\u0e38\u0e22\u0e15\u0e23\u0e27\u0e08\u0e23\u0e16\u0e44\u0e1f\u0e2a\u0e32\u0e22\u0e43\u0e15\u0e49-\u0e14\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e1a\u0e01 \u0e22\u0e36\u0e14\u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48\u0e40\u0e16\u0e37\u0e48\u0e2d\u0e19-\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e40\u0e19\u0e21-\u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e23\u0e27\u0e21\u0e20\u0e32\u0e29\u0e35\u0e17\u0e30\u0e25\u0e38 4.37 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17<\/h2>\n<p>\u0e27\u0e32\u0e19\u0e19\u0e35\u0e49 (1 \u0e01.\u0e22.2569) \u0e15\u0e32\u0e21\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e40\u0e23\u0e48\u0e07\u0e14\u0e48\u0e27\u0e19\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e41\u0e25\u0e30\u0e01\u0e23\u0e21\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e01\u0e1b\u0e49\u0e2d\u0e07\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1c\u0e34\u0e14\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 (Social Protection) \u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e48\u0e07\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07 \u0e19\u0e32\u0e22\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e17\u0e2d\u0e07 \u0e25\u0e2d\u0e22\u0e01\u0e38\u0e25\u0e19\u0e31\u0e19\u0e17\u0e4c \u0e2d\u0e18\u0e34\u0e1a\u0e14\u0e35\u0e01\u0e23\u0e21\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23 \u0e19\u0e32\u0e22\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e0a\u0e31\u0e22 \u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e4c\u0e40\u0e2a\u0e19 \u0e1c\u0e39\u0e49\u0e27\u0e48\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c \u0e19\u0e32\u0e07\u0e01\u0e34\u0e08\u0e08\u0e32\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c \u0e28\u0e23\u0e35\u0e19\u0e38\u0e0a\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e17\u0e32\u0e07\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23 \u0e41\u0e25\u0e30\u0e19\u0e32\u0e07\u0e19\u0e34\u0e20\u0e32\u0e27\u0e23\u0e23\u0e13 \u0e43\u0e22\u0e1a\u0e31\u0e27\u0e40\u0e17\u0e28 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e20\u0e32\u0e04\u0e17\u0e35\u0e48 1<\/p>\n<p>\u0e19\u0e32\u0e22\u0e10\u0e34\u0e15\u0e34\u0e1e\u0e07\u0e28\u0e4c \u0e04\u0e33\u0e1c\u0e38\u0e22 \u0e19\u0e32\u0e22\u0e14\u0e48\u0e32\u0e19\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c \u0e08\u0e36\u0e07\u0e44\u0e14\u0e49\u0e1a\u0e39\u0e23\u0e13\u0e32\u0e01\u0e32\u0e23\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2a\u0e23\u0e23\u0e1e\u0e2a\u0e32\u0e21\u0e34\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c \u0e2b\u0e19\u0e48\u0e27\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e01\u0e34\u0e08\u0e08\u0e07\u0e2d\u0e32\u0e07\u0e28\u0e36\u0e01 (\u0e09\u0e01.\u0e08\u0e07\u0e2d\u0e32\u0e07\u0e28\u0e36\u0e01\/\u0e23.9) \u0e01\u0e2d\u0e07\u0e01\u0e33\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e33\u0e23\u0e27\u0e08\u0e15\u0e23\u0e30\u0e40\u0e27\u0e19\u0e0a\u0e32\u0e22\u0e41\u0e14\u0e19\u0e17\u0e35\u0e48 14 (\u0e01\u0e01.\u0e15\u0e0a\u0e14.14) \u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e1d\u0e48\u0e32\u0e22\u0e1b\u0e01\u0e04\u0e23\u0e2d\u0e07 \u0e14\u0e48\u0e32\u0e19\u0e01\u0e31\u0e01\u0e01\u0e31\u0e19\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e21\u0e07\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c \u0e14\u0e48\u0e32\u0e19\u0e15\u0e23\u0e27\u0e08\u0e1b\u0e23\u0e30\u0e21\u0e07\u0e40\u0e02\u0e15 6 (\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c) \u0e14\u0e48\u0e32\u0e19\u0e15\u0e23\u0e27\u0e08\u0e1e\u0e37\u0e0a\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c, \u0e2a\u0e16\u0e32\u0e19\u0e35\u0e15\u0e33\u0e23\u0e27\u0e08\u0e20\u0e39\u0e18\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c \u0e2a\u0e16\u0e32\u0e19\u0e35\u0e15\u0e33\u0e23\u0e27\u0e08\u0e20\u0e39\u0e18\u0e23\u0e2b\u0e49\u0e27\u0e22\u0e22\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e14\u0e48\u0e32\u0e19\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1b\u0e48\u0e32\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c<\/p>\n<p>\u0e40\u0e1b\u0e34\u0e14 \"\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e17\u0e31\u0e01\u0e29\u0e4c\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c\" \u0e19\u0e33\u0e01\u0e33\u0e25\u0e31\u0e07\u0e40\u0e02\u0e49\u0e32\u0e15\u0e23\u0e27\u0e08\u0e04\u0e49\u0e19\u0e02\u0e1a\u0e27\u0e19\u0e23\u0e16\u0e44\u0e1f\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e2a\u0e32\u0e22\u0e43\u0e15\u0e49 \u0e13 \u0e2a\u0e16\u0e32\u0e19\u0e35\u0e23\u0e16\u0e44\u0e1f\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c \u0e04\u0e27\u0e1a\u0e04\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e31\u0e49\u0e07\u0e08\u0e38\u0e14\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e01\u0e31\u0e14\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1a\u0e19\u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e22\u0e38\u0e17\u0e18\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e14\u0e48\u0e32\u0e19\u0e15\u0e23\u0e27\u0e08\u0e2b\u0e49\u0e27\u0e22\u0e22\u0e32\u0e07 \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21 \u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e17\u0e31\u0e1a\u0e2a\u0e30\u0e41\u0e01 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c \u0e2b\u0e25\u0e31\u0e07\u0e2a\u0e37\u0e1a\u0e17\u0e23\u0e32\u0e1a\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e40\u0e0a\u0e34\u0e07\u0e25\u0e36\u0e01\u0e27\u0e48\u0e32\u0e08\u0e30\u0e21\u0e35\u0e01\u0e32\u0e23\u0e25\u0e31\u0e01\u0e25\u0e2d\u0e1a\u0e25\u0e33\u0e40\u0e25\u0e35\u0e22\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2b\u0e19\u0e35\u0e20\u0e32\u0e29\u0e35\u0e08\u0e32\u0e01\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e20\u0e32\u0e04\u0e43\u0e15\u0e49\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23<\/p>\n<p>\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e04\u0e49\u0e19\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22 \u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e15\u0e23\u0e27\u0e08\u0e22\u0e36\u0e14\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e25\u0e31\u0e01\u0e25\u0e2d\u0e1a\u0e2b\u0e19\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e44\u0e14\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e08\u0e33\u0e19\u0e27\u0e19\u0e21\u0e32\u0e01 \u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e21\u0e35\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e2b\u0e25\u0e31\u0e01\u0e10\u0e32\u0e19\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e35\u0e22\u0e20\u0e32\u0e29\u0e35\u0e2b\u0e23\u0e37\u0e2d\u0e1c\u0e48\u0e32\u0e19\u0e1e\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22<br>1. \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e25\u0e31\u0e01\u0e25\u0e2d\u0e1a\u0e2b\u0e19\u0e35\u0e20\u0e32\u0e29\u0e35: \u0e08\u0e33\u0e19\u0e27\u0e19 1,853 \u0e41\u0e17\u0e48\u0e07 (18,530 \u0e0b\u0e2d\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 370,600 \u0e21\u0e27\u0e19) \u0e23\u0e32\u0e04\u0e32\u0e02\u0e2d\u0e07\u0e23\u0e27\u0e21\u0e20\u0e32\u0e29\u0e35\u0e2d\u0e32\u0e01\u0e23\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e34\u0e49\u0e19 4,201,496 \u0e1a\u0e32\u0e17<br>2. \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e40\u0e19\u0e21: \u0e08\u0e33\u0e19\u0e27\u0e19 23 \u0e43\u0e1a \u0e23\u0e32\u0e04\u0e32\u0e02\u0e2d\u0e07\u0e23\u0e27\u0e21\u0e20\u0e32\u0e29\u0e35\u0e2d\u0e32\u0e01\u0e23\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e34\u0e49\u0e19 132,894 \u0e1a\u0e32\u0e17<br>3. \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e0a\u0e19\u0e34\u0e14\u0e43\u0e0a\u0e49\u0e41\u0e25\u0e49\u0e27\u0e17\u0e34\u0e49\u0e07\u0e41\u0e25\u0e30\u0e2b\u0e31\u0e27\u0e19\u0e49\u0e33\u0e22\u0e32\u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48\u0e44\u0e1f\u0e1f\u0e49\u0e32: \u0e23\u0e27\u0e21 55 \u0e0a\u0e34\u0e49\u0e19 \u0e23\u0e32\u0e04\u0e32\u0e02\u0e2d\u0e07\u0e23\u0e27\u0e21\u0e20\u0e32\u0e29\u0e35\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e34\u0e49\u0e19 21,500 \u0e1a\u0e32\u0e17<br>4. \u0e19\u0e49\u0e33\u0e2b\u0e2d\u0e21\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28: \u0e08\u0e33\u0e19\u0e27\u0e19 53 \u0e02\u0e27\u0e14 \u0e23\u0e32\u0e04\u0e32\u0e02\u0e2d\u0e07\u0e23\u0e27\u0e21\u0e20\u0e32\u0e29\u0e35\u0e2d\u0e32\u0e01\u0e23\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e34\u0e49\u0e19 20,380 \u0e1a\u0e32\u0e17<br>\u0e23\u0e27\u0e21\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e23\u0e32\u0e04\u0e32\u0e02\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e20\u0e32\u0e29\u0e35\u0e2d\u0e32\u0e01\u0e23\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e34\u0e49\u0e19 4,376,270 \u0e1a\u0e32\u0e17<br>\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e33\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e40\u0e02\u0e49\u0e32\u0e02\u0e48\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e1c\u0e34\u0e14\u0e10\u0e32\u0e19\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e43\u0e19\u0e23\u0e32\u0e0a\u0e2d\u0e32\u0e13\u0e32\u0e08\u0e31\u0e01\u0e23\u0e0b\u0e36\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e22\u0e31\u0e07\u0e21\u0e34\u0e44\u0e14\u0e49\u0e1c\u0e48\u0e32\u0e19\u0e1e\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e22\u0e49\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15 \u0e15\u0e32\u0e21\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e1a\u0e31\u0e0d\u0e0d\u0e31\u0e15\u0e34\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23 \u0e1e.\u0e28. 2560 \u0e41\u0e25\u0e30\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e1a\u0e31\u0e0d\u0e0d\u0e31\u0e15\u0e34\u0e20\u0e32\u0e29\u0e35\u0e2a\u0e23\u0e23\u0e1e\u0e2a\u0e32\u0e21\u0e34\u0e15 \u0e1e.\u0e28. 2560 \u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e08\u0e36\u0e07\u0e44\u0e14\u0e49\u0e17\u0e33\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e22\u0e36\u0e14\u0e02\u0e2d\u0e07\u0e01\u0e25\u0e32\u0e07\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e15\u0e31\u0e27\u0e1c\u0e39\u0e49\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e2a\u0e48\u0e07\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e04\u0e14\u0e35\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e2a\u0e37\u0e1a\u0e2a\u0e27\u0e19\u0e02\u0e22\u0e32\u0e22\u0e1c\u0e25\u0e2b\u0e32\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e02\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e39\u0e49\u0e23\u0e48\u0e27\u0e21\u0e01\u0e23\u0e30\u0e17\u0e33\u0e1c\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e44\u0e1b<\/p>\n<p>\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e19\u0e32\u0e22\u0e10\u0e34\u0e15\u0e34\u0e1e\u0e07\u0e28\u0e4c \u0e04\u0e33\u0e1c\u0e38\u0e22 \u0e19\u0e32\u0e22\u0e14\u0e48\u0e32\u0e19\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c \u0e40\u0e19\u0e49\u0e19\u0e22\u0e49\u0e33\u0e27\u0e48\u0e32\u0e08\u0e30\u0e22\u0e31\u0e07\u0e04\u0e07\u0e40\u0e14\u0e34\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e1a\u0e39\u0e23\u0e13\u0e32\u0e01\u0e32\u0e23\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e17\u0e38\u0e01\u0e20\u0e32\u0e04\u0e2a\u0e48\u0e27\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e27\u0e32\u0e21\u0e40\u0e02\u0e49\u0e21\u0e07\u0e27\u0e14\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e1d\u0e49\u0e32\u0e23\u0e30\u0e27\u0e31\u0e07\u0e08\u0e38\u0e14\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e41\u0e25\u0e30\u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e25\u0e33\u0e40\u0e25\u0e35\u0e22\u0e07\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01 \u0e17\u0e32\u0e07\u0e23\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c\u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e01\u0e31\u0e14\u0e01\u0e31\u0e49\u0e19\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1c\u0e34\u0e14\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e35\u0e48\u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e15\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e48\u0e2d\u0e44\u0e1b<\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u0e40\u0e1b\u0e34\u0e14\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e17\u0e31\u0e01\u0e29\u0e4c\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c! \u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e2f \u0e2a\u0e19\u0e18\u0e34\u0e01\u0e33\u0e25\u0e31 [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":38438,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[337],"tags":[557],"class_list":["post-38405","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-region-news","tag-557"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u0e40\u0e1b\u0e34\u0e14\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e17\u0e31\u0e01\u0e29\u0e4c\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c! \u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e2f \u0e23\u0e48\u0e27\u0e21\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e25\u0e38\u0e22\u0e15\u0e23\u0e27\u0e08\u0e23\u0e16\u0e44\u0e1f\u0e2a\u0e32\u0e22\u0e43\u0e15\u0e49-\u0e14\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e1a\u0e01 \u0e22\u0e36\u0e14\u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48\u0e40\u0e16\u0e37\u0e48\u0e2d\u0e19-\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e40\u0e19\u0e21-\u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e23\u0e27\u0e21 4.37 \u0e25\u0e49\u0e32\u0e19 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.naewna.com\/n\/national-news\/region-news\/38405\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e40\u0e1b\u0e34\u0e14\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e17\u0e31\u0e01\u0e29\u0e4c\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c! \u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e2f \u0e23\u0e48\u0e27\u0e21\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e25\u0e38\u0e22\u0e15\u0e23\u0e27\u0e08\u0e23\u0e16\u0e44\u0e1f\u0e2a\u0e32\u0e22\u0e43\u0e15\u0e49-\u0e14\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e1a\u0e01 \u0e22\u0e36\u0e14\u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48\u0e40\u0e16\u0e37\u0e48\u0e2d\u0e19-\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e40\u0e19\u0e21-\u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e23\u0e27\u0e21 4.37 \u0e25\u0e49\u0e32\u0e19\" \/>\n<meta property=\"og:description\" content=\"\u0e40\u0e1b\u0e34\u0e14\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e17\u0e31\u0e01\u0e29\u0e4c\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c! \u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e2f \u0e2a\u0e19\u0e18\u0e34\u0e01\u0e33\u0e25\u0e31 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.naewna.com\/n\/national-news\/region-news\/38405\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NaewnaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2026-09-02T03:53:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-02T03:53:28+00:00\" \/>\n<meta name=\"author\" content=\"\u0e41\u0e1e\u0e23\u0e04\u0e48\u0e30\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@naewna_news\" \/>\n<meta name=\"twitter:site\" content=\"@naewna_news\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u0e41\u0e1e\u0e23\u0e04\u0e48\u0e30\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/national-news\\\/region-news\\\/38405\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/national-news\\\/region-news\\\/38405\\\/\"},\"author\":{\"name\":\"\u0e41\u0e1e\u0e23\u0e04\u0e48\u0e30\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#\\\/schema\\\/person\\\/fd4e4c7b483396e84508b1a1151c9d12\"},\"headline\":\"\u0e40\u0e1b\u0e34\u0e14\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e17\u0e31\u0e01\u0e29\u0e4c\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c! \u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e2f \u0e23\u0e48\u0e27\u0e21\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e25\u0e38\u0e22\u0e15\u0e23\u0e27\u0e08\u0e23\u0e16\u0e44\u0e1f\u0e2a\u0e32\u0e22\u0e43\u0e15\u0e49-\u0e14\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e1a\u0e01 \u0e22\u0e36\u0e14\u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48\u0e40\u0e16\u0e37\u0e48\u0e2d\u0e19-\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e40\u0e19\u0e21-\u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e23\u0e27\u0e21 4.37 \u0e25\u0e49\u0e32\u0e19\",\"datePublished\":\"2026-09-02T03:53:27+00:00\",\"dateModified\":\"2026-09-02T03:53:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/national-news\\\/region-news\\\/38405\\\/\"},\"wordCount\":8,\"image\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/national-news\\\/region-news\\\/38405\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/storage-wp.naewna.com\\\/2026\\\/09\\\/963750.jpg\",\"keywords\":[\"\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\"],\"articleSection\":[\"\u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04\"],\"inLanguage\":\"th\",\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/national-news\\\/region-news\\\/38405\\\/\",\"url\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/national-news\\\/region-news\\\/38405\\\/\",\"name\":\"\u0e40\u0e1b\u0e34\u0e14\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e17\u0e31\u0e01\u0e29\u0e4c\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c! \u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e2f \u0e23\u0e48\u0e27\u0e21\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e25\u0e38\u0e22\u0e15\u0e23\u0e27\u0e08\u0e23\u0e16\u0e44\u0e1f\u0e2a\u0e32\u0e22\u0e43\u0e15\u0e49-\u0e14\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e1a\u0e01 \u0e22\u0e36\u0e14\u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48\u0e40\u0e16\u0e37\u0e48\u0e2d\u0e19-\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e40\u0e19\u0e21-\u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e23\u0e27\u0e21 4.37 \u0e25\u0e49\u0e32\u0e19 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/national-news\\\/region-news\\\/38405\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/national-news\\\/region-news\\\/38405\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/storage-wp.naewna.com\\\/2026\\\/09\\\/963750.jpg\",\"datePublished\":\"2026-09-02T03:53:27+00:00\",\"dateModified\":\"2026-09-02T03:53:28+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#\\\/schema\\\/person\\\/fd4e4c7b483396e84508b1a1151c9d12\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/national-news\\\/region-news\\\/38405\\\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.naewna.com\\\/n\\\/national-news\\\/region-news\\\/38405\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/national-news\\\/region-news\\\/38405\\\/#primaryimage\",\"url\":\"https:\\\/\\\/storage-wp.naewna.com\\\/2026\\\/09\\\/963750.jpg\",\"contentUrl\":\"https:\\\/\\\/storage-wp.naewna.com\\\/2026\\\/09\\\/963750.jpg\",\"width\":1566,\"height\":1044},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/national-news\\\/region-news\\\/38405\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e40\u0e1b\u0e34\u0e14\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e17\u0e31\u0e01\u0e29\u0e4c\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c! \u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e2f \u0e23\u0e48\u0e27\u0e21\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e25\u0e38\u0e22\u0e15\u0e23\u0e27\u0e08\u0e23\u0e16\u0e44\u0e1f\u0e2a\u0e32\u0e22\u0e43\u0e15\u0e49-\u0e14\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e1a\u0e01 \u0e22\u0e36\u0e14\u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48\u0e40\u0e16\u0e37\u0e48\u0e2d\u0e19-\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e40\u0e19\u0e21-\u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e23\u0e27\u0e21 4.37 \u0e25\u0e49\u0e32\u0e19\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#website\",\"url\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/\",\"name\":\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#\\\/schema\\\/person\\\/fd4e4c7b483396e84508b1a1151c9d12\",\"name\":\"\u0e41\u0e1e\u0e23\u0e04\u0e48\u0e30\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c101c894a4f535d17ca4e42e85475744d0feb4586dd6bca93b75ad6c8ca65876?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c101c894a4f535d17ca4e42e85475744d0feb4586dd6bca93b75ad6c8ca65876?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c101c894a4f535d17ca4e42e85475744d0feb4586dd6bca93b75ad6c8ca65876?s=96&d=mm&r=g\",\"caption\":\"\u0e41\u0e1e\u0e23\u0e04\u0e48\u0e30\"},\"url\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/author\\\/workingmode\\\/\"}]}<\/script>\n<meta property=\"article:section\" content=\"\u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u0e40\u0e1b\u0e34\u0e14\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e17\u0e31\u0e01\u0e29\u0e4c\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c! \u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e2f \u0e23\u0e48\u0e27\u0e21\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e25\u0e38\u0e22\u0e15\u0e23\u0e27\u0e08\u0e23\u0e16\u0e44\u0e1f\u0e2a\u0e32\u0e22\u0e43\u0e15\u0e49-\u0e14\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e1a\u0e01 \u0e22\u0e36\u0e14\u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48\u0e40\u0e16\u0e37\u0e48\u0e2d\u0e19-\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e40\u0e19\u0e21-\u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e23\u0e27\u0e21 4.37 \u0e25\u0e49\u0e32\u0e19 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.naewna.com\/n\/national-news\/region-news\/38405\/","og_locale":"th_TH","og_type":"article","og_title":"\u0e40\u0e1b\u0e34\u0e14\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e17\u0e31\u0e01\u0e29\u0e4c\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c! \u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e2f \u0e23\u0e48\u0e27\u0e21\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e25\u0e38\u0e22\u0e15\u0e23\u0e27\u0e08\u0e23\u0e16\u0e44\u0e1f\u0e2a\u0e32\u0e22\u0e43\u0e15\u0e49-\u0e14\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e1a\u0e01 \u0e22\u0e36\u0e14\u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48\u0e40\u0e16\u0e37\u0e48\u0e2d\u0e19-\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e40\u0e19\u0e21-\u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e23\u0e27\u0e21 4.37 \u0e25\u0e49\u0e32\u0e19","og_description":"\u0e40\u0e1b\u0e34\u0e14\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e17\u0e31\u0e01\u0e29\u0e4c\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c! \u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e2f \u0e2a\u0e19\u0e18\u0e34\u0e01\u0e33\u0e25\u0e31 [&hellip;]","og_url":"https:\/\/www.naewna.com\/n\/national-news\/region-news\/38405\/","og_site_name":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32","article_publisher":"https:\/\/www.facebook.com\/NaewnaOnline","article_published_time":"2026-09-02T03:53:27+00:00","article_modified_time":"2026-09-02T03:53:28+00:00","author":"\u0e41\u0e1e\u0e23\u0e04\u0e48\u0e30","twitter_card":"summary_large_image","twitter_creator":"@naewna_news","twitter_site":"@naewna_news","twitter_misc":{"Written by":"\u0e41\u0e1e\u0e23\u0e04\u0e48\u0e30"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.naewna.com\/n\/national-news\/region-news\/38405\/#article","isPartOf":{"@id":"https:\/\/www.naewna.com\/n\/national-news\/region-news\/38405\/"},"author":{"name":"\u0e41\u0e1e\u0e23\u0e04\u0e48\u0e30","@id":"https:\/\/www.naewna.com\/n\/#\/schema\/person\/fd4e4c7b483396e84508b1a1151c9d12"},"headline":"\u0e40\u0e1b\u0e34\u0e14\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e17\u0e31\u0e01\u0e29\u0e4c\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c! \u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e2f \u0e23\u0e48\u0e27\u0e21\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e25\u0e38\u0e22\u0e15\u0e23\u0e27\u0e08\u0e23\u0e16\u0e44\u0e1f\u0e2a\u0e32\u0e22\u0e43\u0e15\u0e49-\u0e14\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e1a\u0e01 \u0e22\u0e36\u0e14\u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48\u0e40\u0e16\u0e37\u0e48\u0e2d\u0e19-\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e40\u0e19\u0e21-\u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e23\u0e27\u0e21 4.37 \u0e25\u0e49\u0e32\u0e19","datePublished":"2026-09-02T03:53:27+00:00","dateModified":"2026-09-02T03:53:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.naewna.com\/n\/national-news\/region-news\/38405\/"},"wordCount":8,"image":{"@id":"https:\/\/www.naewna.com\/n\/national-news\/region-news\/38405\/#primaryimage"},"thumbnailUrl":"https:\/\/storage-wp.naewna.com\/2026\/09\/963750.jpg","keywords":["\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c"],"articleSection":["\u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04"],"inLanguage":"th","copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/www.naewna.com\/n\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.naewna.com\/n\/national-news\/region-news\/38405\/","url":"https:\/\/www.naewna.com\/n\/national-news\/region-news\/38405\/","name":"\u0e40\u0e1b\u0e34\u0e14\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e17\u0e31\u0e01\u0e29\u0e4c\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c! \u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e2f \u0e23\u0e48\u0e27\u0e21\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e25\u0e38\u0e22\u0e15\u0e23\u0e27\u0e08\u0e23\u0e16\u0e44\u0e1f\u0e2a\u0e32\u0e22\u0e43\u0e15\u0e49-\u0e14\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e1a\u0e01 \u0e22\u0e36\u0e14\u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48\u0e40\u0e16\u0e37\u0e48\u0e2d\u0e19-\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e40\u0e19\u0e21-\u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e23\u0e27\u0e21 4.37 \u0e25\u0e49\u0e32\u0e19 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32","isPartOf":{"@id":"https:\/\/www.naewna.com\/n\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.naewna.com\/n\/national-news\/region-news\/38405\/#primaryimage"},"image":{"@id":"https:\/\/www.naewna.com\/n\/national-news\/region-news\/38405\/#primaryimage"},"thumbnailUrl":"https:\/\/storage-wp.naewna.com\/2026\/09\/963750.jpg","datePublished":"2026-09-02T03:53:27+00:00","dateModified":"2026-09-02T03:53:28+00:00","author":{"@id":"https:\/\/www.naewna.com\/n\/#\/schema\/person\/fd4e4c7b483396e84508b1a1151c9d12"},"breadcrumb":{"@id":"https:\/\/www.naewna.com\/n\/national-news\/region-news\/38405\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.naewna.com\/n\/national-news\/region-news\/38405\/"]}]},{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.naewna.com\/n\/national-news\/region-news\/38405\/#primaryimage","url":"https:\/\/storage-wp.naewna.com\/2026\/09\/963750.jpg","contentUrl":"https:\/\/storage-wp.naewna.com\/2026\/09\/963750.jpg","width":1566,"height":1044},{"@type":"BreadcrumbList","@id":"https:\/\/www.naewna.com\/n\/national-news\/region-news\/38405\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.naewna.com\/n\/"},{"@type":"ListItem","position":2,"name":"\u0e40\u0e1b\u0e34\u0e14\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e17\u0e31\u0e01\u0e29\u0e4c\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c! \u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e2f \u0e23\u0e48\u0e27\u0e21\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e25\u0e38\u0e22\u0e15\u0e23\u0e27\u0e08\u0e23\u0e16\u0e44\u0e1f\u0e2a\u0e32\u0e22\u0e43\u0e15\u0e49-\u0e14\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e1a\u0e01 \u0e22\u0e36\u0e14\u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48\u0e40\u0e16\u0e37\u0e48\u0e2d\u0e19-\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e40\u0e19\u0e21-\u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e23\u0e27\u0e21 4.37 \u0e25\u0e49\u0e32\u0e19"}]},{"@type":"WebSite","@id":"https:\/\/www.naewna.com\/n\/#website","url":"https:\/\/www.naewna.com\/n\/","name":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.naewna.com\/n\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"},{"@type":"Person","@id":"https:\/\/www.naewna.com\/n\/#\/schema\/person\/fd4e4c7b483396e84508b1a1151c9d12","name":"\u0e41\u0e1e\u0e23\u0e04\u0e48\u0e30","image":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/secure.gravatar.com\/avatar\/c101c894a4f535d17ca4e42e85475744d0feb4586dd6bca93b75ad6c8ca65876?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c101c894a4f535d17ca4e42e85475744d0feb4586dd6bca93b75ad6c8ca65876?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c101c894a4f535d17ca4e42e85475744d0feb4586dd6bca93b75ad6c8ca65876?s=96&d=mm&r=g","caption":"\u0e41\u0e1e\u0e23\u0e04\u0e48\u0e30"},"url":"https:\/\/www.naewna.com\/n\/author\/workingmode\/"}]}},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/storage-wp.naewna.com\/2026\/09\/963750.jpg","_links":{"self":[{"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/posts\/38405","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/comments?post=38405"}],"version-history":[{"count":2,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/posts\/38405\/revisions"}],"predecessor-version":[{"id":38446,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/posts\/38405\/revisions\/38446"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/media\/38438"}],"wp:attachment":[{"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/media?parent=38405"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/categories?post=38405"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/tags?post=38405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}