{"id":38548,"date":"2026-09-02T11:37:42","date_gmt":"2026-09-02T04:37:42","guid":{"rendered":"https:\/\/www.naewna.com\/n\/?p=38548"},"modified":"2026-09-02T12:00:19","modified_gmt":"2026-09-02T05:00:19","slug":"%e0%b8%a2%e0%b8%b1%e0%b8%81%e0%b8%a9%e0%b9%8c%e0%b9%83%e0%b8%ab%e0%b8%8d%e0%b9%88%e0%b9%80%e0%b8%97%e0%b8%b5%e0%b8%a2%e0%b8%9a%e0%b8%97%e0%b9%88%e0%b8%b2-%e0%b9%80%e0%b8%a3%e0%b8%b7%e0%b8%ad","status":"publish","type":"post","link":"https:\/\/www.naewna.com\/n\/top-stories\/38548\/","title":{"rendered":"\u0e22\u0e31\u0e01\u0e29\u0e4c\u0e43\u0e2b\u0e0d\u0e48\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e17\u0e48\u0e32! \u0e40\u0e23\u0e37\u0e2d\u2018USS Abraham Lincoln\u2019 \u0e16\u0e36\u0e07\u0e41\u0e2b\u0e25\u0e21\u0e09\u0e1a\u0e31\u0e07-\u0e02\u0e19\u0e17\u0e2b\u0e32\u0e23 5 \u0e1e\u0e31\u0e19\u0e19\u0e32\u0e22\u0e1a\u0e38\u0e01\u0e1e\u0e31\u0e17\u0e22\u0e32"},"content":{"rendered":"<div class=\"vce-row-container\" data-vce-boxed-width=\"true\"><div class=\"vce-row vce-row--col-gap-30 vce-row-equal-height vce-row-content--top\" id=\"el-ff32ff1c\" data-vce-do-apply=\"all el-ff32ff1c\"><div class=\"vce-row-content\" data-vce-element-content=\"true\"><div class=\"vce-col vce-col--md-auto vce-col--xs-1 vce-col--xs-last vce-col--xs-first vce-col--sm-last vce-col--sm-first vce-col--md-last vce-col--lg-last vce-col--xl-last vce-col--md-first vce-col--lg-first vce-col--xl-first\" id=\"el-3de8afee\"><div class=\"vce-col-inner\" data-vce-do-apply=\"border margin background  el-3de8afee\"><div class=\"vce-col-content\" data-vce-element-content=\"true\" data-vce-do-apply=\"padding el-3de8afee\"><div class=\"vce-text-block\"><div class=\"vce-text-block-wrapper vce\" id=\"el-89afbced\" data-vce-do-apply=\"all el-89afbced\"><p><strong>\u0e22\u0e31\u0e01\u0e29\u0e4c\u0e43\u0e2b\u0e0d\u0e48\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e17\u0e48\u0e32! \u0e40\u0e23\u0e37\u0e2d\u0e2a\u0e2b\u0e23\u0e31\u0e10\u0e2f \u2018USS Abraham Lincoln\u2019 \u0e16\u0e36\u0e07\u0e41\u0e2b\u0e25\u0e21\u0e09\u0e1a\u0e31\u0e07 \u0e02\u0e19\u0e17\u0e2b\u0e32\u0e23 5 \u0e1e\u0e31\u0e19\u0e19\u0e32\u0e22\u0e1a\u0e38\u0e01\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e1b\u0e25\u0e38\u0e01\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e04\u0e36\u0e01\u0e04\u0e31\u0e01<\/strong><\/p>\n<p>\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 2 \u0e01.\u0e22. 2569 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e27\u0e25\u0e32 09.30 \u0e19. \u0e1c\u0e39\u0e49\u0e2a\u0e37\u0e48\u0e2d\u0e02\u0e48\u0e32\u0e27\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e27\u0e48\u0e32 \u0e2a\u0e37\u0e48\u0e2d\u0e21\u0e27\u0e25\u0e0a\u0e19\u0e17\u0e31\u0e49\u0e07\u0e44\u0e17\u0e22\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e15\u0e48\u0e32\u0e07\u0e40\u0e01\u0e32\u0e30\u0e15\u0e34\u0e14\u0e04\u0e27\u0e32\u0e21\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e2b\u0e27\u0e01\u0e23\u0e13\u0e35\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e21\u0e32\u0e16\u0e36\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e02\u0e2d\u0e07 \u0e40\u0e23\u0e37\u0e2d\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e34\u0e19\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e19\u0e34\u0e27\u0e40\u0e04\u0e25\u0e35\u0e22\u0e23\u0e4c USS Abraham Lincoln (CVN-72) \u0e40\u0e23\u0e37\u0e2d\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e34\u0e19\u0e0a\u0e31\u0e49\u0e19 Nimitz \u0e02\u0e2d\u0e07\u0e01\u0e2d\u0e07\u0e17\u0e31\u0e1e\u0e40\u0e23\u0e37\u0e2d\u0e2a\u0e2b\u0e23\u0e31\u0e10\u0e2f \u0e0b\u0e36\u0e48\u0e07\u0e44\u0e14\u0e49\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e19\u0e19\u0e49\u0e33\u0e41\u0e2b\u0e25\u0e21\u0e09\u0e1a\u0e31\u0e07 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u0e41\u0e25\u0e30\u0e40\u0e02\u0e49\u0e32\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e17\u0e48\u0e32\u0e17\u0e35\u0e48 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e41\u0e2b\u0e25\u0e21\u0e09\u0e1a\u0e31\u0e07 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e42\u0e23-\u0e42\u0e23 \u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e21\u0e34\u0e19\u0e31\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 \u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e40\u0e23\u0e35\u0e22\u0e1a\u0e23\u0e49\u0e2d\u0e22\u0e41\u0e25\u0e49\u0e27 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e01\u0e33\u0e25\u0e31\u0e07\u0e1e\u0e25\u0e41\u0e25\u0e30\u0e20\u0e32\u0e23\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e22\u0e37\u0e2d\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38556 aligncenter\" src=\"https:\/\/storage-wp.naewna.com\/2026\/09\/S__17342501_0.jpg\" alt=\"\" width=\"1080\" height=\"607\"><\/p>\n<p>\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e21\u0e32\u0e40\u0e22\u0e37\u0e2d\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e43\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e21\u0e35\u0e01\u0e33\u0e25\u0e31\u0e07\u0e1e\u0e25\u0e01\u0e2d\u0e07\u0e17\u0e31\u0e1e\u0e40\u0e23\u0e37\u0e2d\u0e2a\u0e2b\u0e23\u0e31\u0e10\u0e2f \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e40\u0e23\u0e37\u0e2d\u0e23\u0e32\u0e27 5,000 \u0e19\u0e32\u0e22 \u0e42\u0e14\u0e22\u0e20\u0e32\u0e22\u0e2b\u0e25\u0e31\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e40\u0e02\u0e49\u0e32\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e17\u0e48\u0e32\u0e40\u0e23\u0e35\u0e22\u0e1a\u0e23\u0e49\u0e2d\u0e22\u0e41\u0e25\u0e49\u0e27 \u0e01\u0e33\u0e25\u0e31\u0e07\u0e1e\u0e25\u0e08\u0e30\u0e17\u0e22\u0e2d\u0e22\u0e25\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e02\u0e36\u0e49\u0e19\u0e1d\u0e31\u0e48\u0e07\u0e15\u0e32\u0e21\u0e41\u0e1c\u0e19\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49 \u0e01\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e04\u0e13\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e32\u0e41\u0e25\u0e30\u0e01\u0e33\u0e25\u0e31\u0e07\u0e1e\u0e25\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e2b\u0e0d\u0e48\u0e08\u0e30\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e22\u0e31\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e2b\u0e25\u0e31\u0e01\u0e02\u0e2d\u0e07\u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38557 aligncenter\" src=\"https:\/\/storage-wp.naewna.com\/2026\/09\/S__17342504_0.jpg\" alt=\"\" width=\"1080\" height=\"810\"><\/p>\n<p>\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e02\u0e2d\u0e07\u0e01\u0e33\u0e25\u0e31\u0e07\u0e1e\u0e25\u0e2a\u0e2b\u0e23\u0e31\u0e10\u0e2f \u0e08\u0e33\u0e19\u0e27\u0e19\u0e21\u0e32\u0e01\u0e43\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e43\u0e2b\u0e49\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e1e\u0e31\u0e17\u0e22\u0e32\u0e41\u0e25\u0e30\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e23\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e43\u0e19\u0e01\u0e32\u0e23\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e15\u0e47\u0e21\u0e17\u0e35\u0e48 \u0e02\u0e13\u0e30\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e17\u0e31\u0e49\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e2a\u0e16\u0e32\u0e19\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e15\u0e48\u0e32\u0e07\u0e08\u0e31\u0e1a\u0e15\u0e32\u0e21\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e02\u0e32\u0e19\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e02\u0e2d\u0e07\u0e01\u0e33\u0e25\u0e31\u0e07\u0e1e\u0e25\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e04\u0e36\u0e01\u0e04\u0e31\u0e01 \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e04\u0e32\u0e14\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e0a\u0e48\u0e27\u0e22\u0e01\u0e23\u0e30\u0e15\u0e38\u0e49\u0e19\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e1a\u0e08\u0e48\u0e32\u0e22\u0e43\u0e0a\u0e49\u0e2a\u0e2d\u0e22\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e1e\u0e31\u0e17\u0e22\u0e32\u0e43\u0e2b\u0e49\u0e2a\u0e30\u0e1e\u0e31\u0e14\u0e02\u0e36\u0e49\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e2b\u0e47\u0e19\u0e44\u0e14\u0e49\u0e0a\u0e31\u0e14<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38558 aligncenter\" src=\"https:\/\/storage-wp.naewna.com\/2026\/09\/S__17342503_0.jpg\" alt=\"\" width=\"1080\" height=\"810\"><\/p>\n<p>\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e17\u0e48\u0e32\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e34\u0e19\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e19\u0e34\u0e27\u0e40\u0e04\u0e25\u0e35\u0e22\u0e23\u0e4c\u0e43\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e44\u0e14\u0e49\u0e21\u0e35\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e43\u0e01\u0e25\u0e49\u0e0a\u0e34\u0e14\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e2d\u0e32\u0e17\u0e34 \u0e01\u0e32\u0e23\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22, \u0e01\u0e2d\u0e07\u0e17\u0e31\u0e1e\u0e40\u0e23\u0e37\u0e2d, \u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e41\u0e25\u0e30\u0e1d\u0e48\u0e32\u0e22\u0e1b\u0e01\u0e04\u0e23\u0e2d\u0e07 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e43\u0e19\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e08\u0e23\u0e32\u0e08\u0e23\u0e17\u0e32\u0e07\u0e19\u0e49\u0e33 \u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e1a\u0e19\u0e1d\u0e31\u0e48\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e21\u0e32\u0e15\u0e23\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e02\u0e49\u0e21\u0e07\u0e27\u0e14\u0e15\u0e25\u0e2d\u0e14\u0e0a\u0e48\u0e27\u0e07\u0e23\u0e30\u0e22\u0e30\u0e40\u0e27\u0e25\u0e32\u0e17\u0e35\u0e48\u0e40\u0e23\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e01\u0e33\u0e25\u0e31\u0e07\u0e1e\u0e25\u0e2a\u0e2b\u0e23\u0e31\u0e10\u0e2f \u0e1e\u0e31\u0e01\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e32\u0e23\u0e01\u0e34\u0e08\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38561 aligncenter\" src=\"https:\/\/storage-wp.naewna.com\/2026\/09\/S__17342505_0-1.jpg\" alt=\"\" width=\"1080\" height=\"590\"><\/p>\n<p>\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e0f\u0e15\u0e31\u0e27\u0e02\u0e2d\u0e07 USS Abraham Lincoln (CVN-72) \u0e0b\u0e36\u0e48\u0e07\u0e16\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19\u0e40\u0e23\u0e37\u0e2d\u0e22\u0e38\u0e17\u0e18\u0e01\u0e32\u0e23\u0e02\u0e19\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e02\u0e2d\u0e07\u0e01\u0e2d\u0e07\u0e17\u0e31\u0e1e\u0e40\u0e23\u0e37\u0e2d\u0e2a\u0e2b\u0e23\u0e31\u0e10\u0e2f \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e19\u0e43\u0e08\u0e08\u0e32\u0e01\u0e2a\u0e37\u0e48\u0e2d\u0e21\u0e27\u0e25\u0e0a\u0e19\u0e17\u0e31\u0e48\u0e27\u0e42\u0e25\u0e01\u0e17\u0e35\u0e48\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e21\u0e32\u0e23\u0e48\u0e27\u0e21\u0e17\u0e33\u0e02\u0e48\u0e32\u0e27\u0e20\u0e32\u0e1e\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e17\u0e48\u0e32\u0e41\u0e2b\u0e25\u0e21\u0e09\u0e1a\u0e31\u0e07 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e1e\u0e31\u0e17\u0e22\u0e32\u0e02\u0e2d\u0e07\u0e01\u0e33\u0e25\u0e31\u0e07\u0e1e\u0e25\u0e17\u0e2b\u0e32\u0e23\u0e40\u0e23\u0e37\u0e2d\u0e2a\u0e2b\u0e23\u0e31\u0e10\u0e2f \u0e43\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e04\u0e36\u0e01\u0e04\u0e31\u0e01<\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u0e22\u0e31\u0e01\u0e29\u0e4c\u0e43\u0e2b\u0e0d\u0e48\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e17\u0e48\u0e32! \u0e40\u0e23\u0e37\u0e2d\u0e2a\u0e2b\u0e23\u0e31\u0e10\u0e2f \u2018USS Abraham Lincoln\u2019 \u0e16\u0e36\u0e07 [&hellip;]<\/p>\n","protected":false},"author":28,"featured_media":38555,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[241,16,3,343,337,9],"tags":[5948,5947,5949,275,5914,290],"class_list":["post-38548","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking","category-like-learn","category-top-stories","category-travel-news","category-region-news","category-national-news","tag-cvn72","tag-ussabrahamlincoln","tag-5949","tag-275","tag-5914","tag-290"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u0e22\u0e31\u0e01\u0e29\u0e4c\u0e43\u0e2b\u0e0d\u0e48\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e17\u0e48\u0e32! \u0e40\u0e23\u0e37\u0e2d\u2018USS Abraham Lincoln\u2019 \u0e16\u0e36\u0e07\u0e41\u0e2b\u0e25\u0e21\u0e09\u0e1a\u0e31\u0e07-\u0e02\u0e19\u0e17\u0e2b\u0e32\u0e23 5 \u0e1e\u0e31\u0e19\u0e19\u0e32\u0e22\u0e1a\u0e38\u0e01\u0e1e\u0e31\u0e17\u0e22\u0e32 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.naewna.com\/n\/top-stories\/38548\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e22\u0e31\u0e01\u0e29\u0e4c\u0e43\u0e2b\u0e0d\u0e48\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e17\u0e48\u0e32! \u0e40\u0e23\u0e37\u0e2d\u2018USS Abraham Lincoln\u2019 \u0e16\u0e36\u0e07\u0e41\u0e2b\u0e25\u0e21\u0e09\u0e1a\u0e31\u0e07-\u0e02\u0e19\u0e17\u0e2b\u0e32\u0e23 5 \u0e1e\u0e31\u0e19\u0e19\u0e32\u0e22\u0e1a\u0e38\u0e01\u0e1e\u0e31\u0e17\u0e22\u0e32\" \/>\n<meta property=\"og:description\" content=\"\u0e22\u0e31\u0e01\u0e29\u0e4c\u0e43\u0e2b\u0e0d\u0e48\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e17\u0e48\u0e32! \u0e40\u0e23\u0e37\u0e2d\u0e2a\u0e2b\u0e23\u0e31\u0e10\u0e2f \u2018USS Abraham Lincoln\u2019 \u0e16\u0e36\u0e07 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.naewna.com\/n\/top-stories\/38548\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NaewnaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2026-09-02T04:37:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-02T05:00:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/storage-wp.naewna.com\/2026\/09\/S__17342505_0.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"590\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"\u0e04\u0e23\u0e34\u0e2a\u0e15\u0e4c\u0e44\u0e07\u0e08\u0e30\u0e43\u0e04\u0e23\u0e25\u0e48\u0e30\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@naewna_news\" \/>\n<meta name=\"twitter:site\" content=\"@naewna_news\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u0e04\u0e23\u0e34\u0e2a\u0e15\u0e4c\u0e44\u0e07\u0e08\u0e30\u0e43\u0e04\u0e23\u0e25\u0e48\u0e30\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/top-stories\\\/38548\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/top-stories\\\/38548\\\/\"},\"author\":{\"name\":\"\u0e04\u0e23\u0e34\u0e2a\u0e15\u0e4c\u0e44\u0e07\u0e08\u0e30\u0e43\u0e04\u0e23\u0e25\u0e48\u0e30\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#\\\/schema\\\/person\\\/89786e63af3279dd8041bb8a5d30a3f3\"},\"headline\":\"\u0e22\u0e31\u0e01\u0e29\u0e4c\u0e43\u0e2b\u0e0d\u0e48\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e17\u0e48\u0e32! \u0e40\u0e23\u0e37\u0e2d\u2018USS Abraham Lincoln\u2019 \u0e16\u0e36\u0e07\u0e41\u0e2b\u0e25\u0e21\u0e09\u0e1a\u0e31\u0e07-\u0e02\u0e19\u0e17\u0e2b\u0e32\u0e23 5 \u0e1e\u0e31\u0e19\u0e19\u0e32\u0e22\u0e1a\u0e38\u0e01\u0e1e\u0e31\u0e17\u0e22\u0e32\",\"datePublished\":\"2026-09-02T04:37:42+00:00\",\"dateModified\":\"2026-09-02T05:00:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/top-stories\\\/38548\\\/\"},\"wordCount\":17,\"image\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/top-stories\\\/38548\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/storage-wp.naewna.com\\\/2026\\\/09\\\/S__17342505_0.jpg\",\"keywords\":[\"CVN72\",\"USSAbrahamLincoln\",\"\u0e01\u0e2d\u0e07\u0e17\u0e31\u0e1e\u0e40\u0e23\u0e37\u0e2d\u0e2a\u0e2b\u0e23\u0e31\u0e10\",\"\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e41\u0e2b\u0e25\u0e21\u0e09\u0e1a\u0e31\u0e07\",\"\u0e1e\u0e31\u0e17\u0e22\u0e32\"],\"articleSection\":[\"Breaking News\",\"Like \u0e2a\u0e32\u0e23\u0e30\",\"\u0e02\u0e48\u0e32\u0e27\u0e40\u0e14\u0e48\u0e19\",\"\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\",\"\u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04\",\"\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\"],\"inLanguage\":\"th\",\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/top-stories\\\/38548\\\/\",\"url\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/top-stories\\\/38548\\\/\",\"name\":\"\u0e22\u0e31\u0e01\u0e29\u0e4c\u0e43\u0e2b\u0e0d\u0e48\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e17\u0e48\u0e32! \u0e40\u0e23\u0e37\u0e2d\u2018USS Abraham Lincoln\u2019 \u0e16\u0e36\u0e07\u0e41\u0e2b\u0e25\u0e21\u0e09\u0e1a\u0e31\u0e07-\u0e02\u0e19\u0e17\u0e2b\u0e32\u0e23 5 \u0e1e\u0e31\u0e19\u0e19\u0e32\u0e22\u0e1a\u0e38\u0e01\u0e1e\u0e31\u0e17\u0e22\u0e32 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/top-stories\\\/38548\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/top-stories\\\/38548\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/storage-wp.naewna.com\\\/2026\\\/09\\\/S__17342505_0.jpg\",\"datePublished\":\"2026-09-02T04:37:42+00:00\",\"dateModified\":\"2026-09-02T05:00:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#\\\/schema\\\/person\\\/89786e63af3279dd8041bb8a5d30a3f3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/top-stories\\\/38548\\\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.naewna.com\\\/n\\\/top-stories\\\/38548\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/top-stories\\\/38548\\\/#primaryimage\",\"url\":\"https:\\\/\\\/storage-wp.naewna.com\\\/2026\\\/09\\\/S__17342505_0.jpg\",\"contentUrl\":\"https:\\\/\\\/storage-wp.naewna.com\\\/2026\\\/09\\\/S__17342505_0.jpg\",\"width\":1080,\"height\":590},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/top-stories\\\/38548\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e22\u0e31\u0e01\u0e29\u0e4c\u0e43\u0e2b\u0e0d\u0e48\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e17\u0e48\u0e32! \u0e40\u0e23\u0e37\u0e2d\u2018USS Abraham Lincoln\u2019 \u0e16\u0e36\u0e07\u0e41\u0e2b\u0e25\u0e21\u0e09\u0e1a\u0e31\u0e07-\u0e02\u0e19\u0e17\u0e2b\u0e32\u0e23 5 \u0e1e\u0e31\u0e19\u0e19\u0e32\u0e22\u0e1a\u0e38\u0e01\u0e1e\u0e31\u0e17\u0e22\u0e32\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#website\",\"url\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/\",\"name\":\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#\\\/schema\\\/person\\\/89786e63af3279dd8041bb8a5d30a3f3\",\"name\":\"\u0e04\u0e23\u0e34\u0e2a\u0e15\u0e4c\u0e44\u0e07\u0e08\u0e30\u0e43\u0e04\u0e23\u0e25\u0e48\u0e30\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ef03eb2b6ecd67b446b219e9760f088d71d928554dbd66c46969f008aae8836?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ef03eb2b6ecd67b446b219e9760f088d71d928554dbd66c46969f008aae8836?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ef03eb2b6ecd67b446b219e9760f088d71d928554dbd66c46969f008aae8836?s=96&d=mm&r=g\",\"caption\":\"\u0e04\u0e23\u0e34\u0e2a\u0e15\u0e4c\u0e44\u0e07\u0e08\u0e30\u0e43\u0e04\u0e23\u0e25\u0e48\u0e30\"},\"url\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/author\\\/christmas_251237\\\/\"}]}<\/script>\n<meta property=\"article:section\" content=\"Breaking News\" \/>\n<meta property=\"article:section\" content=\"Like \u0e2a\u0e32\u0e23\u0e30\" \/>\n<meta property=\"article:section\" content=\"\u0e02\u0e48\u0e32\u0e27\u0e40\u0e14\u0e48\u0e19\" \/>\n<meta property=\"article:section\" content=\"\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\" \/>\n<meta property=\"article:section\" content=\"\u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04\" \/>\n<meta property=\"article:section\" content=\"\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u0e22\u0e31\u0e01\u0e29\u0e4c\u0e43\u0e2b\u0e0d\u0e48\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e17\u0e48\u0e32! \u0e40\u0e23\u0e37\u0e2d\u2018USS Abraham Lincoln\u2019 \u0e16\u0e36\u0e07\u0e41\u0e2b\u0e25\u0e21\u0e09\u0e1a\u0e31\u0e07-\u0e02\u0e19\u0e17\u0e2b\u0e32\u0e23 5 \u0e1e\u0e31\u0e19\u0e19\u0e32\u0e22\u0e1a\u0e38\u0e01\u0e1e\u0e31\u0e17\u0e22\u0e32 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.naewna.com\/n\/top-stories\/38548\/","og_locale":"th_TH","og_type":"article","og_title":"\u0e22\u0e31\u0e01\u0e29\u0e4c\u0e43\u0e2b\u0e0d\u0e48\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e17\u0e48\u0e32! \u0e40\u0e23\u0e37\u0e2d\u2018USS Abraham Lincoln\u2019 \u0e16\u0e36\u0e07\u0e41\u0e2b\u0e25\u0e21\u0e09\u0e1a\u0e31\u0e07-\u0e02\u0e19\u0e17\u0e2b\u0e32\u0e23 5 \u0e1e\u0e31\u0e19\u0e19\u0e32\u0e22\u0e1a\u0e38\u0e01\u0e1e\u0e31\u0e17\u0e22\u0e32","og_description":"\u0e22\u0e31\u0e01\u0e29\u0e4c\u0e43\u0e2b\u0e0d\u0e48\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e17\u0e48\u0e32! \u0e40\u0e23\u0e37\u0e2d\u0e2a\u0e2b\u0e23\u0e31\u0e10\u0e2f \u2018USS Abraham Lincoln\u2019 \u0e16\u0e36\u0e07 [&hellip;]","og_url":"https:\/\/www.naewna.com\/n\/top-stories\/38548\/","og_site_name":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32","article_publisher":"https:\/\/www.facebook.com\/NaewnaOnline","article_published_time":"2026-09-02T04:37:42+00:00","article_modified_time":"2026-09-02T05:00:19+00:00","og_image":[{"width":1080,"height":590,"url":"https:\/\/storage-wp.naewna.com\/2026\/09\/S__17342505_0.jpg","type":"image\/jpeg"}],"author":"\u0e04\u0e23\u0e34\u0e2a\u0e15\u0e4c\u0e44\u0e07\u0e08\u0e30\u0e43\u0e04\u0e23\u0e25\u0e48\u0e30","twitter_card":"summary_large_image","twitter_creator":"@naewna_news","twitter_site":"@naewna_news","twitter_misc":{"Written by":"\u0e04\u0e23\u0e34\u0e2a\u0e15\u0e4c\u0e44\u0e07\u0e08\u0e30\u0e43\u0e04\u0e23\u0e25\u0e48\u0e30"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.naewna.com\/n\/top-stories\/38548\/#article","isPartOf":{"@id":"https:\/\/www.naewna.com\/n\/top-stories\/38548\/"},"author":{"name":"\u0e04\u0e23\u0e34\u0e2a\u0e15\u0e4c\u0e44\u0e07\u0e08\u0e30\u0e43\u0e04\u0e23\u0e25\u0e48\u0e30","@id":"https:\/\/www.naewna.com\/n\/#\/schema\/person\/89786e63af3279dd8041bb8a5d30a3f3"},"headline":"\u0e22\u0e31\u0e01\u0e29\u0e4c\u0e43\u0e2b\u0e0d\u0e48\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e17\u0e48\u0e32! \u0e40\u0e23\u0e37\u0e2d\u2018USS Abraham Lincoln\u2019 \u0e16\u0e36\u0e07\u0e41\u0e2b\u0e25\u0e21\u0e09\u0e1a\u0e31\u0e07-\u0e02\u0e19\u0e17\u0e2b\u0e32\u0e23 5 \u0e1e\u0e31\u0e19\u0e19\u0e32\u0e22\u0e1a\u0e38\u0e01\u0e1e\u0e31\u0e17\u0e22\u0e32","datePublished":"2026-09-02T04:37:42+00:00","dateModified":"2026-09-02T05:00:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.naewna.com\/n\/top-stories\/38548\/"},"wordCount":17,"image":{"@id":"https:\/\/www.naewna.com\/n\/top-stories\/38548\/#primaryimage"},"thumbnailUrl":"https:\/\/storage-wp.naewna.com\/2026\/09\/S__17342505_0.jpg","keywords":["CVN72","USSAbrahamLincoln","\u0e01\u0e2d\u0e07\u0e17\u0e31\u0e1e\u0e40\u0e23\u0e37\u0e2d\u0e2a\u0e2b\u0e23\u0e31\u0e10","\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35","\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e41\u0e2b\u0e25\u0e21\u0e09\u0e1a\u0e31\u0e07","\u0e1e\u0e31\u0e17\u0e22\u0e32"],"articleSection":["Breaking News","Like \u0e2a\u0e32\u0e23\u0e30","\u0e02\u0e48\u0e32\u0e27\u0e40\u0e14\u0e48\u0e19","\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27","\u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04","\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28"],"inLanguage":"th","copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/www.naewna.com\/n\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.naewna.com\/n\/top-stories\/38548\/","url":"https:\/\/www.naewna.com\/n\/top-stories\/38548\/","name":"\u0e22\u0e31\u0e01\u0e29\u0e4c\u0e43\u0e2b\u0e0d\u0e48\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e17\u0e48\u0e32! \u0e40\u0e23\u0e37\u0e2d\u2018USS Abraham Lincoln\u2019 \u0e16\u0e36\u0e07\u0e41\u0e2b\u0e25\u0e21\u0e09\u0e1a\u0e31\u0e07-\u0e02\u0e19\u0e17\u0e2b\u0e32\u0e23 5 \u0e1e\u0e31\u0e19\u0e19\u0e32\u0e22\u0e1a\u0e38\u0e01\u0e1e\u0e31\u0e17\u0e22\u0e32 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32","isPartOf":{"@id":"https:\/\/www.naewna.com\/n\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.naewna.com\/n\/top-stories\/38548\/#primaryimage"},"image":{"@id":"https:\/\/www.naewna.com\/n\/top-stories\/38548\/#primaryimage"},"thumbnailUrl":"https:\/\/storage-wp.naewna.com\/2026\/09\/S__17342505_0.jpg","datePublished":"2026-09-02T04:37:42+00:00","dateModified":"2026-09-02T05:00:19+00:00","author":{"@id":"https:\/\/www.naewna.com\/n\/#\/schema\/person\/89786e63af3279dd8041bb8a5d30a3f3"},"breadcrumb":{"@id":"https:\/\/www.naewna.com\/n\/top-stories\/38548\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.naewna.com\/n\/top-stories\/38548\/"]}]},{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.naewna.com\/n\/top-stories\/38548\/#primaryimage","url":"https:\/\/storage-wp.naewna.com\/2026\/09\/S__17342505_0.jpg","contentUrl":"https:\/\/storage-wp.naewna.com\/2026\/09\/S__17342505_0.jpg","width":1080,"height":590},{"@type":"BreadcrumbList","@id":"https:\/\/www.naewna.com\/n\/top-stories\/38548\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.naewna.com\/n\/"},{"@type":"ListItem","position":2,"name":"\u0e22\u0e31\u0e01\u0e29\u0e4c\u0e43\u0e2b\u0e0d\u0e48\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e17\u0e48\u0e32! \u0e40\u0e23\u0e37\u0e2d\u2018USS Abraham Lincoln\u2019 \u0e16\u0e36\u0e07\u0e41\u0e2b\u0e25\u0e21\u0e09\u0e1a\u0e31\u0e07-\u0e02\u0e19\u0e17\u0e2b\u0e32\u0e23 5 \u0e1e\u0e31\u0e19\u0e19\u0e32\u0e22\u0e1a\u0e38\u0e01\u0e1e\u0e31\u0e17\u0e22\u0e32"}]},{"@type":"WebSite","@id":"https:\/\/www.naewna.com\/n\/#website","url":"https:\/\/www.naewna.com\/n\/","name":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.naewna.com\/n\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"},{"@type":"Person","@id":"https:\/\/www.naewna.com\/n\/#\/schema\/person\/89786e63af3279dd8041bb8a5d30a3f3","name":"\u0e04\u0e23\u0e34\u0e2a\u0e15\u0e4c\u0e44\u0e07\u0e08\u0e30\u0e43\u0e04\u0e23\u0e25\u0e48\u0e30","image":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/secure.gravatar.com\/avatar\/7ef03eb2b6ecd67b446b219e9760f088d71d928554dbd66c46969f008aae8836?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7ef03eb2b6ecd67b446b219e9760f088d71d928554dbd66c46969f008aae8836?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7ef03eb2b6ecd67b446b219e9760f088d71d928554dbd66c46969f008aae8836?s=96&d=mm&r=g","caption":"\u0e04\u0e23\u0e34\u0e2a\u0e15\u0e4c\u0e44\u0e07\u0e08\u0e30\u0e43\u0e04\u0e23\u0e25\u0e48\u0e30"},"url":"https:\/\/www.naewna.com\/n\/author\/christmas_251237\/"}]}},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/storage-wp.naewna.com\/2026\/09\/S__17342505_0.jpg","_links":{"self":[{"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/posts\/38548","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/comments?post=38548"}],"version-history":[{"count":2,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/posts\/38548\/revisions"}],"predecessor-version":[{"id":38617,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/posts\/38548\/revisions\/38617"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/media\/38555"}],"wp:attachment":[{"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/media?parent=38548"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/categories?post=38548"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/tags?post=38548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}