{"id":38591,"date":"2026-09-02T11:49:37","date_gmt":"2026-09-02T04:49:37","guid":{"rendered":"https:\/\/www.naewna.com\/n\/?p=38591"},"modified":"2026-09-02T11:51:13","modified_gmt":"2026-09-02T04:51:13","slug":"%e0%b8%a2%e0%b8%b4%e0%b8%9b%e0%b8%8b%e0%b8%b5%e0%b8%9e%e0%b8%a2%e0%b8%b2%e0%b8%81%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%94%e0%b8%a7%e0%b8%87%e0%b8%a3%e0%b8%b2%e0%b8%a2%e0%b8%a7%e0%b8%b1%e0%b8%99-18","status":"publish","type":"post","link":"https:\/\/www.naewna.com\/n\/women\/38591\/","title":{"rendered":"\u0e22\u0e34\u0e1b\u0e0b\u0e35\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e13\u0e4c\u0e14\u0e27\u0e07\u0e23\u0e32\u0e22\u0e27\u0e31\u0e19 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19\u200b\u0e1e\u0e38\u0e18 2\u00a0\u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19\u00a02569"},"content":{"rendered":"<div class=\"vce-row-container\" data-vce-boxed-width=\"true\"><div class=\"vce-row vce-row--col-gap-30 vce-row-equal-height vce-row-content--top\" id=\"el-3659af57\" data-vce-do-apply=\"all el-3659af57\"><div class=\"vce-row-content\" data-vce-element-content=\"true\"><div class=\"vce-col vce-col--md-auto vce-col--xs-1 vce-col--xs-last vce-col--xs-first vce-col--sm-last vce-col--sm-first vce-col--md-last vce-col--lg-last vce-col--xl-last vce-col--md-first vce-col--lg-first vce-col--xl-first\" id=\"el-06f0d9bd\"><div class=\"vce-col-inner\" data-vce-do-apply=\"border margin background  el-06f0d9bd\"><div class=\"vce-col-content\" data-vce-element-content=\"true\" data-vce-do-apply=\"padding el-06f0d9bd\"><div class=\"vce-text-block\"><div class=\"vce-text-block-wrapper vce\" id=\"el-7451cd1a\" data-vce-do-apply=\"all el-7451cd1a\"><div><strong>\u0e17\u0e48\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e27\u0e31\u0e19\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c&nbsp;&nbsp;<\/strong><\/div>\n<div dir=\"ltr\">&nbsp;<\/div>\n<div dir=\"ltr\">\u0e2d\u0e34\u0e17\u0e18\u0e34\u0e1e\u0e25\u0e02\u0e2d\u0e07\u0e44\u0e1e\u0e48 10 \u0e16\u0e49\u0e27\u0e22 (Ten of Cups) \u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e23\u0e31\u0e01\u0e2a\u0e14\u0e43\u0e2a\u0e2b\u0e25\u0e31\u0e07\u0e21\u0e35\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e01\u0e31<wbr>\u0e19\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e19\u0e35\u0e49 \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e2a\u0e14\u0e08\u0e30\u0e44\u0e14\u0e49\u0e1e\u0e1a\u0e04\u0e19\u0e15\u0e23\u0e07\u0e2a\u0e40\u0e1b\u0e01 \u0e40\u0e07\u0e34\u0e19\u0e17\u0e2d\u0e07\u0e40\u0e23\u0e34\u0e48\u0e21\u0e40\u0e14\u0e34\u0e19\u0e2a\u0e30\u0e1e\u0e31\u0e14\u0e04\u0e25\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u200b<wbr> \u0e01\u0e32\u0e23\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e42\u0e0a\u0e04\u0e44\u0e14\u0e49\u0e21\u0e32\u0e1a\u0e49\u0e32\u0e07\u0e08\u0e32\u0e01\u0e0d\u0e32\u0e15\u0e34\u0e21\u0e34<wbr>\u0e15\u0e23 \u0e07\u0e32\u0e19\u0e01\u0e49\u0e32\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e04\u0e48\u0e2d\u0e19\u0e02\u0e49\u0e32\u0e07\u0e14\u0e35 \u0e04\u0e49\u0e32\u0e02\u0e32\u0e22\u0e44\u0e1b\u0e44\u0e14\u0e49\u0e14\u0e35\u0e02\u0e36\u0e49\u0e19\u0e0a\u0e31\u0e14\u0e40\u0e08\u0e19<\/div>\n<div>&nbsp;<\/div>\n<div><strong>\u0e17\u0e48\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e27\u0e31\u0e19\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c<\/strong><\/div>\n<div dir=\"ltr\">&nbsp;<\/div>\n<div dir=\"ltr\">\u0e2d\u0e34\u0e17\u0e18\u0e34\u0e1e\u0e25\u0e02\u0e2d\u0e07\u0e44\u0e1e\u0e48 8 \u0e44\u0e21\u0e49\u0e40\u0e17\u0e49\u0e32 (Eight of Wands) \u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e04\u0e19\u0e04\u0e49\u0e32\u0e02\u0e32\u0e22\u0e40\u0e23\u0e34\u0e48\u0e21\u0e14\u0e35\u0e02\u0e36\u0e49\u0e19 \u0e41\u0e25\u0e30\u0e04\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e07\u0e32\u0e19\u0e01\u0e34\u0e19\u0e40\u0e07\u0e34\u0e19\u0e40\u0e14\u0e37<wbr>\u0e2d\u0e19\u0e1c\u0e25\u0e07\u0e32\u0e19\u200b\u0e08\u0e30\u0e14\u0e35\u0e02\u0e36\u0e49\u0e19\u200b \u0e04\u0e27\u0e32\u0e21\u0e23\u0e31\u0e01\u0e21\u0e35\u0e07\u0e2d\u0e19\u0e01\u0e31\u0e19\u0e1a\u0e49\u0e32\u0e07\u0e08\u0e32\u0e01\u0e40\u0e23\u0e37\u0e48<wbr>\u0e2d\u0e07\u0e40\u0e27\u0e25\u0e32 \u0e41\u0e15\u0e48\u0e44\u0e21\u0e48\u0e19\u0e32\u0e19\u0e08\u0e30\u0e01\u0e25\u0e31\u0e1a\u0e21\u0e32\u0e04\u0e37\u0e19\u0e14\u0e35\u0e01\u0e31\u0e19\u200b \u0e40\u0e07\u0e34\u0e19\u0e17\u0e2d\u0e07\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e44\u0e21\u0e48\u0e21\u0e32\u0e01\u0e14\u0e31\u0e07\u0e19\u0e31\u0e49\u0e19\u0e15\u0e49<wbr>\u0e2d\u0e07\u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e43\u0e0a\u0e49 \u0e2a\u0e48\u0e27\u0e19\u0e42\u0e0a\u0e04\u0e25\u0e32\u0e20\u0e44\u0e21\u0e48\u0e40\u0e14\u0e48\u0e19\u0e08\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e04\u0e32\u0e14\u0e2b\u0e31<wbr>\u0e07\u0e21\u0e32\u0e01\u0e19\u0e31\u0e01<\/div>\n<div>&nbsp;<\/div>\n<div><strong>\u0e17\u0e48\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e27\u0e31\u0e19\u0e2d\u0e31\u0e07\u0e04\u0e32\u0e23<\/strong><\/div>\n<div dir=\"ltr\">&nbsp;<\/div>\n<div dir=\"ltr\">\u0e2d\u0e34\u0e17\u0e18\u0e34\u0e1e\u0e25\u0e02\u0e2d\u0e07\u0e44\u0e1e\u0e48\u0e23\u0e32\u0e0a\u0e34\u0e19\u0e35\u0e16\u0e37\u0e2d\u0e16\u0e49\u0e27\u0e22 (Queen of Cups) \u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e40\u0e07\u0e34\u0e19\u0e17\u0e2d\u0e07\u0e40\u0e23\u0e34\u0e48\u0e21\u0e2b\u0e21\u0e38\u0e19\u0e44\u0e14\u0e49\u0e04\u0e25\u0e48\u0e2d\u0e07 \u0e02\u0e2d\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e43\u0e0a\u0e49\u0e08\u0e48\u0e32\u0e22\u0e40\u0e01\u0e34\u0e19\u0e15\u0e31\u0e27 \u0e04\u0e27\u0e32\u0e21\u0e23\u0e31\u0e01\u0e0a\u0e37\u0e48\u0e19\u0e21\u0e37\u0e48\u0e19\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e01\u0e31\u0e19\u0e41\u0e25\u0e30\u0e01\u0e31<wbr>\u0e19 \u0e2a\u0e48\u0e27\u0e19\u0e04\u0e19\u0e17\u0e35\u0e48\u0e41\u0e2d\u0e1a\u0e25\u0e38\u0e49\u0e19\u0e43\u0e04\u0e23 \u0e40\u0e02\u0e32\u0e21\u0e35\u0e17\u0e48\u0e32\u0e17\u0e35\u0e15\u0e48\u0e2d\u0e40\u0e23\u0e32\u0e14\u0e35\u0e02\u0e36\u0e49\u0e19 \u0e07\u0e32\u0e19\u0e40\u0e14\u0e48\u0e19\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e14\u0e35\u0e40\u0e08\u0e49\u0e32\u0e19\u0e32\u0e22\u0e0a\u0e37\u0e48\u0e19\u0e0a\u0e21 \u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e44\u0e14\u0e49\u0e04\u0e19\u0e1d\u0e35\u0e21\u0e37\u0e2d\u0e14\u0e35\u0e40\u0e02\u0e49<wbr>\u0e32\u0e21\u0e32\u0e0a\u0e48\u0e27\u0e22<\/div>\n<div>&nbsp;<\/div>\n<div><strong>\u0e17\u0e48\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e27\u0e31\u0e19\u0e1e\u0e38\u0e18<\/strong><\/div>\n<div>&nbsp;<\/div>\n<div>\u0e2d\u0e34\u0e17\u0e18\u0e34\u0e1e\u0e25\u0e02\u0e2d\u0e07\u0e44\u0e1e\u0e48\u0e19\u0e31\u0e01\u0e21\u0e32\u0e22\u0e32\u0e01\u0e25 (The Magician) \u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e40\u0e07\u0e34\u0e19\u0e17\u0e2d\u0e07\u0e40\u0e23\u0e34\u0e48\u0e21\u0e40\u0e14\u0e34\u0e19\u0e2a\u0e30\u0e1e\u0e31\u0e14\u0e21\u0e35<wbr>\u0e25\u0e32\u0e20\u0e25\u0e2d\u0e22\u0e40\u0e02\u0e49\u0e32\u200b\u0e21\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u200b\u0e44\u0e21\u0e48\u0e04\u0e32\u0e14\u0e1d\u0e31\u0e19 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e2b\u0e32\u0e22\u0e40\u0e04\u0e23\u0e35\u0e22\u0e14\u0e01\u0e31\u0e07\u0e27\u0e25\u0e43\u0e08 \u0e07\u0e32\u0e19\u0e44\u0e1b\u0e44\u0e14\u0e49\u0e14\u0e35\u0e21\u0e35\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e19\u0e48\u0e32\u0e1e\u0e2d\u0e43\u0e08 \u0e04\u0e49\u0e32\u0e02\u0e32\u0e22\u0e40\u0e23\u0e34\u0e48\u0e21\u0e14\u0e35\u0e02\u0e36\u0e49\u0e19\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e14\u0e35<wbr>\u0e46\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32 \u0e04\u0e27\u0e32\u0e21\u0e23\u0e31\u0e01\u0e04\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e01\u0e34\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e31<wbr>\u0e27\u0e44\u0e1b\u0e44\u0e14\u0e49\u0e14\u0e35\u0e14\u0e39\u0e2d\u0e1a\u0e2d\u0e38\u0e48\u0e19\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19<\/div>\n<div>&nbsp;<\/div>\n<div><strong>\u0e17\u0e48\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e27\u0e31\u0e19\u0e1e\u0e24\u0e2b\u0e31\u0e2a\u0e1a\u0e14\u0e35<\/strong><\/div>\n<div>&nbsp;<\/div>\n<div>\u0e2d\u0e34\u0e17\u0e18\u0e34\u0e1e\u0e25\u0e02\u0e2d\u0e07\u0e44\u0e1e\u0e48\u0e42\u0e25\u0e01 (The World) \u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e04\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2a\u0e48\u0e27\u0e19\u0e15\u0e31<wbr>\u0e27\u0e44\u0e1b\u0e44\u0e14\u0e49\u0e14\u0e35\u0e01\u0e27\u0e48\u0e32\u0e40\u0e14\u0e34\u0e21 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e01\u0e33\u0e25\u0e31\u0e07\u0e43\u0e08\u0e02\u0e36\u0e49\u0e19\u0e21\u0e32\u0e2d\u0e35<wbr>\u0e01\u0e21\u0e32\u0e01 \u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19\u0e42\u0e0a\u0e04\u0e25\u0e32\u0e20\u0e21\u0e35\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e2d\u0e22\u0e48<wbr>\u0e32\u0e07\u0e44\u0e21\u0e48\u0e04\u0e32\u0e14\u0e1d\u0e31\u0e19 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e2a\u0e20\u0e32\u0e27\u0e30\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19\u0e14\u0e35\u0e02\u0e36\u0e49\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e19\u0e48<wbr>\u0e32\u0e1e\u0e2d\u0e43\u0e08 \u0e04\u0e27\u0e32\u0e21\u0e23\u0e31\u0e01\u0e2a\u0e14\u0e43\u0e2a\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e40\u0e04\u0e25\u0e35\u0e22\u0e23\u0e37\u0e43\u0e08\u0e01\u0e31<wbr>\u0e19\u0e44\u0e14\u0e49 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e2a\u0e14\u0e43\u0e2a\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19\u0e01\u0e27\u0e48\u0e32\u0e40\u0e14\u0e34\u0e21<\/div>\n<div>&nbsp;<\/div>\n<div><strong>\u0e17\u0e48\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e27\u0e31\u0e19\u0e28\u0e38\u0e01\u0e23\u0e4c<\/strong><\/div>\n<div>&nbsp;<\/div>\n<div>\u0e2d\u0e34\u0e17\u0e18\u0e34\u0e1e\u0e25\u0e02\u0e2d\u0e07\u0e44\u0e1e\u0e48\u0e01\u0e07\u0e25\u0e49\u0e2d\u0e21\u0e2b\u0e32\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34 (Wheel of Fortune) \u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e40\u0e07\u0e34\u0e19\u0e17\u0e2d\u0e07\u0e40\u0e14\u0e34\u0e19\u0e2a\u0e30\u0e1e\u0e31\u0e14\u0e21\u0e35\u0e40\u0e02\u0e49<wbr>\u0e32\u0e21\u0e32\u0e1f\u0e25\u0e38\u0e01\u0e46\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e21\u0e48\u0e04\u0e32\u0e14\u0e1d\u0e31\u0e19 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e01\u0e49\u0e32\u0e27\u0e40\u0e14\u0e34\u0e19\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e44\u0e14\u0e49 \u0e04\u0e27\u0e32\u0e21\u0e23\u0e31\u0e01\u0e40\u0e23\u0e34\u0e48\u0e21\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e38\u0e02\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e1b\u0e23\u0e31<wbr>\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e01\u0e31\u0e19 \u0e07\u0e32\u0e19\u0e40\u0e14\u0e48\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e19\u0e48\u0e32\u0e1e\u0e36\u0e07\u0e1e\u0e2d\u0e43\u0e08 \u0e41\u0e25\u0e30\u0e04\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e2a\u0e48\u0e27\u0e19\u0e15\u0e31\u0e27\u0e40\u0e14\u0e34\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e44\u0e1b\u0e44\u0e14\u0e49<wbr>\u0e14\u0e35\u0e40\u0e01\u0e34\u0e19\u0e25\u0e38\u0e49\u0e19\u0e44\u0e27\u0e49<\/div>\n<div>&nbsp;<\/div>\n<div><strong>\u0e17\u0e48\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e27\u0e31\u0e19\u0e40\u0e2a\u0e32\u0e23\u0e4c<\/strong><\/div>\n<div dir=\"ltr\">&nbsp;<\/div>\n<div dir=\"ltr\">\u0e2d\u0e34\u0e17\u0e18\u0e34\u0e1e\u0e25\u0e02\u0e2d\u0e07\u0e44\u0e1e\u0e48\u0e23\u0e32\u0e0a\u0e32\u0e16\u0e37\u0e2d\u0e40\u0e2b\u0e23\u0e35\u0e22\u0e0d (King of Pentacles) \u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e42\u0e0a\u0e04\u0e14\u0e35\u0e21\u0e35\u0e40\u0e07\u0e34\u0e19\u0e1f\u0e25\u0e38\u0e01\u0e46\u0e40\u0e02\u0e49<wbr>\u0e32\u0e21\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e21\u0e48\u0e04\u0e32\u0e14\u0e1d\u0e31\u0e19 \u0e40\u0e07\u0e34\u0e19\u0e17\u0e2d\u0e07\u0e08\u0e36\u0e07\u0e40\u0e14\u0e34\u0e19\u0e2a\u0e30\u0e1e\u0e31\u0e14\u0e44\u0e21\u0e48\u0e15\u0e34\u0e14\u0e02\u0e31<wbr>\u0e14\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e01\u0e48\u0e2d\u0e19 \u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e07\u0e32\u0e19\u0e21\u0e35\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e42\u0e14\u0e14\u0e40\u0e14\u0e48\u0e19\u0e40\u0e08\u0e49<wbr>\u0e32\u0e19\u0e32\u0e22\u0e1e\u0e36\u0e07\u0e1e\u0e2d\u0e43\u0e08 \u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e21\u0e35\u0e07\u0e32\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e15\u0e31\u0e27\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34<wbr>\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e44\u0e1b\u0e44\u0e14\u0e49\u0e14\u0e35 \u0e04\u0e27\u0e32\u0e21\u0e23\u0e31\u0e01\u0e21\u0e35\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e01\u0e31\u0e19\u0e1a\u0e49\u0e32\u0e07\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e40\u0e23\u0e37\u0e48<wbr>\u0e2d\u0e07\u0e44\u0e21\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07<\/div>\n<div>&nbsp;<\/div>\n<div style=\"text-align: center;\"><strong>\u0e17\u0e48\u0e32\u0e19\u0e1c\u0e39\u0e49\u0e2d\u0e48\u0e32\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32<\/strong><\/div>\n<div style=\"text-align: center;\"><strong>\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e27\u0e07\u0e0a\u0e30\u0e15\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e27\u0e19\u0e15\u0e31\u0e27 \u0e01\u0e31\u0e1a \u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e01\u0e34\u0e15\u0e34\u0e04\u0e38\u0e13 \u0e1e\u0e25\u0e27\u0e31\u0e19<\/strong><\/div>\n<div style=\"text-align: center;\"><strong>\u0e2a\u0e2d\u0e1a\u0e16\u0e32\u0e21\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48<wbr>&nbsp;094-629-8799<\/strong><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u0e17\u0e48\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e27\u0e31\u0e19\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c&nbsp;&nbsp; &nbsp; \u0e2d\u0e34\u0e17\u0e18\u0e34\u0e1e\u0e25\u0e02\u0e2d\u0e07\u0e44\u0e1e\u0e48  [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":38593,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[340,13],"tags":[659,662,960],"class_list":["post-38591","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destiny-news","category-women","tag-659","tag-662","tag-960"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u0e22\u0e34\u0e1b\u0e0b\u0e35\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e13\u0e4c\u0e14\u0e27\u0e07\u0e23\u0e32\u0e22\u0e27\u0e31\u0e19 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19\u200b\u0e1e\u0e38\u0e18 2\u00a0\u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19\u00a02569 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.naewna.com\/n\/women\/38591\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e22\u0e34\u0e1b\u0e0b\u0e35\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e13\u0e4c\u0e14\u0e27\u0e07\u0e23\u0e32\u0e22\u0e27\u0e31\u0e19 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19\u200b\u0e1e\u0e38\u0e18 2\u00a0\u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19\u00a02569\" \/>\n<meta property=\"og:description\" content=\"\u0e17\u0e48\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e27\u0e31\u0e19\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c&nbsp;&nbsp; &nbsp; \u0e2d\u0e34\u0e17\u0e18\u0e34\u0e1e\u0e25\u0e02\u0e2d\u0e07\u0e44\u0e1e\u0e48 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.naewna.com\/n\/women\/38591\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NaewnaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2026-09-02T04:49:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-02T04:51:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/storage-wp.naewna.com\/2026\/09\/%E0%B8%9E%E0%B8%B8%E0%B8%98_0.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"607\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Netnapa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@naewna_news\" \/>\n<meta name=\"twitter:site\" content=\"@naewna_news\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Netnapa\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/women\\\/38591\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/women\\\/38591\\\/\"},\"author\":{\"name\":\"Netnapa\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#\\\/schema\\\/person\\\/8e1e5ae497ff2411c6f2ebd66cb920d9\"},\"headline\":\"\u0e22\u0e34\u0e1b\u0e0b\u0e35\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e13\u0e4c\u0e14\u0e27\u0e07\u0e23\u0e32\u0e22\u0e27\u0e31\u0e19 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19\u200b\u0e1e\u0e38\u0e18 2\u00a0\u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19\u00a02569\",\"datePublished\":\"2026-09-02T04:49:37+00:00\",\"dateModified\":\"2026-09-02T04:51:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/women\\\/38591\\\/\"},\"wordCount\":38,\"image\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/women\\\/38591\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/storage-wp.naewna.com\\\/2026\\\/09\\\/\u0e1e\u0e38\u0e18_0.jpg\",\"keywords\":[\"\u0e14\u0e27\u0e07\u0e23\u0e32\u0e22\u0e27\u0e31\u0e19\",\"\u0e14\u0e39\u0e14\u0e27\u0e07\",\"\u0e22\u0e34\u0e1b\u0e0b\u0e35\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e13\u0e4c\"],\"articleSection\":[\"\u0e14\u0e27\u0e07\u0e0a\u0e30\u0e15\u0e32\",\"\u0e1c\u0e39\u0e49\u0e2b\u0e0d\u0e34\u0e07\"],\"inLanguage\":\"th\",\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/women\\\/38591\\\/\",\"url\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/women\\\/38591\\\/\",\"name\":\"\u0e22\u0e34\u0e1b\u0e0b\u0e35\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e13\u0e4c\u0e14\u0e27\u0e07\u0e23\u0e32\u0e22\u0e27\u0e31\u0e19 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19\u200b\u0e1e\u0e38\u0e18 2\u00a0\u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19\u00a02569 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/women\\\/38591\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/women\\\/38591\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/storage-wp.naewna.com\\\/2026\\\/09\\\/\u0e1e\u0e38\u0e18_0.jpg\",\"datePublished\":\"2026-09-02T04:49:37+00:00\",\"dateModified\":\"2026-09-02T04:51:13+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#\\\/schema\\\/person\\\/8e1e5ae497ff2411c6f2ebd66cb920d9\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/women\\\/38591\\\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.naewna.com\\\/n\\\/women\\\/38591\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/women\\\/38591\\\/#primaryimage\",\"url\":\"https:\\\/\\\/storage-wp.naewna.com\\\/2026\\\/09\\\/\u0e1e\u0e38\u0e18_0.jpg\",\"contentUrl\":\"https:\\\/\\\/storage-wp.naewna.com\\\/2026\\\/09\\\/\u0e1e\u0e38\u0e18_0.jpg\",\"width\":1080,\"height\":607},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/women\\\/38591\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e22\u0e34\u0e1b\u0e0b\u0e35\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e13\u0e4c\u0e14\u0e27\u0e07\u0e23\u0e32\u0e22\u0e27\u0e31\u0e19 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19\u200b\u0e1e\u0e38\u0e18 2\u00a0\u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19\u00a02569\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#website\",\"url\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/\",\"name\":\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#\\\/schema\\\/person\\\/8e1e5ae497ff2411c6f2ebd66cb920d9\",\"name\":\"Netnapa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/edbccfcff1f6430f6cd3b17fd66b7f4c46f0bfc77579e12305da938dad515034?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/edbccfcff1f6430f6cd3b17fd66b7f4c46f0bfc77579e12305da938dad515034?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/edbccfcff1f6430f6cd3b17fd66b7f4c46f0bfc77579e12305da938dad515034?s=96&d=mm&r=g\",\"caption\":\"Netnapa\"},\"url\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/author\\\/netnapa\\\/\"}]}<\/script>\n<meta property=\"article:section\" content=\"\u0e14\u0e27\u0e07\u0e0a\u0e30\u0e15\u0e32\" \/>\n<meta property=\"article:section\" content=\"\u0e1c\u0e39\u0e49\u0e2b\u0e0d\u0e34\u0e07\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u0e22\u0e34\u0e1b\u0e0b\u0e35\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e13\u0e4c\u0e14\u0e27\u0e07\u0e23\u0e32\u0e22\u0e27\u0e31\u0e19 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19\u200b\u0e1e\u0e38\u0e18 2\u00a0\u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19\u00a02569 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.naewna.com\/n\/women\/38591\/","og_locale":"th_TH","og_type":"article","og_title":"\u0e22\u0e34\u0e1b\u0e0b\u0e35\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e13\u0e4c\u0e14\u0e27\u0e07\u0e23\u0e32\u0e22\u0e27\u0e31\u0e19 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19\u200b\u0e1e\u0e38\u0e18 2\u00a0\u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19\u00a02569","og_description":"\u0e17\u0e48\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e27\u0e31\u0e19\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c&nbsp;&nbsp; &nbsp; \u0e2d\u0e34\u0e17\u0e18\u0e34\u0e1e\u0e25\u0e02\u0e2d\u0e07\u0e44\u0e1e\u0e48 [&hellip;]","og_url":"https:\/\/www.naewna.com\/n\/women\/38591\/","og_site_name":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32","article_publisher":"https:\/\/www.facebook.com\/NaewnaOnline","article_published_time":"2026-09-02T04:49:37+00:00","article_modified_time":"2026-09-02T04:51:13+00:00","og_image":[{"width":1080,"height":607,"url":"https:\/\/storage-wp.naewna.com\/2026\/09\/%E0%B8%9E%E0%B8%B8%E0%B8%98_0.jpg","type":"image\/jpeg"}],"author":"Netnapa","twitter_card":"summary_large_image","twitter_creator":"@naewna_news","twitter_site":"@naewna_news","twitter_misc":{"Written by":"Netnapa"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.naewna.com\/n\/women\/38591\/#article","isPartOf":{"@id":"https:\/\/www.naewna.com\/n\/women\/38591\/"},"author":{"name":"Netnapa","@id":"https:\/\/www.naewna.com\/n\/#\/schema\/person\/8e1e5ae497ff2411c6f2ebd66cb920d9"},"headline":"\u0e22\u0e34\u0e1b\u0e0b\u0e35\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e13\u0e4c\u0e14\u0e27\u0e07\u0e23\u0e32\u0e22\u0e27\u0e31\u0e19 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19\u200b\u0e1e\u0e38\u0e18 2\u00a0\u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19\u00a02569","datePublished":"2026-09-02T04:49:37+00:00","dateModified":"2026-09-02T04:51:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.naewna.com\/n\/women\/38591\/"},"wordCount":38,"image":{"@id":"https:\/\/www.naewna.com\/n\/women\/38591\/#primaryimage"},"thumbnailUrl":"https:\/\/storage-wp.naewna.com\/2026\/09\/\u0e1e\u0e38\u0e18_0.jpg","keywords":["\u0e14\u0e27\u0e07\u0e23\u0e32\u0e22\u0e27\u0e31\u0e19","\u0e14\u0e39\u0e14\u0e27\u0e07","\u0e22\u0e34\u0e1b\u0e0b\u0e35\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e13\u0e4c"],"articleSection":["\u0e14\u0e27\u0e07\u0e0a\u0e30\u0e15\u0e32","\u0e1c\u0e39\u0e49\u0e2b\u0e0d\u0e34\u0e07"],"inLanguage":"th","copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/www.naewna.com\/n\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.naewna.com\/n\/women\/38591\/","url":"https:\/\/www.naewna.com\/n\/women\/38591\/","name":"\u0e22\u0e34\u0e1b\u0e0b\u0e35\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e13\u0e4c\u0e14\u0e27\u0e07\u0e23\u0e32\u0e22\u0e27\u0e31\u0e19 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19\u200b\u0e1e\u0e38\u0e18 2\u00a0\u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19\u00a02569 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32","isPartOf":{"@id":"https:\/\/www.naewna.com\/n\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.naewna.com\/n\/women\/38591\/#primaryimage"},"image":{"@id":"https:\/\/www.naewna.com\/n\/women\/38591\/#primaryimage"},"thumbnailUrl":"https:\/\/storage-wp.naewna.com\/2026\/09\/\u0e1e\u0e38\u0e18_0.jpg","datePublished":"2026-09-02T04:49:37+00:00","dateModified":"2026-09-02T04:51:13+00:00","author":{"@id":"https:\/\/www.naewna.com\/n\/#\/schema\/person\/8e1e5ae497ff2411c6f2ebd66cb920d9"},"breadcrumb":{"@id":"https:\/\/www.naewna.com\/n\/women\/38591\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.naewna.com\/n\/women\/38591\/"]}]},{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.naewna.com\/n\/women\/38591\/#primaryimage","url":"https:\/\/storage-wp.naewna.com\/2026\/09\/\u0e1e\u0e38\u0e18_0.jpg","contentUrl":"https:\/\/storage-wp.naewna.com\/2026\/09\/\u0e1e\u0e38\u0e18_0.jpg","width":1080,"height":607},{"@type":"BreadcrumbList","@id":"https:\/\/www.naewna.com\/n\/women\/38591\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.naewna.com\/n\/"},{"@type":"ListItem","position":2,"name":"\u0e22\u0e34\u0e1b\u0e0b\u0e35\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e13\u0e4c\u0e14\u0e27\u0e07\u0e23\u0e32\u0e22\u0e27\u0e31\u0e19 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19\u200b\u0e1e\u0e38\u0e18 2\u00a0\u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19\u00a02569"}]},{"@type":"WebSite","@id":"https:\/\/www.naewna.com\/n\/#website","url":"https:\/\/www.naewna.com\/n\/","name":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.naewna.com\/n\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"},{"@type":"Person","@id":"https:\/\/www.naewna.com\/n\/#\/schema\/person\/8e1e5ae497ff2411c6f2ebd66cb920d9","name":"Netnapa","image":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/secure.gravatar.com\/avatar\/edbccfcff1f6430f6cd3b17fd66b7f4c46f0bfc77579e12305da938dad515034?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/edbccfcff1f6430f6cd3b17fd66b7f4c46f0bfc77579e12305da938dad515034?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/edbccfcff1f6430f6cd3b17fd66b7f4c46f0bfc77579e12305da938dad515034?s=96&d=mm&r=g","caption":"Netnapa"},"url":"https:\/\/www.naewna.com\/n\/author\/netnapa\/"}]}},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/storage-wp.naewna.com\/2026\/09\/\u0e1e\u0e38\u0e18_0.jpg","_links":{"self":[{"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/posts\/38591","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/comments?post=38591"}],"version-history":[{"count":2,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/posts\/38591\/revisions"}],"predecessor-version":[{"id":38596,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/posts\/38591\/revisions\/38596"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/media\/38593"}],"wp:attachment":[{"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/media?parent=38591"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/categories?post=38591"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/tags?post=38591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}