{"id":38672,"date":"2026-09-02T12:25:18","date_gmt":"2026-09-02T05:25:18","guid":{"rendered":"https:\/\/www.naewna.com\/n\/?p=38672"},"modified":"2026-09-02T12:25:19","modified_gmt":"2026-09-02T05:25:19","slug":"%e0%b8%ad%e0%b8%b2%e0%b9%80%e0%b8%8b%e0%b8%b5%e0%b8%a2%e0%b8%99%e0%b9%80%e0%b8%a3%e0%b9%88%e0%b8%87%e0%b8%aa%e0%b8%a3%e0%b9%89%e0%b8%b2%e0%b8%87%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b8%a1%e0%b8%b1","status":"publish","type":"post","link":"https:\/\/www.naewna.com\/n\/business-world\/38672\/","title":{"rendered":"\u0e2d\u0e32\u0e40\u0e0b\u0e35\u0e22\u0e19\u0e40\u0e23\u0e48\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e17\u0e32\u0e07\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e23\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e42\u0e25\u0e01\u0e1c\u0e31\u0e19\u0e1c\u0e27\u0e19"},"content":{"rendered":"<div class=\"vce-row-container\" data-vce-boxed-width=\"true\"><div class=\"vce-row vce-row--col-gap-30 vce-row-equal-height vce-row-content--top\" id=\"el-d1404085\" data-vce-do-apply=\"all el-d1404085\"><div class=\"vce-row-content\" data-vce-element-content=\"true\"><div class=\"vce-col vce-col--md-auto vce-col--xs-1 vce-col--xs-last vce-col--xs-first vce-col--sm-last vce-col--sm-first vce-col--md-last vce-col--lg-last vce-col--xl-last vce-col--md-first vce-col--lg-first vce-col--xl-first\" id=\"el-bd766205\"><div class=\"vce-col-inner\" data-vce-do-apply=\"border margin background  el-bd766205\"><div class=\"vce-col-content\" data-vce-element-content=\"true\" data-vce-do-apply=\"padding el-bd766205\"><div class=\"vce-text-block\"><div class=\"vce-text-block-wrapper vce\" id=\"el-da43be21\" data-vce-do-apply=\"all el-da43be21\"><p><strong>\u2018\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u2019 \u0e23\u0e48\u0e27\u0e21\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e39\u0e07\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e23\u0e27\u0e21\u0e01\u0e25\u0e38\u0e48\u0e21\u0e02\u0e2d\u0e07\u0e2d\u0e32\u0e40\u0e0b\u0e35\u0e22\u0e19 \u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\u0e21\u0e38\u0e21\u0e21\u0e2d\u0e07\u0e40\u0e2d\u0e01\u0e0a\u0e19-\u0e19\u0e31\u0e01\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e2d\u0e32\u0e40\u0e0b\u0e35\u0e22\u0e19\u0e23\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e17\u0e32\u0e07\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e08\u0e31\u0e14\u0e17\u0e33\u0e02\u0e49\u0e2d\u0e40\u0e2a\u0e19\u0e2d\u0e41\u0e19\u0e30\u0e15\u0e48\u0e2d\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e2d\u0e32\u0e40\u0e0b\u0e35\u0e22\u0e19 \u0e40\u0e14\u0e37\u0e2d\u0e19 \u0e01.\u0e22.\u0e19\u0e35\u0e49<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-38685\" src=\"https:\/\/storage-wp.naewna.com\/2026\/09\/10-2.jpg\" alt=\"\" width=\"1080\" height=\"607\"><\/p>\n<p>\u0e19\u0e32\u0e22\u0e40\u0e2d\u0e01\u0e09\u0e31\u0e15\u0e23 \u0e28\u0e35\u0e15\u0e27\u0e23\u0e23\u0e31\u0e15\u0e19\u0e4c \u0e23\u0e2d\u0e07\u0e1b\u0e25\u0e31\u0e14\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e40\u0e1b\u0e34\u0e14\u0e40\u0e1c\u0e22\u0e27\u0e48\u0e32 \u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e17\u0e33\u0e07\u0e32\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e39\u0e07\u0e27\u0e48\u0e32\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e23\u0e27\u0e21\u0e01\u0e25\u0e38\u0e48\u0e21\u0e17\u0e32\u0e07\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e02\u0e2d\u0e07\u0e2d\u0e32\u0e40\u0e0b\u0e35\u0e22\u0e19 (HLTF-EI) \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 50 \u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 26-28 \u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21 2569 \u0e13 \u0e01\u0e23\u0e38\u0e07\u0e21\u0e30\u0e19\u0e34\u0e25\u0e32 \u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e23\u0e31\u0e10\u0e1f\u0e34\u0e25\u0e34\u0e1b\u0e1b\u0e34\u0e19\u0e2a\u0e4c \u0e44\u0e14\u0e49\u0e23\u0e48\u0e27\u0e21\u0e2b\u0e32\u0e23\u0e37\u0e2d\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2b\u0e47\u0e19\u0e01\u0e31\u0e1a\u0e20\u0e32\u0e04\u0e40\u0e2d\u0e01\u0e0a\u0e19\u0e41\u0e25\u0e30\u0e19\u0e31\u0e01\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e17\u0e31\u0e49\u0e07\u0e08\u0e32\u0e01\u0e20\u0e32\u0e22\u0e43\u0e19\u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04\u0e41\u0e25\u0e30\u0e08\u0e32\u0e01\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e17\u0e32\u0e07\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01 \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e2a\u0e2b\u0e23\u0e32\u0e0a\u0e2d\u0e32\u0e13\u0e32\u0e08\u0e31\u0e01\u0e23 \u0e44\u0e14\u0e49\u0e40\u0e2b\u0e47\u0e19\u0e1e\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e16\u0e36\u0e07\u0e04\u0e27\u0e32\u0e21\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e32\u0e40\u0e0b\u0e35\u0e22\u0e19\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e19\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e39\u0e49 \u0e1b\u0e23\u0e31\u0e1a\u0e15\u0e31\u0e27 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e01\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\u0e46 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19 \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e42\u0e22\u0e07\u0e01\u0e31\u0e1a\u0e2b\u0e48\u0e27\u0e07\u0e42\u0e0b\u0e48\u0e2d\u0e38\u0e1b\u0e17\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e42\u0e25\u0e01 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e23\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e01\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e17\u0e35\u0e48\u0e2d\u0e32\u0e40\u0e0b\u0e35\u0e22\u0e19\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e1c\u0e0a\u0e34\u0e0d\u0e08\u0e32\u0e01\u0e04\u0e27\u0e32\u0e21\u0e1c\u0e31\u0e19\u0e1c\u0e27\u0e19\u0e17\u0e32\u0e07\u0e20\u0e39\u0e21\u0e34\u0e23\u0e31\u0e10\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e42\u0e25\u0e01\u0e43\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19 \u0e42\u0e14\u0e22\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e17\u0e32\u0e07\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e43\u0e19\u0e23\u0e30\u0e22\u0e30\u0e22\u0e32\u0e27<\/p>\n<p>\u0e19\u0e32\u0e22\u0e40\u0e2d\u0e01\u0e09\u0e31\u0e15\u0e23 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32 \u0e41\u0e21\u0e49\u0e1b\u0e23\u0e30\u0e40\u0e14\u0e47\u0e19\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e17\u0e32\u0e07\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e08\u0e30\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e21\u0e32\u0e22\u0e41\u0e25\u0e30\u0e02\u0e2d\u0e1a\u0e40\u0e02\u0e15\u0e17\u0e35\u0e48\u0e01\u0e27\u0e49\u0e32\u0e07 \u0e41\u0e15\u0e48\u0e2d\u0e32\u0e40\u0e0b\u0e35\u0e22\u0e19\u0e40\u0e2b\u0e47\u0e19\u0e15\u0e23\u0e07\u0e01\u0e31\u0e19\u0e27\u0e48\u0e32 \u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e17\u0e32\u0e07\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08 \u0e44\u0e21\u0e48\u0e04\u0e27\u0e23\u0e19\u0e33\u0e44\u0e1b\u0e2a\u0e39\u0e48\u0e21\u0e32\u0e15\u0e23\u0e01\u0e32\u0e23\u0e01\u0e35\u0e14\u0e01\u0e31\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e41\u0e15\u0e48\u0e04\u0e27\u0e23\u0e21\u0e38\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e02\u0e2d\u0e07\u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04\u0e43\u0e19\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e01\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e44\u0e21\u0e48\u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19\u0e43\u0e19\u0e23\u0e30\u0e22\u0e30\u0e22\u0e32\u0e27 \u0e42\u0e14\u0e22\u0e22\u0e31\u0e07\u0e04\u0e07\u0e22\u0e36\u0e14\u0e21\u0e31\u0e48\u0e19\u0e43\u0e19\u0e2b\u0e25\u0e31\u0e01\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e2d\u0e32\u0e40\u0e0b\u0e35\u0e22\u0e19\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e40\u0e1b\u0e34\u0e14 \u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e41\u0e1a\u0e1a\u0e1e\u0e2b\u0e38\u0e20\u0e32\u0e04\u0e35 \u0e41\u0e25\u0e30\u0e22\u0e36\u0e14\u0e21\u0e31\u0e48\u0e19\u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e1a\u0e19\u0e01\u0e0e\u0e01\u0e15\u0e34\u0e01\u0e32 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e31\u0e49\u0e07\u0e04\u0e27\u0e23\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e25\u0e44\u0e01\u0e43\u0e19\u0e01\u0e32\u0e23 \u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e2a\u0e32\u0e02\u0e32 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e23\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e01\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e1c\u0e31\u0e19\u0e1c\u0e27\u0e19\u0e08\u0e32\u0e01\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e23\u0e27\u0e14\u0e40\u0e23\u0e47\u0e27\u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e43\u0e19\u0e17\u0e34\u0e28\u0e17\u0e32\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19 \u0e42\u0e14\u0e22\u0e08\u0e30\u0e08\u0e31\u0e14\u0e17\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e02\u0e49\u0e2d\u0e40\u0e2a\u0e19\u0e2d\u0e40\u0e0a\u0e34\u0e07\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e15\u0e48\u0e2d\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e2d\u0e32\u0e40\u0e0b\u0e35\u0e22\u0e19 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 58 \u0e43\u0e19\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2569 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e17\u0e32\u0e07\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e02\u0e2d\u0e07\u0e2d\u0e32\u0e40\u0e0b\u0e35\u0e22\u0e19\u0e41\u0e25\u0e30\u0e40\u0e2a\u0e19\u0e2d\u0e15\u0e48\u0e2d\u0e1c\u0e39\u0e49\u0e19\u0e33\u0e2d\u0e32\u0e40\u0e0b\u0e35\u0e22\u0e19\u0e15\u0e48\u0e2d\u0e44\u0e1b<\/p>\n<p>&nbsp;<\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u2018\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u2019 \u0e23\u0e48\u0e27\u0e21\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e39\u0e07\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e23\u0e27\u0e21\u0e01\u0e25\u0e38\u0e48\u0e21 [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":38686,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[375,6],"tags":[3947,157,1510,176],"class_list":["post-38672","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-commerce-industry","category-business-world","tag-3947","tag-157","tag-1510","tag-176"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u0e2d\u0e32\u0e40\u0e0b\u0e35\u0e22\u0e19\u0e40\u0e23\u0e48\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e17\u0e32\u0e07\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e23\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e42\u0e25\u0e01\u0e1c\u0e31\u0e19\u0e1c\u0e27\u0e19 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.naewna.com\/n\/business-world\/38672\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e2d\u0e32\u0e40\u0e0b\u0e35\u0e22\u0e19\u0e40\u0e23\u0e48\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e17\u0e32\u0e07\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e23\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e42\u0e25\u0e01\u0e1c\u0e31\u0e19\u0e1c\u0e27\u0e19\" \/>\n<meta property=\"og:description\" content=\"\u2018\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u2019 \u0e23\u0e48\u0e27\u0e21\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e39\u0e07\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e23\u0e27\u0e21\u0e01\u0e25\u0e38\u0e48\u0e21 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.naewna.com\/n\/business-world\/38672\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NaewnaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2026-09-02T05:25:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-02T05:25:19+00:00\" \/>\n<meta name=\"author\" content=\"\u0e1a\u0e2d\u0e25 (\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08 : \u0e42\u0e25\u0e01\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08)\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@naewna_news\" \/>\n<meta name=\"twitter:site\" content=\"@naewna_news\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u0e1a\u0e2d\u0e25 (\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08 : \u0e42\u0e25\u0e01\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08)\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/business-world\\\/38672\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/business-world\\\/38672\\\/\"},\"author\":{\"name\":\"\u0e1a\u0e2d\u0e25 (\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08 : \u0e42\u0e25\u0e01\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08)\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#\\\/schema\\\/person\\\/af74f237318be7c0827695b155857e0c\"},\"headline\":\"\u0e2d\u0e32\u0e40\u0e0b\u0e35\u0e22\u0e19\u0e40\u0e23\u0e48\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e17\u0e32\u0e07\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e23\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e42\u0e25\u0e01\u0e1c\u0e31\u0e19\u0e1c\u0e27\u0e19\",\"datePublished\":\"2026-09-02T05:25:18+00:00\",\"dateModified\":\"2026-09-02T05:25:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/business-world\\\/38672\\\/\"},\"wordCount\":4,\"image\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/business-world\\\/38672\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/storage-wp.naewna.com\\\/2026\\\/09\\\/9-4.jpg\",\"keywords\":[\"\u0e1e\u0e13.\",\"\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\",\"\u0e2d\u0e32\u0e40\u0e0b\u0e35\u0e22\u0e19\",\"\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\"],\"articleSection\":[\"\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c-\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\",\"\u0e42\u0e25\u0e01\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\"],\"inLanguage\":\"th\",\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/business-world\\\/38672\\\/\",\"url\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/business-world\\\/38672\\\/\",\"name\":\"\u0e2d\u0e32\u0e40\u0e0b\u0e35\u0e22\u0e19\u0e40\u0e23\u0e48\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e17\u0e32\u0e07\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e23\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e42\u0e25\u0e01\u0e1c\u0e31\u0e19\u0e1c\u0e27\u0e19 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/business-world\\\/38672\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/business-world\\\/38672\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/storage-wp.naewna.com\\\/2026\\\/09\\\/9-4.jpg\",\"datePublished\":\"2026-09-02T05:25:18+00:00\",\"dateModified\":\"2026-09-02T05:25:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#\\\/schema\\\/person\\\/af74f237318be7c0827695b155857e0c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/business-world\\\/38672\\\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.naewna.com\\\/n\\\/business-world\\\/38672\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/business-world\\\/38672\\\/#primaryimage\",\"url\":\"https:\\\/\\\/storage-wp.naewna.com\\\/2026\\\/09\\\/9-4.jpg\",\"contentUrl\":\"https:\\\/\\\/storage-wp.naewna.com\\\/2026\\\/09\\\/9-4.jpg\",\"width\":1080,\"height\":607},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/business-world\\\/38672\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e2d\u0e32\u0e40\u0e0b\u0e35\u0e22\u0e19\u0e40\u0e23\u0e48\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e17\u0e32\u0e07\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e23\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e42\u0e25\u0e01\u0e1c\u0e31\u0e19\u0e1c\u0e27\u0e19\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#website\",\"url\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/\",\"name\":\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#\\\/schema\\\/person\\\/af74f237318be7c0827695b155857e0c\",\"name\":\"\u0e1a\u0e2d\u0e25 (\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08 : \u0e42\u0e25\u0e01\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08)\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8daed82550edc04d49c4ca9b1b634f5038cec1ecd2d1e06717fb8bcec0059226?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8daed82550edc04d49c4ca9b1b634f5038cec1ecd2d1e06717fb8bcec0059226?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8daed82550edc04d49c4ca9b1b634f5038cec1ecd2d1e06717fb8bcec0059226?s=96&d=mm&r=g\",\"caption\":\"\u0e1a\u0e2d\u0e25 (\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08 : \u0e42\u0e25\u0e01\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08)\"},\"url\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/author\\\/kanatazz\\\/\"}]}<\/script>\n<meta property=\"article:section\" content=\"\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c-\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\" \/>\n<meta property=\"article:section\" content=\"\u0e42\u0e25\u0e01\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u0e2d\u0e32\u0e40\u0e0b\u0e35\u0e22\u0e19\u0e40\u0e23\u0e48\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e17\u0e32\u0e07\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e23\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e42\u0e25\u0e01\u0e1c\u0e31\u0e19\u0e1c\u0e27\u0e19 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.naewna.com\/n\/business-world\/38672\/","og_locale":"th_TH","og_type":"article","og_title":"\u0e2d\u0e32\u0e40\u0e0b\u0e35\u0e22\u0e19\u0e40\u0e23\u0e48\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e17\u0e32\u0e07\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e23\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e42\u0e25\u0e01\u0e1c\u0e31\u0e19\u0e1c\u0e27\u0e19","og_description":"\u2018\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u2019 \u0e23\u0e48\u0e27\u0e21\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e39\u0e07\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e23\u0e27\u0e21\u0e01\u0e25\u0e38\u0e48\u0e21 [&hellip;]","og_url":"https:\/\/www.naewna.com\/n\/business-world\/38672\/","og_site_name":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32","article_publisher":"https:\/\/www.facebook.com\/NaewnaOnline","article_published_time":"2026-09-02T05:25:18+00:00","article_modified_time":"2026-09-02T05:25:19+00:00","author":"\u0e1a\u0e2d\u0e25 (\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08 : \u0e42\u0e25\u0e01\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08)","twitter_card":"summary_large_image","twitter_creator":"@naewna_news","twitter_site":"@naewna_news","twitter_misc":{"Written by":"\u0e1a\u0e2d\u0e25 (\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08 : \u0e42\u0e25\u0e01\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08)"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.naewna.com\/n\/business-world\/38672\/#article","isPartOf":{"@id":"https:\/\/www.naewna.com\/n\/business-world\/38672\/"},"author":{"name":"\u0e1a\u0e2d\u0e25 (\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08 : \u0e42\u0e25\u0e01\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08)","@id":"https:\/\/www.naewna.com\/n\/#\/schema\/person\/af74f237318be7c0827695b155857e0c"},"headline":"\u0e2d\u0e32\u0e40\u0e0b\u0e35\u0e22\u0e19\u0e40\u0e23\u0e48\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e17\u0e32\u0e07\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e23\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e42\u0e25\u0e01\u0e1c\u0e31\u0e19\u0e1c\u0e27\u0e19","datePublished":"2026-09-02T05:25:18+00:00","dateModified":"2026-09-02T05:25:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.naewna.com\/n\/business-world\/38672\/"},"wordCount":4,"image":{"@id":"https:\/\/www.naewna.com\/n\/business-world\/38672\/#primaryimage"},"thumbnailUrl":"https:\/\/storage-wp.naewna.com\/2026\/09\/9-4.jpg","keywords":["\u0e1e\u0e13.","\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c","\u0e2d\u0e32\u0e40\u0e0b\u0e35\u0e22\u0e19","\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08"],"articleSection":["\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c-\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21","\u0e42\u0e25\u0e01\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08"],"inLanguage":"th","copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/www.naewna.com\/n\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.naewna.com\/n\/business-world\/38672\/","url":"https:\/\/www.naewna.com\/n\/business-world\/38672\/","name":"\u0e2d\u0e32\u0e40\u0e0b\u0e35\u0e22\u0e19\u0e40\u0e23\u0e48\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e17\u0e32\u0e07\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e23\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e42\u0e25\u0e01\u0e1c\u0e31\u0e19\u0e1c\u0e27\u0e19 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32","isPartOf":{"@id":"https:\/\/www.naewna.com\/n\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.naewna.com\/n\/business-world\/38672\/#primaryimage"},"image":{"@id":"https:\/\/www.naewna.com\/n\/business-world\/38672\/#primaryimage"},"thumbnailUrl":"https:\/\/storage-wp.naewna.com\/2026\/09\/9-4.jpg","datePublished":"2026-09-02T05:25:18+00:00","dateModified":"2026-09-02T05:25:19+00:00","author":{"@id":"https:\/\/www.naewna.com\/n\/#\/schema\/person\/af74f237318be7c0827695b155857e0c"},"breadcrumb":{"@id":"https:\/\/www.naewna.com\/n\/business-world\/38672\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.naewna.com\/n\/business-world\/38672\/"]}]},{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.naewna.com\/n\/business-world\/38672\/#primaryimage","url":"https:\/\/storage-wp.naewna.com\/2026\/09\/9-4.jpg","contentUrl":"https:\/\/storage-wp.naewna.com\/2026\/09\/9-4.jpg","width":1080,"height":607},{"@type":"BreadcrumbList","@id":"https:\/\/www.naewna.com\/n\/business-world\/38672\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.naewna.com\/n\/"},{"@type":"ListItem","position":2,"name":"\u0e2d\u0e32\u0e40\u0e0b\u0e35\u0e22\u0e19\u0e40\u0e23\u0e48\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e17\u0e32\u0e07\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e23\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e42\u0e25\u0e01\u0e1c\u0e31\u0e19\u0e1c\u0e27\u0e19"}]},{"@type":"WebSite","@id":"https:\/\/www.naewna.com\/n\/#website","url":"https:\/\/www.naewna.com\/n\/","name":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.naewna.com\/n\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"},{"@type":"Person","@id":"https:\/\/www.naewna.com\/n\/#\/schema\/person\/af74f237318be7c0827695b155857e0c","name":"\u0e1a\u0e2d\u0e25 (\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08 : \u0e42\u0e25\u0e01\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08)","image":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/secure.gravatar.com\/avatar\/8daed82550edc04d49c4ca9b1b634f5038cec1ecd2d1e06717fb8bcec0059226?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8daed82550edc04d49c4ca9b1b634f5038cec1ecd2d1e06717fb8bcec0059226?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8daed82550edc04d49c4ca9b1b634f5038cec1ecd2d1e06717fb8bcec0059226?s=96&d=mm&r=g","caption":"\u0e1a\u0e2d\u0e25 (\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08 : \u0e42\u0e25\u0e01\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08)"},"url":"https:\/\/www.naewna.com\/n\/author\/kanatazz\/"}]}},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/storage-wp.naewna.com\/2026\/09\/9-4.jpg","_links":{"self":[{"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/posts\/38672","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/comments?post=38672"}],"version-history":[{"count":2,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/posts\/38672\/revisions"}],"predecessor-version":[{"id":38688,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/posts\/38672\/revisions\/38688"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/media\/38686"}],"wp:attachment":[{"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/media?parent=38672"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/categories?post=38672"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/tags?post=38672"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}