{"id":38695,"date":"2026-09-02T12:36:13","date_gmt":"2026-09-02T05:36:13","guid":{"rendered":"https:\/\/www.naewna.com\/n\/?p=38695"},"modified":"2026-09-02T12:36:13","modified_gmt":"2026-09-02T05:36:13","slug":"%e0%b8%a3%e0%b8%b8%e0%b8%97%e0%b8%98%e0%b8%9e%e0%b8%a5-%e0%b9%80%e0%b8%9c%e0%b8%a2%e0%b8%94%e0%b8%b5%e0%b9%80%e0%b8%ad%e0%b8%aa%e0%b9%84%e0%b8%ad-%e0%b8%95%e0%b8%b1%e0%b9%89%e0%b8%87-%e0%b8%84","status":"publish","type":"post","link":"https:\/\/www.naewna.com\/n\/crime\/38695\/","title":{"rendered":"\u0e23\u0e38\u0e17\u0e18\u0e1e\u0e25 \u0e40\u0e1c\u0e22\u0e14\u0e35\u0e40\u0e2d\u0e2a\u0e44\u0e2d \u0e15\u0e31\u0e49\u0e07 \u0e04\u0e01\u0e01.\u0e2a\u0e2d\u0e1a\u0e27\u0e34\u0e19\u0e31\u0e22\u0e23\u0e49\u0e32\u0e22\u0e41\u0e23\u0e07 \u0e08\u0e19\u0e17.\u0e40\u0e2d\u0e35\u0e48\u0e22\u0e27 \u0e2a\u0e2d\u0e1a\u0e17\u0e38\u0e08\u0e23\u0e34\u0e15\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e01\u0e4a\u0e27\u0e19\u0e19\u0e32\u0e22\u0e01\u0e40\u0e2e\u0e07"},"content":{"rendered":"<div class=\"vce-row-container\" data-vce-boxed-width=\"true\"><div class=\"vce-row vce-row--col-gap-30 vce-row-equal-height vce-row-content--top\" id=\"el-e6e42623\" data-vce-do-apply=\"all el-e6e42623\"><div class=\"vce-row-content\" data-vce-element-content=\"true\"><div class=\"vce-col vce-col--md-auto vce-col--xs-1 vce-col--xs-last vce-col--xs-first vce-col--sm-last vce-col--sm-first vce-col--md-last vce-col--lg-last vce-col--xl-last vce-col--md-first vce-col--lg-first vce-col--xl-first\" id=\"el-b149669e\"><div class=\"vce-col-inner\" data-vce-do-apply=\"border margin background  el-b149669e\"><div class=\"vce-col-content\" data-vce-element-content=\"true\" data-vce-do-apply=\"padding el-b149669e\"><div class=\"vce-text-block\"><div class=\"vce-text-block-wrapper vce\" id=\"el-f099da74\" data-vce-do-apply=\"all el-f099da74\"><p>2 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2569 \u0e17\u0e35\u0e48\u0e17\u0e33\u0e40\u0e19\u0e35\u0e22\u0e1a\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25 \u0e1e\u0e25.\u0e15.\u0e17.\u0e23\u0e38\u0e17\u0e18\u0e1e\u0e25 \u0e40\u0e19\u0e32\u0e27\u0e23\u0e31\u0e15\u0e19\u0e4c \u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e22\u0e38\u0e15\u0e34\u0e18\u0e23\u0e23\u0e21 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e16\u0e36\u0e07\u0e01\u0e23\u0e13\u0e35\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e32\u0e18\u0e34\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e32\u0e1a\u0e1b\u0e23\u0e32\u0e21\u0e01\u0e32\u0e23\u0e17\u0e38\u0e08\u0e23\u0e34\u0e15\u0e1b\u0e23\u0e30\u0e1e\u0e24\u0e15\u0e34\u0e21\u0e34\u0e0a\u0e2d\u0e1a (\u0e01\u0e21\u0e18.\u0e1b.\u0e1b.\u0e0a.) \u0e2a\u0e20\u0e32\u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e23\u0e32\u0e29\u0e0e\u0e23 \u0e23\u0e30\u0e1a\u0e38\u0e16\u0e36\u0e07\u0e01\u0e23\u0e13\u0e35\u0e17\u0e35\u0e48\u0e01\u0e2d\u0e07\u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e1b\u0e23\u0e32\u0e1a\u0e1b\u0e23\u0e32\u0e21\u0e01\u0e32\u0e23\u0e17\u0e38\u0e08\u0e23\u0e34\u0e15\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e1e\u0e24\u0e15\u0e34\u0e21\u0e34\u0e0a\u0e2d\u0e1a (\u0e1a\u0e01.\u0e1b\u0e1b\u0e1b.) \u0e40\u0e02\u0e49\u0e32\u0e08\u0e31\u0e1a\u0e01\u0e38\u0e21 \u0e19\u0e32\u0e22\u0e1b\u0e23\u0e30\u0e27\u0e34\u0e17\u0e22\u0e4c \u0e08\u0e32\u0e23\u0e38\u0e23\u0e31\u0e0a\u0e01\u0e38\u0e25 \u0e2b\u0e23\u0e37\u0e2d \u201c\u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e0d\u0e48\u0e40\u0e2e\u0e07\u201d \u0e2d\u0e14\u0e35\u0e15\u0e1c\u0e39\u0e49\u0e2a\u0e21\u0e31\u0e04\u0e23 \u0e2a\u0e2a.\u0e1e\u0e23\u0e23\u0e04\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e44\u0e17\u0e22 \u0e2b\u0e25\u0e31\u0e07\u0e40\u0e23\u0e35\u0e22\u0e01\u0e23\u0e31\u0e1a\u0e40\u0e07\u0e34\u0e19\u0e42\u0e14\u0e22\u0e2d\u0e49\u0e32\u0e07\u0e27\u0e48\u0e32\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e1a\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19\u0e44\u0e14\u0e49 \u0e0b\u0e36\u0e48\u0e07\u0e01\u0e32\u0e23\u0e08\u0e31\u0e1a\u0e01\u0e38\u0e21\u0e43\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e42\u0e22\u0e07\u0e44\u0e1b\u0e16\u0e36\u0e07\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e01\u0e23\u0e21\u0e2a\u0e2d\u0e1a\u0e2a\u0e27\u0e19\u0e04\u0e14\u0e35\u0e1e\u0e34\u0e40\u0e28\u0e29 (\u0e14\u0e35\u0e40\u0e2d\u0e2a\u0e44\u0e2d) \u0e27\u0e48\u0e32 \u0e43\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e14\u0e35\u0e40\u0e2d\u0e2a\u0e44\u0e2d \u0e15\u0e32\u0e21\u0e02\u0e48\u0e32\u0e27\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e40\u0e1a\u0e37\u0e49\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e21\u0e35\u0e2a\u0e2d\u0e07\u0e19\u0e32\u0e22 \u0e0b\u0e36\u0e48\u0e07\u0e43\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e19\u0e35\u0e49\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e15\u0e33\u0e23\u0e27\u0e08\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34\u0e44\u0e14\u0e49\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e04\u0e14\u0e35\u0e43\u0e19\u0e20\u0e32\u0e1e\u0e23\u0e27\u0e21\u0e44\u0e1b\u0e41\u0e25\u0e49\u0e27 \u0e2a\u0e48\u0e27\u0e19\u0e14\u0e35\u0e40\u0e2d\u0e2a\u0e44\u0e2d\u0e19\u0e31\u0e49\u0e19\u0e17\u0e32\u0e07\u0e2d\u0e18\u0e34\u0e1a\u0e14\u0e35 \u0e08\u0e30\u0e15\u0e31\u0e49\u0e07\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e02\u0e49\u0e2d\u0e40\u0e17\u0e47\u0e08\u0e08\u0e23\u0e34\u0e07 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e27\u0e34\u0e19\u0e31\u0e22\u0e23\u0e49\u0e32\u0e22\u0e41\u0e23\u0e07<\/p>\n<p>\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e16\u0e32\u0e21\u0e27\u0e48\u0e32 \u0e08\u0e30\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e40\u0e2a\u0e23\u0e47\u0e08\u0e20\u0e32\u0e22\u0e43\u0e19\u0e01\u0e35\u0e48\u0e27\u0e31\u0e19 \u0e1e\u0e25.\u0e15.\u0e17.\u0e23\u0e38\u0e17\u0e18\u0e1e\u0e25 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32\u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e40\u0e1a\u0e37\u0e49\u0e2d\u0e07\u0e15\u0e49\u0e19 \u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e33\u0e19\u0e32\u0e08\u0e02\u0e2d\u0e07\u0e2d\u0e18\u0e34\u0e1a\u0e14\u0e35\u0e14\u0e35\u0e40\u0e2d\u0e2a\u0e44\u0e2d \u0e0b\u0e36\u0e48\u0e07\u0e17\u0e48\u0e32\u0e19\u0e01\u0e47\u0e0a\u0e35\u0e49\u0e41\u0e08\u0e07<\/p>\n<p>\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e16\u0e32\u0e21\u0e27\u0e48\u0e32 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e1a\u0e02\u0e2d\u0e07\u0e14\u0e35\u0e40\u0e2d\u0e2a\u0e44\u0e2d \u0e08\u0e30\u0e02\u0e22\u0e32\u0e22\u0e1c\u0e25\u0e44\u0e1b\u0e16\u0e36\u0e07\u0e04\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e2d\u0e1a\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e41\u0e04\u0e48 2 \u0e04\u0e19\u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e1e\u0e32\u0e14\u0e1e\u0e34\u0e07 \u0e1e\u0e25.\u0e15.\u0e17.\u0e23\u0e38\u0e17\u0e18\u0e1e\u0e25 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32 \u0e43\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e38\u0e08\u0e23\u0e34\u0e15\u0e2a\u0e2d\u0e1a\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e14\u0e35\u0e40\u0e2d\u0e2a\u0e44\u0e2d\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e1a\u0e2a\u0e27\u0e19 \u0e41\u0e15\u0e48\u0e04\u0e14\u0e35\u0e2b\u0e25\u0e31\u0e01 \u0e43\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e02\u0e2d\u0e07\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e32\u0e1a\u0e1b\u0e23\u0e32\u0e21\u0e01\u0e32\u0e23\u0e17\u0e38\u0e08\u0e23\u0e34\u0e15\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e15\u0e49\u0e19 \u0e01\u0e47\u0e44\u0e14\u0e49\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e44\u0e1b\u0e41\u0e25\u0e49\u0e27 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e27\u0e19\u0e02\u0e2d\u0e07\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e15\u0e33\u0e23\u0e27\u0e08\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 \u0e01\u0e47\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e04\u0e14\u0e35\u0e43\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e19\u0e35\u0e49\u0e44\u0e1b\u0e41\u0e25\u0e49\u0e27<\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>2 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2569 \u0e17\u0e35\u0e48\u0e17\u0e33\u0e40\u0e19\u0e35\u0e22\u0e1a\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25 \u0e1e\u0e25.\u0e15.\u0e17.\u0e23\u0e38\u0e17\u0e18\u0e1e\u0e25 \u0e40\u0e19\u0e32\u0e27\u0e23\u0e31\u0e15\u0e19\u0e4c [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":38714,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[241,7,9],"tags":[5932],"class_list":["post-38695","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking","category-crime","category-national-news","tag-5932"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u0e23\u0e38\u0e17\u0e18\u0e1e\u0e25 \u0e40\u0e1c\u0e22\u0e14\u0e35\u0e40\u0e2d\u0e2a\u0e44\u0e2d \u0e15\u0e31\u0e49\u0e07 \u0e04\u0e01\u0e01.\u0e2a\u0e2d\u0e1a\u0e27\u0e34\u0e19\u0e31\u0e22\u0e23\u0e49\u0e32\u0e22\u0e41\u0e23\u0e07 \u0e08\u0e19\u0e17.\u0e40\u0e2d\u0e35\u0e48\u0e22\u0e27 \u0e2a\u0e2d\u0e1a\u0e17\u0e38\u0e08\u0e23\u0e34\u0e15\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e01\u0e4a\u0e27\u0e19\u0e19\u0e32\u0e22\u0e01\u0e40\u0e2e\u0e07 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.naewna.com\/n\/crime\/38695\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e23\u0e38\u0e17\u0e18\u0e1e\u0e25 \u0e40\u0e1c\u0e22\u0e14\u0e35\u0e40\u0e2d\u0e2a\u0e44\u0e2d \u0e15\u0e31\u0e49\u0e07 \u0e04\u0e01\u0e01.\u0e2a\u0e2d\u0e1a\u0e27\u0e34\u0e19\u0e31\u0e22\u0e23\u0e49\u0e32\u0e22\u0e41\u0e23\u0e07 \u0e08\u0e19\u0e17.\u0e40\u0e2d\u0e35\u0e48\u0e22\u0e27 \u0e2a\u0e2d\u0e1a\u0e17\u0e38\u0e08\u0e23\u0e34\u0e15\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e01\u0e4a\u0e27\u0e19\u0e19\u0e32\u0e22\u0e01\u0e40\u0e2e\u0e07\" \/>\n<meta property=\"og:description\" content=\"2 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2569 \u0e17\u0e35\u0e48\u0e17\u0e33\u0e40\u0e19\u0e35\u0e22\u0e1a\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25 \u0e1e\u0e25.\u0e15.\u0e17.\u0e23\u0e38\u0e17\u0e18\u0e1e\u0e25 \u0e40\u0e19\u0e32\u0e27\u0e23\u0e31\u0e15\u0e19\u0e4c [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.naewna.com\/n\/crime\/38695\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NaewnaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2026-09-02T05:36:13+00:00\" \/>\n<meta name=\"author\" content=\"monthontus\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@naewna_news\" \/>\n<meta name=\"twitter:site\" content=\"@naewna_news\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"monthontus\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/crime\\\/38695\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/crime\\\/38695\\\/\"},\"author\":{\"name\":\"monthontus\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#\\\/schema\\\/person\\\/c661d95de6b20e592a319a8ef805436a\"},\"headline\":\"\u0e23\u0e38\u0e17\u0e18\u0e1e\u0e25 \u0e40\u0e1c\u0e22\u0e14\u0e35\u0e40\u0e2d\u0e2a\u0e44\u0e2d \u0e15\u0e31\u0e49\u0e07 \u0e04\u0e01\u0e01.\u0e2a\u0e2d\u0e1a\u0e27\u0e34\u0e19\u0e31\u0e22\u0e23\u0e49\u0e32\u0e22\u0e41\u0e23\u0e07 \u0e08\u0e19\u0e17.\u0e40\u0e2d\u0e35\u0e48\u0e22\u0e27 \u0e2a\u0e2d\u0e1a\u0e17\u0e38\u0e08\u0e23\u0e34\u0e15\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e01\u0e4a\u0e27\u0e19\u0e19\u0e32\u0e22\u0e01\u0e40\u0e2e\u0e07\",\"datePublished\":\"2026-09-02T05:36:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/crime\\\/38695\\\/\"},\"wordCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/crime\\\/38695\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/storage-wp.naewna.com\\\/2026\\\/09\\\/1-46.jpg\",\"keywords\":[\"\u0e23\u0e38\u0e17\u0e18\u0e1e\u0e25 \u0e40\u0e19\u0e32\u0e27\u0e23\u0e31\u0e15\u0e19\u0e4c,\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e22\u0e38\u0e15\u0e34\u0e18\u0e23\u0e23\u0e21,\u0e14\u0e35\u0e40\u0e2d\u0e2a\u0e44\u0e2d,\u0e2a\u0e21\u0e0a\u0e32\u0e15\u0e34 \u0e40\u0e15\u0e0a\u0e16\u0e32\u0e27\u0e23\u0e40\u0e08\u0e23\u0e34\u0e0d,\u0e2a\u0e2a.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15,\u0e1e\u0e23\u0e23\u0e04\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\"],\"articleSection\":[\"Breaking News\",\"\u0e2d\u0e32\u0e0a\u0e0d\u0e32\u0e01\u0e23\u0e23\u0e21\",\"\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\"],\"inLanguage\":\"th\",\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/crime\\\/38695\\\/\",\"url\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/crime\\\/38695\\\/\",\"name\":\"\u0e23\u0e38\u0e17\u0e18\u0e1e\u0e25 \u0e40\u0e1c\u0e22\u0e14\u0e35\u0e40\u0e2d\u0e2a\u0e44\u0e2d \u0e15\u0e31\u0e49\u0e07 \u0e04\u0e01\u0e01.\u0e2a\u0e2d\u0e1a\u0e27\u0e34\u0e19\u0e31\u0e22\u0e23\u0e49\u0e32\u0e22\u0e41\u0e23\u0e07 \u0e08\u0e19\u0e17.\u0e40\u0e2d\u0e35\u0e48\u0e22\u0e27 \u0e2a\u0e2d\u0e1a\u0e17\u0e38\u0e08\u0e23\u0e34\u0e15\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e01\u0e4a\u0e27\u0e19\u0e19\u0e32\u0e22\u0e01\u0e40\u0e2e\u0e07 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/crime\\\/38695\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/crime\\\/38695\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/storage-wp.naewna.com\\\/2026\\\/09\\\/1-46.jpg\",\"datePublished\":\"2026-09-02T05:36:13+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#\\\/schema\\\/person\\\/c661d95de6b20e592a319a8ef805436a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/crime\\\/38695\\\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.naewna.com\\\/n\\\/crime\\\/38695\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/crime\\\/38695\\\/#primaryimage\",\"url\":\"https:\\\/\\\/storage-wp.naewna.com\\\/2026\\\/09\\\/1-46.jpg\",\"contentUrl\":\"https:\\\/\\\/storage-wp.naewna.com\\\/2026\\\/09\\\/1-46.jpg\",\"width\":1080,\"height\":607},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/crime\\\/38695\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e23\u0e38\u0e17\u0e18\u0e1e\u0e25 \u0e40\u0e1c\u0e22\u0e14\u0e35\u0e40\u0e2d\u0e2a\u0e44\u0e2d \u0e15\u0e31\u0e49\u0e07 \u0e04\u0e01\u0e01.\u0e2a\u0e2d\u0e1a\u0e27\u0e34\u0e19\u0e31\u0e22\u0e23\u0e49\u0e32\u0e22\u0e41\u0e23\u0e07 \u0e08\u0e19\u0e17.\u0e40\u0e2d\u0e35\u0e48\u0e22\u0e27 \u0e2a\u0e2d\u0e1a\u0e17\u0e38\u0e08\u0e23\u0e34\u0e15\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e01\u0e4a\u0e27\u0e19\u0e19\u0e32\u0e22\u0e01\u0e40\u0e2e\u0e07\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#website\",\"url\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/\",\"name\":\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#\\\/schema\\\/person\\\/c661d95de6b20e592a319a8ef805436a\",\"name\":\"monthontus\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/753bd31ff90c84edaffda4a60b4fe164e7a044d02e4bfe0e761be429dcca30ac?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/753bd31ff90c84edaffda4a60b4fe164e7a044d02e4bfe0e761be429dcca30ac?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/753bd31ff90c84edaffda4a60b4fe164e7a044d02e4bfe0e761be429dcca30ac?s=96&d=mm&r=g\",\"caption\":\"monthontus\"},\"url\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/author\\\/monthontus\\\/\"}]}<\/script>\n<meta property=\"article:section\" content=\"Breaking News\" \/>\n<meta property=\"article:section\" content=\"\u0e2d\u0e32\u0e0a\u0e0d\u0e32\u0e01\u0e23\u0e23\u0e21\" \/>\n<meta property=\"article:section\" content=\"\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u0e23\u0e38\u0e17\u0e18\u0e1e\u0e25 \u0e40\u0e1c\u0e22\u0e14\u0e35\u0e40\u0e2d\u0e2a\u0e44\u0e2d \u0e15\u0e31\u0e49\u0e07 \u0e04\u0e01\u0e01.\u0e2a\u0e2d\u0e1a\u0e27\u0e34\u0e19\u0e31\u0e22\u0e23\u0e49\u0e32\u0e22\u0e41\u0e23\u0e07 \u0e08\u0e19\u0e17.\u0e40\u0e2d\u0e35\u0e48\u0e22\u0e27 \u0e2a\u0e2d\u0e1a\u0e17\u0e38\u0e08\u0e23\u0e34\u0e15\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e01\u0e4a\u0e27\u0e19\u0e19\u0e32\u0e22\u0e01\u0e40\u0e2e\u0e07 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.naewna.com\/n\/crime\/38695\/","og_locale":"th_TH","og_type":"article","og_title":"\u0e23\u0e38\u0e17\u0e18\u0e1e\u0e25 \u0e40\u0e1c\u0e22\u0e14\u0e35\u0e40\u0e2d\u0e2a\u0e44\u0e2d \u0e15\u0e31\u0e49\u0e07 \u0e04\u0e01\u0e01.\u0e2a\u0e2d\u0e1a\u0e27\u0e34\u0e19\u0e31\u0e22\u0e23\u0e49\u0e32\u0e22\u0e41\u0e23\u0e07 \u0e08\u0e19\u0e17.\u0e40\u0e2d\u0e35\u0e48\u0e22\u0e27 \u0e2a\u0e2d\u0e1a\u0e17\u0e38\u0e08\u0e23\u0e34\u0e15\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e01\u0e4a\u0e27\u0e19\u0e19\u0e32\u0e22\u0e01\u0e40\u0e2e\u0e07","og_description":"2 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2569 \u0e17\u0e35\u0e48\u0e17\u0e33\u0e40\u0e19\u0e35\u0e22\u0e1a\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25 \u0e1e\u0e25.\u0e15.\u0e17.\u0e23\u0e38\u0e17\u0e18\u0e1e\u0e25 \u0e40\u0e19\u0e32\u0e27\u0e23\u0e31\u0e15\u0e19\u0e4c [&hellip;]","og_url":"https:\/\/www.naewna.com\/n\/crime\/38695\/","og_site_name":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32","article_publisher":"https:\/\/www.facebook.com\/NaewnaOnline","article_published_time":"2026-09-02T05:36:13+00:00","author":"monthontus","twitter_card":"summary_large_image","twitter_creator":"@naewna_news","twitter_site":"@naewna_news","twitter_misc":{"Written by":"monthontus"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.naewna.com\/n\/crime\/38695\/#article","isPartOf":{"@id":"https:\/\/www.naewna.com\/n\/crime\/38695\/"},"author":{"name":"monthontus","@id":"https:\/\/www.naewna.com\/n\/#\/schema\/person\/c661d95de6b20e592a319a8ef805436a"},"headline":"\u0e23\u0e38\u0e17\u0e18\u0e1e\u0e25 \u0e40\u0e1c\u0e22\u0e14\u0e35\u0e40\u0e2d\u0e2a\u0e44\u0e2d \u0e15\u0e31\u0e49\u0e07 \u0e04\u0e01\u0e01.\u0e2a\u0e2d\u0e1a\u0e27\u0e34\u0e19\u0e31\u0e22\u0e23\u0e49\u0e32\u0e22\u0e41\u0e23\u0e07 \u0e08\u0e19\u0e17.\u0e40\u0e2d\u0e35\u0e48\u0e22\u0e27 \u0e2a\u0e2d\u0e1a\u0e17\u0e38\u0e08\u0e23\u0e34\u0e15\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e01\u0e4a\u0e27\u0e19\u0e19\u0e32\u0e22\u0e01\u0e40\u0e2e\u0e07","datePublished":"2026-09-02T05:36:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.naewna.com\/n\/crime\/38695\/"},"wordCount":0,"image":{"@id":"https:\/\/www.naewna.com\/n\/crime\/38695\/#primaryimage"},"thumbnailUrl":"https:\/\/storage-wp.naewna.com\/2026\/09\/1-46.jpg","keywords":["\u0e23\u0e38\u0e17\u0e18\u0e1e\u0e25 \u0e40\u0e19\u0e32\u0e27\u0e23\u0e31\u0e15\u0e19\u0e4c,\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e22\u0e38\u0e15\u0e34\u0e18\u0e23\u0e23\u0e21,\u0e14\u0e35\u0e40\u0e2d\u0e2a\u0e44\u0e2d,\u0e2a\u0e21\u0e0a\u0e32\u0e15\u0e34 \u0e40\u0e15\u0e0a\u0e16\u0e32\u0e27\u0e23\u0e40\u0e08\u0e23\u0e34\u0e0d,\u0e2a\u0e2a.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15,\u0e1e\u0e23\u0e23\u0e04\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19"],"articleSection":["Breaking News","\u0e2d\u0e32\u0e0a\u0e0d\u0e32\u0e01\u0e23\u0e23\u0e21","\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28"],"inLanguage":"th","copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/www.naewna.com\/n\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.naewna.com\/n\/crime\/38695\/","url":"https:\/\/www.naewna.com\/n\/crime\/38695\/","name":"\u0e23\u0e38\u0e17\u0e18\u0e1e\u0e25 \u0e40\u0e1c\u0e22\u0e14\u0e35\u0e40\u0e2d\u0e2a\u0e44\u0e2d \u0e15\u0e31\u0e49\u0e07 \u0e04\u0e01\u0e01.\u0e2a\u0e2d\u0e1a\u0e27\u0e34\u0e19\u0e31\u0e22\u0e23\u0e49\u0e32\u0e22\u0e41\u0e23\u0e07 \u0e08\u0e19\u0e17.\u0e40\u0e2d\u0e35\u0e48\u0e22\u0e27 \u0e2a\u0e2d\u0e1a\u0e17\u0e38\u0e08\u0e23\u0e34\u0e15\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e01\u0e4a\u0e27\u0e19\u0e19\u0e32\u0e22\u0e01\u0e40\u0e2e\u0e07 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32","isPartOf":{"@id":"https:\/\/www.naewna.com\/n\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.naewna.com\/n\/crime\/38695\/#primaryimage"},"image":{"@id":"https:\/\/www.naewna.com\/n\/crime\/38695\/#primaryimage"},"thumbnailUrl":"https:\/\/storage-wp.naewna.com\/2026\/09\/1-46.jpg","datePublished":"2026-09-02T05:36:13+00:00","author":{"@id":"https:\/\/www.naewna.com\/n\/#\/schema\/person\/c661d95de6b20e592a319a8ef805436a"},"breadcrumb":{"@id":"https:\/\/www.naewna.com\/n\/crime\/38695\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.naewna.com\/n\/crime\/38695\/"]}]},{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.naewna.com\/n\/crime\/38695\/#primaryimage","url":"https:\/\/storage-wp.naewna.com\/2026\/09\/1-46.jpg","contentUrl":"https:\/\/storage-wp.naewna.com\/2026\/09\/1-46.jpg","width":1080,"height":607},{"@type":"BreadcrumbList","@id":"https:\/\/www.naewna.com\/n\/crime\/38695\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.naewna.com\/n\/"},{"@type":"ListItem","position":2,"name":"\u0e23\u0e38\u0e17\u0e18\u0e1e\u0e25 \u0e40\u0e1c\u0e22\u0e14\u0e35\u0e40\u0e2d\u0e2a\u0e44\u0e2d \u0e15\u0e31\u0e49\u0e07 \u0e04\u0e01\u0e01.\u0e2a\u0e2d\u0e1a\u0e27\u0e34\u0e19\u0e31\u0e22\u0e23\u0e49\u0e32\u0e22\u0e41\u0e23\u0e07 \u0e08\u0e19\u0e17.\u0e40\u0e2d\u0e35\u0e48\u0e22\u0e27 \u0e2a\u0e2d\u0e1a\u0e17\u0e38\u0e08\u0e23\u0e34\u0e15\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e01\u0e4a\u0e27\u0e19\u0e19\u0e32\u0e22\u0e01\u0e40\u0e2e\u0e07"}]},{"@type":"WebSite","@id":"https:\/\/www.naewna.com\/n\/#website","url":"https:\/\/www.naewna.com\/n\/","name":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.naewna.com\/n\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"},{"@type":"Person","@id":"https:\/\/www.naewna.com\/n\/#\/schema\/person\/c661d95de6b20e592a319a8ef805436a","name":"monthontus","image":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/secure.gravatar.com\/avatar\/753bd31ff90c84edaffda4a60b4fe164e7a044d02e4bfe0e761be429dcca30ac?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/753bd31ff90c84edaffda4a60b4fe164e7a044d02e4bfe0e761be429dcca30ac?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/753bd31ff90c84edaffda4a60b4fe164e7a044d02e4bfe0e761be429dcca30ac?s=96&d=mm&r=g","caption":"monthontus"},"url":"https:\/\/www.naewna.com\/n\/author\/monthontus\/"}]}},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/storage-wp.naewna.com\/2026\/09\/1-46.jpg","_links":{"self":[{"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/posts\/38695","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/comments?post=38695"}],"version-history":[{"count":2,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/posts\/38695\/revisions"}],"predecessor-version":[{"id":38720,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/posts\/38695\/revisions\/38720"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/media\/38714"}],"wp:attachment":[{"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/media?parent=38695"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/categories?post=38695"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/tags?post=38695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}