{"id":38713,"date":"2026-09-02T12:40:43","date_gmt":"2026-09-02T05:40:43","guid":{"rendered":"https:\/\/www.naewna.com\/n\/?p=38713"},"modified":"2026-09-02T12:40:43","modified_gmt":"2026-09-02T05:40:43","slug":"tods-%e0%b9%80%e0%b8%8a%e0%b8%b4%e0%b8%94%e0%b8%8a%e0%b8%b9%e0%b8%84%e0%b8%b8%e0%b8%93%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%9d%e0%b8%b5","status":"publish","type":"post","link":"https:\/\/www.naewna.com\/n\/women\/fashion-news\/38713\/","title":{"rendered":"Tod\u2019s \u0e40\u0e0a\u0e34\u0e14\u0e0a\u0e39\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e1d\u0e35\u0e21\u0e37\u0e2d Made in Italy  \u0e1c\u0e48\u0e32\u0e19\u0e42\u0e1b\u0e23\u0e40\u0e08\u0e01\u0e15\u0e4c The Art of Craftsmanship"},"content":{"rendered":"<div class=\"vce-row-container\" data-vce-boxed-width=\"true\"><div class=\"vce-row vce-row--col-gap-30 vce-row-equal-height vce-row-content--top\" id=\"el-51d59845\" data-vce-do-apply=\"all el-51d59845\"><div class=\"vce-row-content\" data-vce-element-content=\"true\"><div class=\"vce-col vce-col--md-auto vce-col--xs-1 vce-col--xs-last vce-col--xs-first vce-col--sm-last vce-col--sm-first vce-col--md-last vce-col--lg-last vce-col--xl-last vce-col--md-first vce-col--lg-first vce-col--xl-first\" id=\"el-0c86ddff\"><div class=\"vce-col-inner\" data-vce-do-apply=\"border margin background  el-0c86ddff\"><div class=\"vce-col-content\" data-vce-element-content=\"true\" data-vce-do-apply=\"padding el-0c86ddff\"><div class=\"vce-text-block\"><div class=\"vce-text-block-wrapper vce\" id=\"el-d362ceca\" data-vce-do-apply=\"all el-d362ceca\"><p><strong>\u0e42\u0e1b\u0e23\u0e40\u0e08\u0e01\u0e15\u0e4c\u0e19\u0e35\u0e49\u0e1a\u0e2d\u0e01\u0e40\u0e25\u0e48\u0e32\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e27\u0e21\u0e23\u0e14\u0e01\u0e02\u0e2d\u0e07\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e1c\u0e48\u0e32\u0e19\u0e20\u0e32\u0e1e\u0e23\u0e48\u0e27\u0e21\u0e2a\u0e21\u0e31\u0e22 \u0e2a\u0e30\u0e17\u0e49\u0e2d\u0e19\u0e16\u0e36\u0e07\u0e04\u0e27\u0e32\u0e21\u0e21\u0e38\u0e48\u0e07\u0e21\u0e31\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e25\u0e36\u0e01\u0e0b\u0e36\u0e49\u0e07\u0e15\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e25\u0e34\u0e28\u0e41\u0e2b\u0e48\u0e07\u0e01\u0e32\u0e23\u0e23\u0e31\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e23\u0e30\u0e13\u0e35\u0e15\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e2d\u0e21\u0e23\u0e27\u0e21\u0e08\u0e32\u0e01\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e34\u0e16\u0e35\u0e1e\u0e34\u0e16\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e20\u0e32\u0e04\u0e20\u0e39\u0e21\u0e34\u0e43\u0e08 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e21\u0e19\u0e38\u0e29\u0e22\u0e4c\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e31\u0e27\u0e43\u0e08\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e32\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e22\u0e49\u0e33\u0e40\u0e15\u0e37\u0e2d\u0e19\u0e27\u0e48\u0e32\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e34\u0e49\u0e19\u0e16\u0e37\u0e2d\u0e01\u0e33\u0e40\u0e19\u0e34\u0e14\u0e08\u0e32\u0e01\u0e2d\u0e07\u0e04\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49 \u0e04\u0e27\u0e32\u0e21\u0e0a\u0e33\u0e19\u0e32\u0e0d \u0e41\u0e25\u0e30\u0e2a\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e02\u0e2d\u0e07\u0e0a\u0e48\u0e32\u0e07\u0e1d\u0e35\u0e21\u0e37\u0e2d\u0e1c\u0e39\u0e49\u0e23\u0e31\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e1c\u0e25\u0e07\u0e32\u0e19 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e04\u0e38\u0e13\u0e04\u0e48\u0e32\u0e17\u0e35\u0e48\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e43\u0e14\u0e01\u0e47\u0e44\u0e21\u0e48\u0e2d\u0e32\u0e08\u0e17\u0e14\u0e41\u0e17\u0e19\u0e44\u0e14\u0e49<\/strong><\/p>\n<p>\u0e21\u0e19\u0e38\u0e29\u0e22\u0e4c\u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e14\u0e31\u0e48\u0e07\u0e2a\u0e31\u0e0d\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e2a\u0e37\u0e48\u0e2d\u0e16\u0e36\u0e07\u0e17\u0e31\u0e01\u0e29\u0e30\u0e41\u0e2b\u0e48\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d\u0e0b\u0e36\u0e48\u0e07\u0e19\u0e34\u0e22\u0e32\u0e21\u0e2d\u0e31\u0e15\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e23\u0e34\u0e22\u0e32\u0e17\u0e48\u0e32\u0e17\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e20\u0e32\u0e1e \u0e25\u0e49\u0e27\u0e19\u0e2a\u0e30\u0e17\u0e49\u0e2d\u0e19\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e47\u0e19\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e23\u0e31\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e14\u0e49\u0e27\u0e22\u0e21\u0e37\u0e2d\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e1e\u0e34\u0e16\u0e35\u0e1e\u0e34\u0e16\u0e31\u0e19 \u0e2d\u0e31\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e01\u0e48\u0e19\u0e41\u0e17\u0e49\u0e41\u0e2b\u0e48\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e25\u0e34\u0e28\u0e02\u0e2d\u0e07 Tod\u2019s<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-38715\" src=\"https:\/\/storage-wp.naewna.com\/2026\/09\/Tods-PF26-27_Digital_Website_1080x1080px2.jpg\" alt=\"\" width=\"1920\" height=\"1920\" srcset=\"https:\/\/storage-wp.naewna.com\/2026\/09\/Tods-PF26-27_Digital_Website_1080x1080px2.jpg 1920w, https:\/\/storage-wp.naewna.com\/2026\/09\/Tods-PF26-27_Digital_Website_1080x1080px2-150x150.jpg 150w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e44\u0e2d\u0e04\u0e2d\u0e19\u0e02\u0e2d\u0e07\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c<\/strong> <strong>\u0e04\u0e37\u0e2d\u0e2b\u0e31\u0e27\u0e43\u0e08\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e17\u0e35\u0e48\u0e2a\u0e30\u0e17\u0e49\u0e2d\u0e19\u0e04\u0e27\u0e32\u0e21\u0e42\u0e14\u0e14\u0e40\u0e14\u0e48\u0e19<\/strong><\/p>\n<p>\u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 Gommino \u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e44\u0e25\u0e1f\u0e4c\u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e41\u0e1a\u0e1a\u0e2d\u0e34\u0e15\u0e32\u0e25\u0e35\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e07\u0e48\u0e32\u0e07\u0e32\u0e21\u0e40\u0e2b\u0e19\u0e37\u0e2d\u0e01\u0e32\u0e25\u0e40\u0e27\u0e25\u0e32 \u0e2d\u0e35\u0e01\u0e17\u0e31\u0e49\u0e07\u0e22\u0e31\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e31\u0e0d\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14\u0e02\u0e2d\u0e07\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19 Made in Italy \u0e14\u0e49\u0e27\u0e22\u0e40\u0e2d\u0e01\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e07\u0e32\u0e19\u0e40\u0e22\u0e47\u0e1a\u0e14\u0e49\u0e27\u0e22\u0e21\u0e37\u0e2d\u0e2d\u0e31\u0e19\u0e1b\u0e23\u0e30\u0e13\u0e35\u0e15 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2a\u0e30\u0e17\u0e49\u0e2d\u0e19\u0e16\u0e36\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d\u0e14\u0e49\u0e32\u0e19\u0e07\u0e32\u0e19\u0e1d\u0e35\u0e21\u0e37\u0e2d\u0e2d\u0e31\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e25\u0e34\u0e28\u0e02\u0e2d\u0e07 Tod\u2019s<\/p>\n<p>Red Dot \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32\u0e2a\u0e19\u0e35\u0e01\u0e40\u0e01\u0e2d\u0e23\u0e4c\u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e04\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e1c\u0e2a\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e25\u0e34\u0e28\u0e02\u0e2d\u0e07\u0e07\u0e32\u0e19\u0e1d\u0e35\u0e21\u0e37\u0e2d\u0e41\u0e1a\u0e1a\u0e2d\u0e34\u0e15\u0e32\u0e25\u0e35\u0e40\u0e02\u0e49\u0e32\u0e01\u0e31\u0e1a\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e2b\u0e21\u0e48 \u0e42\u0e14\u0e14\u0e40\u0e14\u0e48\u0e19\u0e14\u0e49\u0e27\u0e22\u0e1b\u0e38\u0e48\u0e21\u0e2a\u0e35\u0e41\u0e14\u0e07\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e2a\u0e49\u0e19\u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e2d\u0e31\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e31\u0e0d\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e2a\u0e37\u0e48\u0e2d\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e01\u0e31\u0e1a\u0e42\u0e25\u0e01\u0e02\u0e2d\u0e07 Tod\u2019s \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32\u0e04\u0e39\u0e48\u0e19\u0e35\u0e49\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e21\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1c\u0e39\u0e49\u0e2b\u0e0d\u0e34\u0e07\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e0a\u0e32\u0e22\u0e22\u0e38\u0e04\u0e43\u0e2b\u0e21\u0e48 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e40\u0e27\u0e25\u0e32\u0e17\u0e33\u0e07\u0e32\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e21\u0e1e\u0e31\u0e01\u0e1c\u0e48\u0e2d\u0e19 \u0e42\u0e14\u0e22\u0e23\u0e31\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e02\u0e36\u0e49\u0e19\u0e08\u0e32\u0e01\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e0a\u0e31\u0e49\u0e19\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21 \u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e0a\u0e37\u0e2d\u0e01\u0e1c\u0e39\u0e01\u0e41\u0e1a\u0e1a\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e49\u0e19\u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32\u0e17\u0e35\u0e48\u0e21\u0e35\u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01\u0e40\u0e1a\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e34\u0e40\u0e28\u0e29<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-38716\" src=\"https:\/\/storage-wp.naewna.com\/2026\/09\/Tods-PF26-27_Digital_Website_1080x1080px5.jpg\" alt=\"\" width=\"1920\" height=\"1920\" srcset=\"https:\/\/storage-wp.naewna.com\/2026\/09\/Tods-PF26-27_Digital_Website_1080x1080px5.jpg 1920w, https:\/\/storage-wp.naewna.com\/2026\/09\/Tods-PF26-27_Digital_Website_1080x1080px5-150x150.jpg 150w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>\u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 T Signature \u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e31\u0e0d\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e07\u0e48\u0e32\u0e07\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e2a\u0e21\u0e31\u0e22 \u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e2d\u0e40\u0e17\u0e21\u0e0a\u0e34\u0e49\u0e19\u0e42\u0e1b\u0e23\u0e14\u0e02\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e04\u0e19\u0e14\u0e31\u0e07\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e42\u0e25\u0e01 \u0e41\u0e25\u0e30 Tod\u2019s \u0e44\u0e14\u0e49\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e23\u0e38\u0e48\u0e19\u0e44\u0e2d\u0e04\u0e2d\u0e19\u0e34\u0e01\u0e19\u0e35\u0e49\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19\u0e1c\u0e48\u0e32\u0e19\u0e42\u0e1b\u0e23\u0e40\u0e08\u0e01\u0e15\u0e4c My Signature \u0e42\u0e14\u0e22\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e31\u0e27\u0e2d\u0e31\u0e01\u0e29\u0e23\u0e21\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e43\u0e19\u0e41\u0e1a\u0e1a\u0e02\u0e2d\u0e07\u0e15\u0e19\u0e40\u0e2d\u0e07\u0e44\u0e14\u0e49 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e31\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e0a\u0e34\u0e49\u0e19\u0e40\u0e14\u0e48\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e30\u0e17\u0e49\u0e2d\u0e19\u0e15\u0e31\u0e27\u0e15\u0e19\u0e41\u0e25\u0e30\u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e0a\u0e31\u0e14\u0e40\u0e08\u0e19<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-38717\" src=\"https:\/\/storage-wp.naewna.com\/2026\/09\/Tods-PF26-27_Digital_Website_1080x1080px11.jpg\" alt=\"\" width=\"1920\" height=\"1920\" srcset=\"https:\/\/storage-wp.naewna.com\/2026\/09\/Tods-PF26-27_Digital_Website_1080x1080px11.jpg 1920w, https:\/\/storage-wp.naewna.com\/2026\/09\/Tods-PF26-27_Digital_Website_1080x1080px11-150x150.jpg 150w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-38718\" src=\"https:\/\/storage-wp.naewna.com\/2026\/09\/Tods-PF26-27_Digital_Website_1080x1080px13.jpg\" alt=\"\" width=\"1920\" height=\"1920\" srcset=\"https:\/\/storage-wp.naewna.com\/2026\/09\/Tods-PF26-27_Digital_Website_1080x1080px13.jpg 1920w, https:\/\/storage-wp.naewna.com\/2026\/09\/Tods-PF26-27_Digital_Website_1080x1080px13-150x150.jpg 150w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Metal Dots \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e41\u0e23\u0e07\u0e1a\u0e31\u0e19\u0e14\u0e32\u0e25\u0e43\u0e08\u0e08\u0e32\u0e01\u0e14\u0e35\u0e40\u0e17\u0e25\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e2d\u0e01\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e02\u0e2d\u0e07\u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 Gommino \u0e23\u0e38\u0e48\u0e19\u0e44\u0e2d\u0e04\u0e2d\u0e19\u0e34\u0e01 \u0e42\u0e14\u0e22\u0e19\u0e33\u0e21\u0e32\u0e23\u0e31\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e43\u0e2b\u0e21\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e1b\u0e38\u0e48\u0e21\u0e42\u0e25\u0e2b\u0e30\u0e2d\u0e31\u0e19\u0e1b\u0e23\u0e30\u0e13\u0e35\u0e15 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e42\u0e14\u0e14\u0e40\u0e14\u0e48\u0e19\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e04\u0e2d\u0e25\u0e40\u0e25\u0e01\u0e0a\u0e31\u0e19\u0e41\u0e2d\u0e04\u0e40\u0e0b\u0e2a\u0e40\u0e0b\u0e2d\u0e23\u0e35\u0e48 \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32\u0e42\u0e25\u0e1f\u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e44\u0e1b\u0e08\u0e19\u0e16\u0e36\u0e07\u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e16\u0e37\u0e2d\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e2a\u0e44\u0e15\u0e25\u0e4c<\/p>\n<p>&nbsp;<\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u0e42\u0e1b\u0e23\u0e40\u0e08\u0e01\u0e15\u0e4c\u0e19\u0e35\u0e49\u0e1a\u0e2d\u0e01\u0e40\u0e25\u0e48\u0e32\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e27\u0e21\u0e23\u0e14\u0e01\u0e02\u0e2d\u0e07\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e1c\u0e48\u0e32\u0e19\u0e20\u0e32\u0e1e\u0e23\u0e48\u0e27\u0e21\u0e2a\u0e21\u0e31\u0e22 [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":38734,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[244],"tags":[5976],"class_list":["post-38713","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fashion-news","tag-tods"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Tod\u2019s \u0e40\u0e0a\u0e34\u0e14\u0e0a\u0e39\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e1d\u0e35\u0e21\u0e37\u0e2d Made in Italy \u0e1c\u0e48\u0e32\u0e19\u0e42\u0e1b\u0e23\u0e40\u0e08\u0e01\u0e15\u0e4c The Art of Craftsmanship - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.naewna.com\/n\/women\/fashion-news\/38713\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tod\u2019s \u0e40\u0e0a\u0e34\u0e14\u0e0a\u0e39\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e1d\u0e35\u0e21\u0e37\u0e2d Made in Italy \u0e1c\u0e48\u0e32\u0e19\u0e42\u0e1b\u0e23\u0e40\u0e08\u0e01\u0e15\u0e4c The Art of Craftsmanship\" \/>\n<meta property=\"og:description\" content=\"\u0e42\u0e1b\u0e23\u0e40\u0e08\u0e01\u0e15\u0e4c\u0e19\u0e35\u0e49\u0e1a\u0e2d\u0e01\u0e40\u0e25\u0e48\u0e32\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e27\u0e21\u0e23\u0e14\u0e01\u0e02\u0e2d\u0e07\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e1c\u0e48\u0e32\u0e19\u0e20\u0e32\u0e1e\u0e23\u0e48\u0e27\u0e21\u0e2a\u0e21\u0e31\u0e22 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.naewna.com\/n\/women\/fashion-news\/38713\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NaewnaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2026-09-02T05:40:43+00:00\" \/>\n<meta name=\"author\" content=\"\u0e01\u0e4a\u0e2d\u0e1a \u0e20\u0e32\u0e1e\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e31\u0e07\u0e04\u0e21\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@naewna_news\" \/>\n<meta name=\"twitter:site\" content=\"@naewna_news\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u0e01\u0e4a\u0e2d\u0e1a \u0e20\u0e32\u0e1e\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e31\u0e07\u0e04\u0e21\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/women\\\/fashion-news\\\/38713\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/women\\\/fashion-news\\\/38713\\\/\"},\"author\":{\"name\":\"\u0e01\u0e4a\u0e2d\u0e1a \u0e20\u0e32\u0e1e\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e31\u0e07\u0e04\u0e21\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#\\\/schema\\\/person\\\/3ea5b7919fcf4258984bc90d5785176d\"},\"headline\":\"Tod\u2019s \u0e40\u0e0a\u0e34\u0e14\u0e0a\u0e39\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e1d\u0e35\u0e21\u0e37\u0e2d Made in Italy \u0e1c\u0e48\u0e32\u0e19\u0e42\u0e1b\u0e23\u0e40\u0e08\u0e01\u0e15\u0e4c The Art of Craftsmanship\",\"datePublished\":\"2026-09-02T05:40:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/women\\\/fashion-news\\\/38713\\\/\"},\"wordCount\":34,\"image\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/women\\\/fashion-news\\\/38713\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/storage-wp.naewna.com\\\/2026\\\/09\\\/1\u0e1b\u0e01\u0e40\u0e27\u0e47\u0e1a-\u0e2a\u0e2d\u0e07\u0e41\u0e16\u0e27-5.jpg\",\"keywords\":[\"Tod\u2019s\"],\"articleSection\":[\"Fashion\"],\"inLanguage\":\"th\",\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/women\\\/fashion-news\\\/38713\\\/\",\"url\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/women\\\/fashion-news\\\/38713\\\/\",\"name\":\"Tod\u2019s \u0e40\u0e0a\u0e34\u0e14\u0e0a\u0e39\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e1d\u0e35\u0e21\u0e37\u0e2d Made in Italy \u0e1c\u0e48\u0e32\u0e19\u0e42\u0e1b\u0e23\u0e40\u0e08\u0e01\u0e15\u0e4c The Art of Craftsmanship - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/women\\\/fashion-news\\\/38713\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/women\\\/fashion-news\\\/38713\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/storage-wp.naewna.com\\\/2026\\\/09\\\/1\u0e1b\u0e01\u0e40\u0e27\u0e47\u0e1a-\u0e2a\u0e2d\u0e07\u0e41\u0e16\u0e27-5.jpg\",\"datePublished\":\"2026-09-02T05:40:43+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#\\\/schema\\\/person\\\/3ea5b7919fcf4258984bc90d5785176d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/women\\\/fashion-news\\\/38713\\\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.naewna.com\\\/n\\\/women\\\/fashion-news\\\/38713\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/women\\\/fashion-news\\\/38713\\\/#primaryimage\",\"url\":\"https:\\\/\\\/storage-wp.naewna.com\\\/2026\\\/09\\\/1\u0e1b\u0e01\u0e40\u0e27\u0e47\u0e1a-\u0e2a\u0e2d\u0e07\u0e41\u0e16\u0e27-5.jpg\",\"contentUrl\":\"https:\\\/\\\/storage-wp.naewna.com\\\/2026\\\/09\\\/1\u0e1b\u0e01\u0e40\u0e27\u0e47\u0e1a-\u0e2a\u0e2d\u0e07\u0e41\u0e16\u0e27-5.jpg\",\"width\":1080,\"height\":607},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/women\\\/fashion-news\\\/38713\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tod\u2019s \u0e40\u0e0a\u0e34\u0e14\u0e0a\u0e39\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e1d\u0e35\u0e21\u0e37\u0e2d Made in Italy \u0e1c\u0e48\u0e32\u0e19\u0e42\u0e1b\u0e23\u0e40\u0e08\u0e01\u0e15\u0e4c The Art of Craftsmanship\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#website\",\"url\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/\",\"name\":\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#\\\/schema\\\/person\\\/3ea5b7919fcf4258984bc90d5785176d\",\"name\":\"\u0e01\u0e4a\u0e2d\u0e1a \u0e20\u0e32\u0e1e\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e31\u0e07\u0e04\u0e21\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/818217ae6cf3d680c6e8ce7942fa1646b9b7f7657867b2d3b7b49dfda0b4e1f9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/818217ae6cf3d680c6e8ce7942fa1646b9b7f7657867b2d3b7b49dfda0b4e1f9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/818217ae6cf3d680c6e8ce7942fa1646b9b7f7657867b2d3b7b49dfda0b4e1f9?s=96&d=mm&r=g\",\"caption\":\"\u0e01\u0e4a\u0e2d\u0e1a \u0e20\u0e32\u0e1e\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e31\u0e07\u0e04\u0e21\"},\"url\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/author\\\/ckaiya_02\\\/\"}]}<\/script>\n<meta property=\"article:section\" content=\"Fashion\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tod\u2019s \u0e40\u0e0a\u0e34\u0e14\u0e0a\u0e39\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e1d\u0e35\u0e21\u0e37\u0e2d Made in Italy \u0e1c\u0e48\u0e32\u0e19\u0e42\u0e1b\u0e23\u0e40\u0e08\u0e01\u0e15\u0e4c The Art of Craftsmanship - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.naewna.com\/n\/women\/fashion-news\/38713\/","og_locale":"th_TH","og_type":"article","og_title":"Tod\u2019s \u0e40\u0e0a\u0e34\u0e14\u0e0a\u0e39\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e1d\u0e35\u0e21\u0e37\u0e2d Made in Italy \u0e1c\u0e48\u0e32\u0e19\u0e42\u0e1b\u0e23\u0e40\u0e08\u0e01\u0e15\u0e4c The Art of Craftsmanship","og_description":"\u0e42\u0e1b\u0e23\u0e40\u0e08\u0e01\u0e15\u0e4c\u0e19\u0e35\u0e49\u0e1a\u0e2d\u0e01\u0e40\u0e25\u0e48\u0e32\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e27\u0e21\u0e23\u0e14\u0e01\u0e02\u0e2d\u0e07\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e1c\u0e48\u0e32\u0e19\u0e20\u0e32\u0e1e\u0e23\u0e48\u0e27\u0e21\u0e2a\u0e21\u0e31\u0e22 [&hellip;]","og_url":"https:\/\/www.naewna.com\/n\/women\/fashion-news\/38713\/","og_site_name":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32","article_publisher":"https:\/\/www.facebook.com\/NaewnaOnline","article_published_time":"2026-09-02T05:40:43+00:00","author":"\u0e01\u0e4a\u0e2d\u0e1a \u0e20\u0e32\u0e1e\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e31\u0e07\u0e04\u0e21","twitter_card":"summary_large_image","twitter_creator":"@naewna_news","twitter_site":"@naewna_news","twitter_misc":{"Written by":"\u0e01\u0e4a\u0e2d\u0e1a \u0e20\u0e32\u0e1e\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e31\u0e07\u0e04\u0e21"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.naewna.com\/n\/women\/fashion-news\/38713\/#article","isPartOf":{"@id":"https:\/\/www.naewna.com\/n\/women\/fashion-news\/38713\/"},"author":{"name":"\u0e01\u0e4a\u0e2d\u0e1a \u0e20\u0e32\u0e1e\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e31\u0e07\u0e04\u0e21","@id":"https:\/\/www.naewna.com\/n\/#\/schema\/person\/3ea5b7919fcf4258984bc90d5785176d"},"headline":"Tod\u2019s \u0e40\u0e0a\u0e34\u0e14\u0e0a\u0e39\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e1d\u0e35\u0e21\u0e37\u0e2d Made in Italy \u0e1c\u0e48\u0e32\u0e19\u0e42\u0e1b\u0e23\u0e40\u0e08\u0e01\u0e15\u0e4c The Art of Craftsmanship","datePublished":"2026-09-02T05:40:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.naewna.com\/n\/women\/fashion-news\/38713\/"},"wordCount":34,"image":{"@id":"https:\/\/www.naewna.com\/n\/women\/fashion-news\/38713\/#primaryimage"},"thumbnailUrl":"https:\/\/storage-wp.naewna.com\/2026\/09\/1\u0e1b\u0e01\u0e40\u0e27\u0e47\u0e1a-\u0e2a\u0e2d\u0e07\u0e41\u0e16\u0e27-5.jpg","keywords":["Tod\u2019s"],"articleSection":["Fashion"],"inLanguage":"th","copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/www.naewna.com\/n\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.naewna.com\/n\/women\/fashion-news\/38713\/","url":"https:\/\/www.naewna.com\/n\/women\/fashion-news\/38713\/","name":"Tod\u2019s \u0e40\u0e0a\u0e34\u0e14\u0e0a\u0e39\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e1d\u0e35\u0e21\u0e37\u0e2d Made in Italy \u0e1c\u0e48\u0e32\u0e19\u0e42\u0e1b\u0e23\u0e40\u0e08\u0e01\u0e15\u0e4c The Art of Craftsmanship - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32","isPartOf":{"@id":"https:\/\/www.naewna.com\/n\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.naewna.com\/n\/women\/fashion-news\/38713\/#primaryimage"},"image":{"@id":"https:\/\/www.naewna.com\/n\/women\/fashion-news\/38713\/#primaryimage"},"thumbnailUrl":"https:\/\/storage-wp.naewna.com\/2026\/09\/1\u0e1b\u0e01\u0e40\u0e27\u0e47\u0e1a-\u0e2a\u0e2d\u0e07\u0e41\u0e16\u0e27-5.jpg","datePublished":"2026-09-02T05:40:43+00:00","author":{"@id":"https:\/\/www.naewna.com\/n\/#\/schema\/person\/3ea5b7919fcf4258984bc90d5785176d"},"breadcrumb":{"@id":"https:\/\/www.naewna.com\/n\/women\/fashion-news\/38713\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.naewna.com\/n\/women\/fashion-news\/38713\/"]}]},{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.naewna.com\/n\/women\/fashion-news\/38713\/#primaryimage","url":"https:\/\/storage-wp.naewna.com\/2026\/09\/1\u0e1b\u0e01\u0e40\u0e27\u0e47\u0e1a-\u0e2a\u0e2d\u0e07\u0e41\u0e16\u0e27-5.jpg","contentUrl":"https:\/\/storage-wp.naewna.com\/2026\/09\/1\u0e1b\u0e01\u0e40\u0e27\u0e47\u0e1a-\u0e2a\u0e2d\u0e07\u0e41\u0e16\u0e27-5.jpg","width":1080,"height":607},{"@type":"BreadcrumbList","@id":"https:\/\/www.naewna.com\/n\/women\/fashion-news\/38713\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.naewna.com\/n\/"},{"@type":"ListItem","position":2,"name":"Tod\u2019s \u0e40\u0e0a\u0e34\u0e14\u0e0a\u0e39\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e1d\u0e35\u0e21\u0e37\u0e2d Made in Italy \u0e1c\u0e48\u0e32\u0e19\u0e42\u0e1b\u0e23\u0e40\u0e08\u0e01\u0e15\u0e4c The Art of Craftsmanship"}]},{"@type":"WebSite","@id":"https:\/\/www.naewna.com\/n\/#website","url":"https:\/\/www.naewna.com\/n\/","name":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.naewna.com\/n\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"},{"@type":"Person","@id":"https:\/\/www.naewna.com\/n\/#\/schema\/person\/3ea5b7919fcf4258984bc90d5785176d","name":"\u0e01\u0e4a\u0e2d\u0e1a \u0e20\u0e32\u0e1e\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e31\u0e07\u0e04\u0e21","image":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/secure.gravatar.com\/avatar\/818217ae6cf3d680c6e8ce7942fa1646b9b7f7657867b2d3b7b49dfda0b4e1f9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/818217ae6cf3d680c6e8ce7942fa1646b9b7f7657867b2d3b7b49dfda0b4e1f9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/818217ae6cf3d680c6e8ce7942fa1646b9b7f7657867b2d3b7b49dfda0b4e1f9?s=96&d=mm&r=g","caption":"\u0e01\u0e4a\u0e2d\u0e1a \u0e20\u0e32\u0e1e\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e31\u0e07\u0e04\u0e21"},"url":"https:\/\/www.naewna.com\/n\/author\/ckaiya_02\/"}]}},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/storage-wp.naewna.com\/2026\/09\/1\u0e1b\u0e01\u0e40\u0e27\u0e47\u0e1a-\u0e2a\u0e2d\u0e07\u0e41\u0e16\u0e27-5.jpg","_links":{"self":[{"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/posts\/38713","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/comments?post=38713"}],"version-history":[{"count":2,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/posts\/38713\/revisions"}],"predecessor-version":[{"id":38736,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/posts\/38713\/revisions\/38736"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/media\/38734"}],"wp:attachment":[{"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/media?parent=38713"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/categories?post=38713"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/tags?post=38713"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}