{"id":39093,"date":"2026-09-02T14:22:47","date_gmt":"2026-09-02T07:22:47","guid":{"rendered":"https:\/\/www.naewna.com\/n\/?p=39093"},"modified":"2026-09-02T14:22:48","modified_gmt":"2026-09-02T07:22:48","slug":"%e0%b8%98%e0%b8%99%e0%b8%81%e0%b8%a3-%e0%b8%a2%e0%b9%89%e0%b8%ad%e0%b8%99-%e0%b9%80%e0%b8%97%e0%b9%89%e0%b8%87-%e0%b8%84%e0%b8%99%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%a3%e0%b8%b1%e0%b8%90%e0%b8%9a","status":"publish","type":"post","link":"https:\/\/www.naewna.com\/n\/politics\/39093\/","title":{"rendered":"\u0e18\u0e19\u0e01\u0e23 \u0e22\u0e49\u0e2d\u0e19 \u0e40\u0e17\u0e49\u0e07 \u0e04\u0e19\u0e17\u0e35\u0e48\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e15\u0e34\u0e14\u0e2b\u0e19\u0e35\u0e49\u0e04\u0e37\u0e2d\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e17\u0e35\u0e48\u0e40\u0e25\u0e37\u0e2d\u0e01 \u0e20\u0e39\u0e21\u0e34\u0e43\u0e08\u0e44\u0e17\u0e22 \u0e21\u0e32\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e40\u0e22\u0e49\u0e22\u0e40\u0e2d\u0e32\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e21\u0e32\u0e08\u0e32\u0e01\u0e44\u0e2b\u0e19"},"content":{"rendered":"<div class=\"vce-row-container\" data-vce-boxed-width=\"true\"><div class=\"vce-row vce-row--col-gap-30 vce-row-equal-height vce-row-content--top\" id=\"el-c59326c7\" data-vce-do-apply=\"all el-c59326c7\"><div class=\"vce-row-content\" data-vce-element-content=\"true\"><div class=\"vce-col vce-col--md-auto vce-col--xs-1 vce-col--xs-last vce-col--xs-first vce-col--sm-last vce-col--sm-first vce-col--md-last vce-col--lg-last vce-col--xl-last vce-col--md-first vce-col--lg-first vce-col--xl-first\" id=\"el-0fb13427\"><div class=\"vce-col-inner\" data-vce-do-apply=\"border margin background  el-0fb13427\"><div class=\"vce-col-content\" data-vce-element-content=\"true\" data-vce-do-apply=\"padding el-0fb13427\"><div class=\"vce-text-block\"><div class=\"vce-text-block-wrapper vce\" id=\"el-cea89180\" data-vce-do-apply=\"all el-cea89180\"><p><strong>\"\u0e18\u0e19\u0e01\u0e23\"\u0e22\u0e49\u0e2d\u0e19\"\u0e40\u0e17\u0e49\u0e07\" \u0e04\u0e19\u0e17\u0e35\u0e48\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e15\u0e34\u0e14\u0e2b\u0e19\u0e35\u0e49\u0e04\u0e37\u0e2d\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e17\u0e35\u0e48\u0e40\u0e25\u0e37\u0e2d\u0e01\"\u0e20\u0e39\u0e21\u0e34\u0e43\u0e08\u0e44\u0e17\u0e22\"\u0e21\u0e32\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e40\u0e22\u0e49\u0e22\u0e40\u0e2d\u0e32\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e21\u0e32\u0e08\u0e32\u0e01\u0e44\u0e2b\u0e19 \u0e0a\u0e35\u0e49\u0e2b\u0e25\u0e31\u0e01\u0e10\u0e32\u0e19\u0e40\u0e14\u0e47\u0e14\u0e41\u0e15\u0e48\u0e2a\u0e38\u0e14\u0e17\u0e49\u0e32\u0e22\u0e01\u0e47\u0e41\u0e04\u0e48\u0e21\u0e42\u0e19\u0e17\u0e36\u0e01\u0e17\u0e31\u0e01\u0e40\u0e2d\u0e32\u0e40\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e04\u0e23\u0e31\u0e49\u0e07 \u0e40\u0e2b\u0e19\u0e47\u0e1a\u0e21\u0e31\u0e27\u0e41\u0e15\u0e48\u0e17\u0e33\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e1d\u0e48\u0e32\u0e22\u0e41\u0e04\u0e49\u0e19 \u0e08\u0e19\u0e25\u0e37\u0e21\u0e17\u0e33\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e1d\u0e48\u0e32\u0e22\u0e04\u0e49\u0e32\u0e19<\/strong><\/p>\n<p>2 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2569 \u0e19\u0e32\u0e22\u0e18\u0e19\u0e01\u0e23 \u0e27\u0e31\u0e07\u0e1a\u0e38\u0e0d\u0e04\u0e07\u0e0a\u0e19\u0e30 \u0e2a.\u0e2a.\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e23\u0e32\u0e22\u0e0a\u0e37\u0e48\u0e2d \u0e1e\u0e23\u0e23\u0e04\u0e20\u0e39\u0e21\u0e34\u0e43\u0e08\u0e44\u0e17\u0e22 \u0e41\u0e25\u0e30\u0e2d\u0e14\u0e35\u0e15\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e43\u0e2b\u0e49\u0e2a\u0e31\u0e21\u0e20\u0e32\u0e29\u0e13\u0e4c\u0e16\u0e36\u0e07\u0e01\u0e23\u0e13\u0e35\u0e17\u0e35\u0e48 \u0e19\u0e32\u0e22\u0e13\u0e31\u0e10\u0e1e\u0e07\u0e29\u0e4c \u0e40\u0e23\u0e37\u0e2d\u0e07\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e27\u0e38\u0e12\u0e34 \u0e2a.\u0e2a.\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e23\u0e32\u0e22\u0e0a\u0e37\u0e48\u0e2d \u0e41\u0e25\u0e30\u0e2b\u0e31\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e1e\u0e23\u0e23\u0e04\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19 \u0e23\u0e30\u0e1a\u0e38\u0e27\u0e48\u0e32 \u0e43\u0e19\u0e10\u0e32\u0e19\u0e30\u0e17\u0e35\u0e48\u0e40\u0e04\u0e22\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e19\u0e32\u0e22\u0e2d\u0e19\u0e38\u0e17\u0e34\u0e19 \u0e0a\u0e32\u0e0d\u0e27\u0e35\u0e23\u0e01\u0e39\u0e25 \u0e44\u0e14\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e01\u0e47\u0e2d\u0e22\u0e48\u0e32\u0e25\u0e37\u0e21\u0e27\u0e48\u0e32\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e17\u0e35\u0e48\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e17\u0e48\u0e32\u0e19\u0e2b\u0e25\u0e38\u0e14\u0e08\u0e32\u0e01\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e44\u0e14\u0e49\u0e40\u0e0a\u0e48\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19\u0e27\u0e48\u0e32 \u0e16\u0e49\u0e32\u0e1e\u0e23\u0e23\u0e04\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e08\u0e30\u0e2d\u0e49\u0e32\u0e07\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e1d\u0e48\u0e32\u0e22\u0e17\u0e35\u0e48\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e19\u0e32\u0e22\u0e2d\u0e19\u0e38\u0e17\u0e34\u0e19\u0e44\u0e14\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e43\u0e19\u0e2a\u0e21\u0e31\u0e22\u0e41\u0e23\u0e01\u0e19\u0e31\u0e49\u0e19 \u0e19\u0e32\u0e22\u0e13\u0e31\u0e10\u0e1e\u0e07\u0e29\u0e4c\u0e01\u0e47\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e21\u0e48\u0e25\u0e37\u0e21\u0e14\u0e49\u0e27\u0e22\u0e27\u0e48\u0e32 \u0e41\u0e25\u0e49\u0e27\u0e01\u0e47\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e23\u0e23\u0e04\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e40\u0e2d\u0e07\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e2b\u0e23\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e17\u0e49\u0e32\u0e22\u0e01\u0e47\u0e40\u0e23\u0e35\u0e22\u0e01\u0e23\u0e49\u0e2d\u0e07\u0e43\u0e2b\u0e49\u0e17\u0e48\u0e32\u0e19\u0e19\u0e32\u0e22\u0e01\u0e2f \u0e22\u0e38\u0e1a\u0e2a\u0e20\u0e32\u0e2f \u0e0b\u0e36\u0e48\u0e07\u0e17\u0e48\u0e32\u0e19\u0e19\u0e32\u0e22\u0e01\u0e2f \u0e01\u0e47\u0e22\u0e38\u0e1a\u0e2a\u0e20\u0e32\u0e2f \u0e43\u0e2b\u0e49\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e40\u0e23\u0e35\u0e22\u0e01\u0e23\u0e49\u0e2d\u0e07 \u0e08\u0e36\u0e07\u0e16\u0e37\u0e2d\u0e27\u0e48\u0e32\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e15\u0e34\u0e14\u0e2b\u0e19\u0e35\u0e49\u0e2d\u0e30\u0e44\u0e23\u0e01\u0e31\u0e19\u0e41\u0e25\u0e49\u0e27 \u0e14\u0e31\u0e07\u0e19\u0e31\u0e49\u0e19 \u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e19\u0e32\u0e22\u0e2d\u0e19\u0e38\u0e17\u0e34\u0e19\u0e01\u0e25\u0e31\u0e1a\u0e21\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e01\u0e2f \u0e43\u0e19\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48 2 \u0e44\u0e14\u0e49\u0e19\u0e31\u0e49\u0e19 \u0e08\u0e36\u0e07\u0e21\u0e32\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e15\u0e31\u0e14\u0e2a\u0e34\u0e19\u0e43\u0e08\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e04\u0e19\u0e44\u0e17\u0e22\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e31\u0e49\u0e07\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 8 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32 \u0e08\u0e19\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e30\u0e41\u0e19\u0e19\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e23\u0e23\u0e04\u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a\u0e2b\u0e19\u0e36\u0e48\u0e07 \u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e23\u0e2d\u0e1a\u0e19\u0e35\u0e49\u0e01\u0e47\u0e44\u0e21\u0e48\u0e21\u0e35 \u0e2a.\u0e2a.\u0e02\u0e2d\u0e07\u0e1e\u0e23\u0e23\u0e04\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e21\u0e32\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e19\u0e32\u0e22\u0e2d\u0e19\u0e38\u0e17\u0e34\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e01\u0e2f \u0e41\u0e21\u0e49\u0e41\u0e15\u0e48\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e14\u0e31\u0e07\u0e19\u0e31\u0e49\u0e19\u0e2b\u0e32\u0e01\u0e08\u0e30\u0e21\u0e32\u0e07\u0e2d\u0e41\u0e07\u0e2d\u0e49\u0e32\u0e07\u0e27\u0e48\u0e32\u0e21\u0e35\u0e2b\u0e19\u0e35\u0e49\u0e1a\u0e38\u0e0d\u0e04\u0e38\u0e13\u0e2d\u0e30\u0e44\u0e23\u0e19\u0e31\u0e49\u0e19\u0e01\u0e47\u0e04\u0e07\u0e44\u0e21\u0e48\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07<\/p>\n<p>\u0e19\u0e32\u0e22\u0e18\u0e19\u0e01\u0e23 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e2d\u0e35\u0e01\u0e27\u0e48\u0e32 \u0e17\u0e48\u0e32\u0e19\u0e19\u0e32\u0e22\u0e01\u0e2f \u0e1e\u0e39\u0e14\u0e0a\u0e31\u0e14\u0e40\u0e08\u0e19\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48\u0e40\u0e02\u0e49\u0e32\u0e23\u0e31\u0e1a\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e27\u0e48\u0e32 \u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e32\u0e22\u0e32\u0e17\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e02\u0e2d\u0e07\u0e43\u0e04\u0e23 \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e19\u0e31\u0e49\u0e19\u0e21\u0e32\u0e08\u0e32\u0e01\u0e04\u0e27\u0e32\u0e21\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e31\u0e48\u0e19\u0e02\u0e2d\u0e07\u0e1e\u0e35\u0e48\u0e19\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e27\u0e48\u0e32 \u0e1e\u0e23\u0e23\u0e04\u0e20\u0e39\u0e21\u0e34\u0e43\u0e08\u0e44\u0e17\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e23\u0e23\u0e04\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e1e\u0e39\u0e14\u0e41\u0e25\u0e49\u0e27\u0e17\u0e33 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e08\u0e36\u0e07\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e43\u0e08\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e1e\u0e23\u0e23\u0e04\u0e20\u0e39\u0e21\u0e34\u0e43\u0e08\u0e44\u0e17\u0e22\u0e44\u0e14\u0e49\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e14\u0e31\u0e07\u0e19\u0e31\u0e49\u0e19 \u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e19\u0e32\u0e22\u0e2d\u0e19\u0e38\u0e17\u0e34\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e01\u0e2f \u0e43\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e08\u0e36\u0e07\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e21\u0e32\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e1a\u0e38\u0e0d\u0e04\u0e38\u0e13\u0e02\u0e2d\u0e07\u0e43\u0e04\u0e23 \u0e41\u0e15\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e1a\u0e38\u0e0d\u0e04\u0e38\u0e13\u0e02\u0e2d\u0e07\u0e1e\u0e35\u0e48\u0e19\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e0a\u0e32\u0e27\u0e44\u0e17\u0e22\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e2b\u0e32\u0e01\u0e17\u0e48\u0e32\u0e19\u0e19\u0e32\u0e22\u0e01\u0e2f \u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e15\u0e2d\u0e1a\u0e41\u0e17\u0e19\u0e43\u0e04\u0e23 \u0e01\u0e47\u0e04\u0e07\u0e15\u0e49\u0e2d\u0e07\u0e15\u0e2d\u0e1a\u0e41\u0e17\u0e19\u0e1e\u0e23\u0e30\u0e04\u0e38\u0e13\u0e1e\u0e35\u0e48\u0e19\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e04\u0e19\u0e44\u0e17\u0e22\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e44\u0e21\u0e48\u0e2d\u0e22\u0e32\u0e01\u0e43\u0e2b\u0e49\u0e1d\u0e48\u0e32\u0e22\u0e04\u0e49\u0e32\u0e19\u0e40\u0e19\u0e49\u0e19\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e27\u0e32\u0e17\u0e01\u0e23\u0e23\u0e21 \u0e2b\u0e23\u0e37\u0e2d\u0e08\u0e49\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e08\u0e30\u0e14\u0e34\u0e2a\u0e40\u0e04\u0e23\u0e14\u0e34\u0e15\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e2d\u0e22\u0e32\u0e01\u0e43\u0e2b\u0e49\u0e17\u0e33\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e01\u0e33\u0e25\u0e31\u0e07\u0e40\u0e1c\u0e0a\u0e34\u0e0d\u0e01\u0e31\u0e1a\u0e27\u0e34\u0e01\u0e24\u0e15\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e42\u0e25\u0e01\u0e01\u0e47\u0e16\u0e37\u0e2d\u0e27\u0e48\u0e32\u0e2b\u0e19\u0e31\u0e01\u0e21\u0e32\u0e01\u0e1e\u0e2d\u0e41\u0e25\u0e49\u0e27 \u0e02\u0e2d\u0e43\u0e2b\u0e49\u0e1d\u0e48\u0e32\u0e22\u0e04\u0e49\u0e32\u0e19\u0e17\u0e33\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e17\u0e49\u0e27\u0e07\u0e15\u0e34\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e35\u0e40\u0e2b\u0e15\u0e38\u0e1c\u0e25 \u0e43\u0e0a\u0e49\u0e01\u0e25\u0e44\u0e01\u0e02\u0e2d\u0e07\u0e2a\u0e20\u0e32\u0e2f \u0e17\u0e49\u0e27\u0e07\u0e15\u0e34\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07 \u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e40\u0e19\u0e49\u0e19\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e27\u0e32\u0e17\u0e01\u0e23\u0e23\u0e21\u0e43\u0e2b\u0e21\u0e48\u0e23\u0e32\u0e22\u0e27\u0e31\u0e19 \u0e08\u0e19\u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e1d\u0e48\u0e32\u0e22\u0e41\u0e04\u0e49\u0e19\u0e41\u0e25\u0e49\u0e27\u0e25\u0e37\u0e21\u0e17\u0e33\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e1d\u0e48\u0e32\u0e22\u0e04\u0e49\u0e32\u0e19<\/p>\n<p>\u201c\u0e1c\u0e21\u0e44\u0e21\u0e48\u0e23\u0e39\u0e49\u0e27\u0e48\u0e32\u0e19\u0e32\u0e22\u0e13\u0e31\u0e10\u0e1e\u0e07\u0e29\u0e4c\u0e44\u0e1b\u0e40\u0e2d\u0e32\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e21\u0e32\u0e08\u0e32\u0e01\u0e44\u0e2b\u0e19 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e40\u0e25\u0e22\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e17\u0e32\u0e07\u0e23\u0e31\u0e10\u0e18\u0e23\u0e23\u0e21\u0e19\u0e39\u0e0d \u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e35\u0e22\u0e07 \u0e2a.\u0e2a.\u0e22\u0e01\u0e21\u0e37\u0e2d\u0e44\u0e21\u0e48\u0e44\u0e27\u0e49\u0e27\u0e32\u0e07\u0e43\u0e08\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32\u0e01\u0e36\u0e48\u0e07\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e08\u0e33\u0e19\u0e27\u0e19 \u0e2a.\u0e2a.\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\u0e40\u0e17\u0e48\u0e32\u0e17\u0e35\u0e48\u0e21\u0e35\u0e2d\u0e22\u0e39\u0e48 \u0e15\u0e49\u0e2d\u0e07\u0e16\u0e32\u0e21\u0e27\u0e48\u0e32 \u0e1e\u0e23\u0e23\u0e04\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e08\u0e30\u0e2b\u0e32\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e21\u0e32\u0e23\u0e48\u0e27\u0e21\u0e44\u0e14\u0e49\u0e02\u0e19\u0e32\u0e14\u0e19\u0e31\u0e49\u0e19\u0e08\u0e32\u0e01\u0e17\u0e35\u0e48\u0e44\u0e2b\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e2b\u0e32\u0e01\u0e08\u0e30\u0e22\u0e37\u0e48\u0e19 \u0e1b.\u0e1b.\u0e0a.\u0e14\u0e49\u0e27\u0e22\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e17\u0e35\u0e48\u0e1d\u0e48\u0e32\u0e22\u0e04\u0e49\u0e32\u0e19\u0e2b\u0e22\u0e34\u0e1a\u0e22\u0e01\u0e21\u0e32\u0e2d\u0e20\u0e34\u0e1b\u0e23\u0e32\u0e22\u0e44\u0e21\u0e48\u0e44\u0e27\u0e49\u0e27\u0e32\u0e07\u0e43\u0e08\u0e19\u0e31\u0e49\u0e19 \u0e01\u0e47\u0e04\u0e27\u0e23\u0e15\u0e49\u0e2d\u0e07\u0e22\u0e49\u0e2d\u0e19\u0e16\u0e32\u0e21\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u0e01\u0e48\u0e2d\u0e19\u0e27\u0e48\u0e32 \u0e2b\u0e25\u0e31\u0e01\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e17\u0e35\u0e48\u0e2d\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19\u0e21\u0e35\u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e1e\u0e2d\u0e17\u0e35\u0e48\u0e08\u0e30\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e17\u0e48\u0e32\u0e19\u0e19\u0e32\u0e22\u0e01\u0e2f \u0e2b\u0e25\u0e38\u0e14\u0e08\u0e32\u0e01\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e44\u0e14\u0e49\u0e08\u0e23\u0e34\u0e07\u0e2b\u0e23\u0e37\u0e2d \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01\u0e17\u0e35\u0e48\u0e17\u0e36\u0e01\u0e17\u0e31\u0e01\u0e01\u0e31\u0e19\u0e40\u0e2d\u0e32\u0e40\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e2a\u0e32\u0e22\u0e15\u0e32\u0e02\u0e2d\u0e07\u0e1d\u0e48\u0e32\u0e22\u0e04\u0e49\u0e32\u0e19\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32\u0e46 \u0e21\u0e31\u0e01\u0e40\u0e2b\u0e47\u0e19\u0e41\u0e15\u0e48\u0e2b\u0e25\u0e31\u0e01\u0e10\u0e32\u0e19\u0e15\u0e31\u0e14\u0e41\u0e1b\u0e30\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e2a\u0e19\u0e2d\u0e02\u0e48\u0e32\u0e27\u0e02\u0e2d\u0e07\u0e2a\u0e37\u0e48\u0e2d\u0e21\u0e27\u0e25\u0e0a\u0e19\u0e1a\u0e49\u0e32\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48\u0e01\u0e47\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e17\u0e35\u0e48\u0e21\u0e42\u0e19\u0e40\u0e2d\u0e32\u0e40\u0e2d\u0e07\u0e1a\u0e49\u0e32\u0e07\u201d \u0e19\u0e32\u0e22\u0e18\u0e19\u0e01\u0e23 \u0e01\u0e25\u0e48\u0e32\u0e27<\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;\u0e18\u0e19\u0e01\u0e23&#8221;\u0e22\u0e49\u0e2d\u0e19&#8221;\u0e40\u0e17\u0e49\u0e07&#8221; \u0e04\u0e19\u0e17\u0e35\u0e48\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e15\u0e34\u0e14\u0e2b\u0e19\u0e35\u0e49\u0e04\u0e37\u0e2d\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e17\u0e35\u0e48\u0e40\u0e25\u0e37\u0e2d\u0e01&#8221;\u0e20 [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":39094,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[5],"tags":[6021],"class_list":["post-39093","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politics","tag-6021"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u0e18\u0e19\u0e01\u0e23 \u0e22\u0e49\u0e2d\u0e19 \u0e40\u0e17\u0e49\u0e07 \u0e04\u0e19\u0e17\u0e35\u0e48\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e15\u0e34\u0e14\u0e2b\u0e19\u0e35\u0e49\u0e04\u0e37\u0e2d\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e17\u0e35\u0e48\u0e40\u0e25\u0e37\u0e2d\u0e01 \u0e20\u0e39\u0e21\u0e34\u0e43\u0e08\u0e44\u0e17\u0e22 \u0e21\u0e32\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e40\u0e22\u0e49\u0e22\u0e40\u0e2d\u0e32\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e21\u0e32\u0e08\u0e32\u0e01\u0e44\u0e2b\u0e19 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.naewna.com\/n\/politics\/39093\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e18\u0e19\u0e01\u0e23 \u0e22\u0e49\u0e2d\u0e19 \u0e40\u0e17\u0e49\u0e07 \u0e04\u0e19\u0e17\u0e35\u0e48\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e15\u0e34\u0e14\u0e2b\u0e19\u0e35\u0e49\u0e04\u0e37\u0e2d\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e17\u0e35\u0e48\u0e40\u0e25\u0e37\u0e2d\u0e01 \u0e20\u0e39\u0e21\u0e34\u0e43\u0e08\u0e44\u0e17\u0e22 \u0e21\u0e32\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e40\u0e22\u0e49\u0e22\u0e40\u0e2d\u0e32\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e21\u0e32\u0e08\u0e32\u0e01\u0e44\u0e2b\u0e19\" \/>\n<meta property=\"og:description\" content=\"&quot;\u0e18\u0e19\u0e01\u0e23&quot;\u0e22\u0e49\u0e2d\u0e19&quot;\u0e40\u0e17\u0e49\u0e07&quot; \u0e04\u0e19\u0e17\u0e35\u0e48\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e15\u0e34\u0e14\u0e2b\u0e19\u0e35\u0e49\u0e04\u0e37\u0e2d\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e17\u0e35\u0e48\u0e40\u0e25\u0e37\u0e2d\u0e01&quot;\u0e20 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.naewna.com\/n\/politics\/39093\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NaewnaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2026-09-02T07:22:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-02T07:22:48+00:00\" \/>\n<meta name=\"author\" content=\"monthontus\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@naewna_news\" \/>\n<meta name=\"twitter:site\" content=\"@naewna_news\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"monthontus\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/politics\\\/39093\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/politics\\\/39093\\\/\"},\"author\":{\"name\":\"monthontus\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#\\\/schema\\\/person\\\/c661d95de6b20e592a319a8ef805436a\"},\"headline\":\"\u0e18\u0e19\u0e01\u0e23 \u0e22\u0e49\u0e2d\u0e19 \u0e40\u0e17\u0e49\u0e07 \u0e04\u0e19\u0e17\u0e35\u0e48\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e15\u0e34\u0e14\u0e2b\u0e19\u0e35\u0e49\u0e04\u0e37\u0e2d\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e17\u0e35\u0e48\u0e40\u0e25\u0e37\u0e2d\u0e01 \u0e20\u0e39\u0e21\u0e34\u0e43\u0e08\u0e44\u0e17\u0e22 \u0e21\u0e32\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e40\u0e22\u0e49\u0e22\u0e40\u0e2d\u0e32\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e21\u0e32\u0e08\u0e32\u0e01\u0e44\u0e2b\u0e19\",\"datePublished\":\"2026-09-02T07:22:47+00:00\",\"dateModified\":\"2026-09-02T07:22:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/politics\\\/39093\\\/\"},\"wordCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/politics\\\/39093\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/storage-wp.naewna.com\\\/2026\\\/09\\\/1-57.jpg\",\"keywords\":[\"\u0e18\u0e19\u0e01\u0e23 \u0e27\u0e31\u0e07\u0e1a\u0e38\u0e0d\u0e04\u0e07\u0e0a\u0e19\u0e30,\u0e1e\u0e23\u0e23\u0e04\u0e20\u0e39\u0e21\u0e34\u0e43\u0e08\u0e44\u0e17\u0e22,\u0e13\u0e31\u0e10\u0e1e\u0e07\u0e29\u0e4c \u0e40\u0e23\u0e37\u0e2d\u0e07\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e27\u0e38\u0e12\u0e34,\u0e1e\u0e23\u0e23\u0e04\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19,\"],\"articleSection\":[\"\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07\"],\"inLanguage\":\"th\",\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/politics\\\/39093\\\/\",\"url\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/politics\\\/39093\\\/\",\"name\":\"\u0e18\u0e19\u0e01\u0e23 \u0e22\u0e49\u0e2d\u0e19 \u0e40\u0e17\u0e49\u0e07 \u0e04\u0e19\u0e17\u0e35\u0e48\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e15\u0e34\u0e14\u0e2b\u0e19\u0e35\u0e49\u0e04\u0e37\u0e2d\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e17\u0e35\u0e48\u0e40\u0e25\u0e37\u0e2d\u0e01 \u0e20\u0e39\u0e21\u0e34\u0e43\u0e08\u0e44\u0e17\u0e22 \u0e21\u0e32\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e40\u0e22\u0e49\u0e22\u0e40\u0e2d\u0e32\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e21\u0e32\u0e08\u0e32\u0e01\u0e44\u0e2b\u0e19 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/politics\\\/39093\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/politics\\\/39093\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/storage-wp.naewna.com\\\/2026\\\/09\\\/1-57.jpg\",\"datePublished\":\"2026-09-02T07:22:47+00:00\",\"dateModified\":\"2026-09-02T07:22:48+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#\\\/schema\\\/person\\\/c661d95de6b20e592a319a8ef805436a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/politics\\\/39093\\\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.naewna.com\\\/n\\\/politics\\\/39093\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/politics\\\/39093\\\/#primaryimage\",\"url\":\"https:\\\/\\\/storage-wp.naewna.com\\\/2026\\\/09\\\/1-57.jpg\",\"contentUrl\":\"https:\\\/\\\/storage-wp.naewna.com\\\/2026\\\/09\\\/1-57.jpg\",\"width\":1080,\"height\":607},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/politics\\\/39093\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e18\u0e19\u0e01\u0e23 \u0e22\u0e49\u0e2d\u0e19 \u0e40\u0e17\u0e49\u0e07 \u0e04\u0e19\u0e17\u0e35\u0e48\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e15\u0e34\u0e14\u0e2b\u0e19\u0e35\u0e49\u0e04\u0e37\u0e2d\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e17\u0e35\u0e48\u0e40\u0e25\u0e37\u0e2d\u0e01 \u0e20\u0e39\u0e21\u0e34\u0e43\u0e08\u0e44\u0e17\u0e22 \u0e21\u0e32\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e40\u0e22\u0e49\u0e22\u0e40\u0e2d\u0e32\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e21\u0e32\u0e08\u0e32\u0e01\u0e44\u0e2b\u0e19\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#website\",\"url\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/\",\"name\":\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#\\\/schema\\\/person\\\/c661d95de6b20e592a319a8ef805436a\",\"name\":\"monthontus\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/753bd31ff90c84edaffda4a60b4fe164e7a044d02e4bfe0e761be429dcca30ac?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/753bd31ff90c84edaffda4a60b4fe164e7a044d02e4bfe0e761be429dcca30ac?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/753bd31ff90c84edaffda4a60b4fe164e7a044d02e4bfe0e761be429dcca30ac?s=96&d=mm&r=g\",\"caption\":\"monthontus\"},\"url\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/author\\\/monthontus\\\/\"}]}<\/script>\n<meta property=\"article:section\" content=\"\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u0e18\u0e19\u0e01\u0e23 \u0e22\u0e49\u0e2d\u0e19 \u0e40\u0e17\u0e49\u0e07 \u0e04\u0e19\u0e17\u0e35\u0e48\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e15\u0e34\u0e14\u0e2b\u0e19\u0e35\u0e49\u0e04\u0e37\u0e2d\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e17\u0e35\u0e48\u0e40\u0e25\u0e37\u0e2d\u0e01 \u0e20\u0e39\u0e21\u0e34\u0e43\u0e08\u0e44\u0e17\u0e22 \u0e21\u0e32\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e40\u0e22\u0e49\u0e22\u0e40\u0e2d\u0e32\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e21\u0e32\u0e08\u0e32\u0e01\u0e44\u0e2b\u0e19 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.naewna.com\/n\/politics\/39093\/","og_locale":"th_TH","og_type":"article","og_title":"\u0e18\u0e19\u0e01\u0e23 \u0e22\u0e49\u0e2d\u0e19 \u0e40\u0e17\u0e49\u0e07 \u0e04\u0e19\u0e17\u0e35\u0e48\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e15\u0e34\u0e14\u0e2b\u0e19\u0e35\u0e49\u0e04\u0e37\u0e2d\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e17\u0e35\u0e48\u0e40\u0e25\u0e37\u0e2d\u0e01 \u0e20\u0e39\u0e21\u0e34\u0e43\u0e08\u0e44\u0e17\u0e22 \u0e21\u0e32\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e40\u0e22\u0e49\u0e22\u0e40\u0e2d\u0e32\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e21\u0e32\u0e08\u0e32\u0e01\u0e44\u0e2b\u0e19","og_description":"\"\u0e18\u0e19\u0e01\u0e23\"\u0e22\u0e49\u0e2d\u0e19\"\u0e40\u0e17\u0e49\u0e07\" \u0e04\u0e19\u0e17\u0e35\u0e48\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e15\u0e34\u0e14\u0e2b\u0e19\u0e35\u0e49\u0e04\u0e37\u0e2d\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e17\u0e35\u0e48\u0e40\u0e25\u0e37\u0e2d\u0e01\"\u0e20 [&hellip;]","og_url":"https:\/\/www.naewna.com\/n\/politics\/39093\/","og_site_name":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32","article_publisher":"https:\/\/www.facebook.com\/NaewnaOnline","article_published_time":"2026-09-02T07:22:47+00:00","article_modified_time":"2026-09-02T07:22:48+00:00","author":"monthontus","twitter_card":"summary_large_image","twitter_creator":"@naewna_news","twitter_site":"@naewna_news","twitter_misc":{"Written by":"monthontus"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.naewna.com\/n\/politics\/39093\/#article","isPartOf":{"@id":"https:\/\/www.naewna.com\/n\/politics\/39093\/"},"author":{"name":"monthontus","@id":"https:\/\/www.naewna.com\/n\/#\/schema\/person\/c661d95de6b20e592a319a8ef805436a"},"headline":"\u0e18\u0e19\u0e01\u0e23 \u0e22\u0e49\u0e2d\u0e19 \u0e40\u0e17\u0e49\u0e07 \u0e04\u0e19\u0e17\u0e35\u0e48\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e15\u0e34\u0e14\u0e2b\u0e19\u0e35\u0e49\u0e04\u0e37\u0e2d\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e17\u0e35\u0e48\u0e40\u0e25\u0e37\u0e2d\u0e01 \u0e20\u0e39\u0e21\u0e34\u0e43\u0e08\u0e44\u0e17\u0e22 \u0e21\u0e32\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e40\u0e22\u0e49\u0e22\u0e40\u0e2d\u0e32\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e21\u0e32\u0e08\u0e32\u0e01\u0e44\u0e2b\u0e19","datePublished":"2026-09-02T07:22:47+00:00","dateModified":"2026-09-02T07:22:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.naewna.com\/n\/politics\/39093\/"},"wordCount":0,"image":{"@id":"https:\/\/www.naewna.com\/n\/politics\/39093\/#primaryimage"},"thumbnailUrl":"https:\/\/storage-wp.naewna.com\/2026\/09\/1-57.jpg","keywords":["\u0e18\u0e19\u0e01\u0e23 \u0e27\u0e31\u0e07\u0e1a\u0e38\u0e0d\u0e04\u0e07\u0e0a\u0e19\u0e30,\u0e1e\u0e23\u0e23\u0e04\u0e20\u0e39\u0e21\u0e34\u0e43\u0e08\u0e44\u0e17\u0e22,\u0e13\u0e31\u0e10\u0e1e\u0e07\u0e29\u0e4c \u0e40\u0e23\u0e37\u0e2d\u0e07\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e27\u0e38\u0e12\u0e34,\u0e1e\u0e23\u0e23\u0e04\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19,"],"articleSection":["\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07"],"inLanguage":"th","copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/www.naewna.com\/n\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.naewna.com\/n\/politics\/39093\/","url":"https:\/\/www.naewna.com\/n\/politics\/39093\/","name":"\u0e18\u0e19\u0e01\u0e23 \u0e22\u0e49\u0e2d\u0e19 \u0e40\u0e17\u0e49\u0e07 \u0e04\u0e19\u0e17\u0e35\u0e48\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e15\u0e34\u0e14\u0e2b\u0e19\u0e35\u0e49\u0e04\u0e37\u0e2d\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e17\u0e35\u0e48\u0e40\u0e25\u0e37\u0e2d\u0e01 \u0e20\u0e39\u0e21\u0e34\u0e43\u0e08\u0e44\u0e17\u0e22 \u0e21\u0e32\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e40\u0e22\u0e49\u0e22\u0e40\u0e2d\u0e32\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e21\u0e32\u0e08\u0e32\u0e01\u0e44\u0e2b\u0e19 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32","isPartOf":{"@id":"https:\/\/www.naewna.com\/n\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.naewna.com\/n\/politics\/39093\/#primaryimage"},"image":{"@id":"https:\/\/www.naewna.com\/n\/politics\/39093\/#primaryimage"},"thumbnailUrl":"https:\/\/storage-wp.naewna.com\/2026\/09\/1-57.jpg","datePublished":"2026-09-02T07:22:47+00:00","dateModified":"2026-09-02T07:22:48+00:00","author":{"@id":"https:\/\/www.naewna.com\/n\/#\/schema\/person\/c661d95de6b20e592a319a8ef805436a"},"breadcrumb":{"@id":"https:\/\/www.naewna.com\/n\/politics\/39093\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.naewna.com\/n\/politics\/39093\/"]}]},{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.naewna.com\/n\/politics\/39093\/#primaryimage","url":"https:\/\/storage-wp.naewna.com\/2026\/09\/1-57.jpg","contentUrl":"https:\/\/storage-wp.naewna.com\/2026\/09\/1-57.jpg","width":1080,"height":607},{"@type":"BreadcrumbList","@id":"https:\/\/www.naewna.com\/n\/politics\/39093\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.naewna.com\/n\/"},{"@type":"ListItem","position":2,"name":"\u0e18\u0e19\u0e01\u0e23 \u0e22\u0e49\u0e2d\u0e19 \u0e40\u0e17\u0e49\u0e07 \u0e04\u0e19\u0e17\u0e35\u0e48\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e15\u0e34\u0e14\u0e2b\u0e19\u0e35\u0e49\u0e04\u0e37\u0e2d\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e17\u0e35\u0e48\u0e40\u0e25\u0e37\u0e2d\u0e01 \u0e20\u0e39\u0e21\u0e34\u0e43\u0e08\u0e44\u0e17\u0e22 \u0e21\u0e32\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e40\u0e22\u0e49\u0e22\u0e40\u0e2d\u0e32\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e21\u0e32\u0e08\u0e32\u0e01\u0e44\u0e2b\u0e19"}]},{"@type":"WebSite","@id":"https:\/\/www.naewna.com\/n\/#website","url":"https:\/\/www.naewna.com\/n\/","name":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.naewna.com\/n\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"},{"@type":"Person","@id":"https:\/\/www.naewna.com\/n\/#\/schema\/person\/c661d95de6b20e592a319a8ef805436a","name":"monthontus","image":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/secure.gravatar.com\/avatar\/753bd31ff90c84edaffda4a60b4fe164e7a044d02e4bfe0e761be429dcca30ac?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/753bd31ff90c84edaffda4a60b4fe164e7a044d02e4bfe0e761be429dcca30ac?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/753bd31ff90c84edaffda4a60b4fe164e7a044d02e4bfe0e761be429dcca30ac?s=96&d=mm&r=g","caption":"monthontus"},"url":"https:\/\/www.naewna.com\/n\/author\/monthontus\/"}]}},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/storage-wp.naewna.com\/2026\/09\/1-57.jpg","_links":{"self":[{"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/posts\/39093","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/comments?post=39093"}],"version-history":[{"count":2,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/posts\/39093\/revisions"}],"predecessor-version":[{"id":39096,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/posts\/39093\/revisions\/39096"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/media\/39094"}],"wp:attachment":[{"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/media?parent=39093"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/categories?post=39093"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/tags?post=39093"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}