{"id":39692,"date":"2026-09-02T17:46:23","date_gmt":"2026-09-02T10:46:23","guid":{"rendered":"https:\/\/www.naewna.com\/n\/?p=39692"},"modified":"2026-09-02T17:51:40","modified_gmt":"2026-09-02T10:51:40","slug":"%e0%b9%82%e0%b8%8b%e0%b9%80%e0%b8%8a%e0%b8%b5%e0%b8%a2%e0%b8%a5%e0%b8%ae%e0%b8%b7%e0%b8%ad%e0%b8%ae%e0%b8%b2-%e0%b8%a1%e0%b8%ab%e0%b8%b1%e0%b8%a8%e0%b8%88%e0%b8%a3%e0%b8%a3%e0%b8%a2%e0%b9%8c%e0%b8%98","status":"publish","type":"post","link":"https:\/\/www.naewna.com\/n\/like-learn\/39692\/","title":{"rendered":"\u0e42\u0e0b\u0e40\u0e0a\u0e35\u0e22\u0e25\u0e2e\u0e37\u0e2d\u0e2e\u0e32 \u0e21\u0e2b\u0e31\u0e28\u0e08\u0e23\u0e23\u0e22\u0e4c\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 \u0e19\u0e01\u0e08\u0e23\u0e34\u0e07 \u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48 AI \u0e0a\u0e32\u0e27\u0e40\u0e19\u0e47\u0e15\u0e41\u0e2b\u0e48\u0e41\u0e0b\u0e27\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e15\u0e31\u0e27\u0e25\u0e30\u0e04\u0e23\u0e21\u0e31\u0e07\u0e07\u0e30\u0e0a\u0e37\u0e48\u0e2d\u0e14\u0e31\u0e07"},"content":{"rendered":"<div class=\"vce-row-container\" data-vce-boxed-width=\"true\"><div class=\"vce-row vce-row--col-gap-30 vce-row-equal-height vce-row-content--top\" id=\"el-10bfba33\" data-vce-do-apply=\"all el-10bfba33\"><div class=\"vce-row-content\" data-vce-element-content=\"true\"><div class=\"vce-col vce-col--md-auto vce-col--xs-1 vce-col--xs-last vce-col--xs-first vce-col--sm-last vce-col--sm-first vce-col--md-last vce-col--lg-last vce-col--xl-last vce-col--md-first vce-col--lg-first vce-col--xl-first\" id=\"el-06c38e17\"><div class=\"vce-col-inner\" data-vce-do-apply=\"border margin background  el-06c38e17\"><div class=\"vce-col-content\" data-vce-element-content=\"true\" data-vce-do-apply=\"padding el-06c38e17\"><div class=\"vce-text-block\"><div class=\"vce-text-block-wrapper vce\" id=\"el-7a6baf16\" data-vce-do-apply=\"all el-7a6baf16\"><p>\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 31 \u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21 2569 \u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e01\u0e31\u0e19\u0e2e\u0e37\u0e2d\u0e2e\u0e32\u0e01\u0e31\u0e19\u0e1a\u0e19\u0e42\u0e25\u0e01\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e1a\u0e19\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21 Reddit \u0e2b\u0e25\u0e31\u0e07\u0e21\u0e35\u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e0a\u0e37\u0e48\u0e2d SerafinZufferey \u0e42\u0e1e\u0e2a\u0e15\u0e4c\u0e20\u0e32\u0e1e\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1b\u0e48\u0e32\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e08\u0e32\u0e01\u0e0a\u0e48\u0e32\u0e07\u0e20\u0e32\u0e1e\u0e04\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07 \u0e08\u0e19\u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e23\u0e30\u0e41\u0e2a\u0e44\u0e27\u0e23\u0e31\u0e25 \u0e17\u0e33\u0e40\u0e2d\u0e32\u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19\u0e16\u0e36\u0e07\u0e01\u0e31\u0e1a\u0e15\u0e49\u0e2d\u0e07\u0e02\u0e22\u0e35\u0e49\u0e15\u0e32\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e19\u0e36\u0e01\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e20\u0e32\u0e1e\u0e27\u0e32\u0e14\u0e07\u0e32\u0e19\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e31\u0e27\u0e25\u0e30\u0e04\u0e23\u0e08\u0e32\u0e01\u0e2d\u0e19\u0e34\u0e40\u0e21\u0e30\u0e0a\u0e37\u0e48\u0e2d\u0e14\u0e31\u0e07<\/p>\n<p>\u0e0b\u0e36\u0e48\u0e07\u0e04\u0e27\u0e32\u0e21\u0e42\u0e14\u0e14\u0e40\u0e14\u0e48\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e30\u0e01\u0e14\u0e17\u0e38\u0e01\u0e2a\u0e32\u0e22\u0e15\u0e32\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48 \u0e14\u0e27\u0e07\u0e15\u0e32\u0e2a\u0e35\u0e41\u0e14\u0e07\u0e09\u0e32\u0e19 \u0e25\u0e27\u0e14\u0e25\u0e32\u0e22\u0e25\u0e36\u0e01\u0e25\u0e31\u0e1a\u0e0a\u0e27\u0e19\u0e04\u0e49\u0e19\u0e2b\u0e32 \u0e1c\u0e2a\u0e32\u0e19\u0e40\u0e02\u0e49\u0e32\u0e01\u0e31\u0e1a\u0e17\u0e23\u0e07\u0e1c\u0e21\u0e2b\u0e07\u0e2d\u0e19\u0e02\u0e19\u0e2a\u0e35\u0e14\u0e33\u0e2a\u0e25\u0e31\u0e1a\u0e02\u0e32\u0e27\u0e41\u0e25\u0e49\u0e27 \u0e41\u0e25\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e08\u0e49\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1b\u0e48\u0e32\u0e0a\u0e19\u0e34\u0e14\u0e19\u0e35\u0e49\u0e19\u0e31\u0e49\u0e19\u0e01\u0e47\u0e04\u0e37\u0e2d \u0e19\u0e01\u0e40\u0e1b\u0e47\u0e14\u0e1c\u0e35\u0e2b\u0e07\u0e2d\u0e19\u0e02\u0e32\u0e27 \u0e21\u0e35\u0e0a\u0e37\u0e48\u0e2d\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e27\u0e48\u0e32 Rollandia rolland \u0e21\u0e35\u0e16\u0e34\u0e48\u0e19\u0e01\u0e33\u0e40\u0e19\u0e34\u0e14\u0e41\u0e25\u0e30\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e2d\u0e22\u0e39\u0e48\u0e15\u0e32\u0e21\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e19\u0e49\u0e33\u0e08\u0e37\u0e14\u0e41\u0e25\u0e30\u0e17\u0e30\u0e40\u0e25\u0e2a\u0e32\u0e1a\u0e17\u0e32\u0e07\u0e15\u0e2d\u0e19\u0e43\u0e15\u0e49\u0e02\u0e2d\u0e07\u0e17\u0e27\u0e35\u0e1b\u0e2d\u0e40\u0e21\u0e23\u0e34\u0e01\u0e32\u0e43\u0e15\u0e49 \u0e40\u0e0a\u0e48\u0e19 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e0a\u0e34\u0e25\u0e35 \u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e08\u0e19\u0e15\u0e34\u0e19\u0e32 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e32\u0e0b\u0e34\u0e25 \u0e42\u0e14\u0e22\u0e20\u0e32\u0e1e\u0e16\u0e48\u0e32\u0e22\u0e2b\u0e32\u0e22\u0e32\u0e01\u0e0a\u0e34\u0e49\u0e19\u0e19\u0e35\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e20\u0e32\u0e1e\u0e02\u0e2d\u0e07 Jag Santander&nbsp;<\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vce-row-container\" data-vce-boxed-width=\"true\"><div class=\"vce-row vce-row--col-gap-30 vce-row-equal-height vce-row-content--top\" id=\"el-38bde91c\" data-vce-do-apply=\"all el-38bde91c\"><div class=\"vce-row-content\" data-vce-element-content=\"true\"><div class=\"vce-col vce-col--md-auto vce-col--xs-1 vce-col--xs-last vce-col--xs-first vce-col--sm-last vce-col--sm-first vce-col--md-last vce-col--lg-last vce-col--xl-last vce-col--md-first vce-col--lg-first vce-col--xl-first\" id=\"el-608ffad6\"><div class=\"vce-col-inner\" data-vce-do-apply=\"border margin background  el-608ffad6\"><div class=\"vce-col-content\" data-vce-element-content=\"true\" data-vce-do-apply=\"padding el-608ffad6\"><div class=\"vce-single-image-container vce-single-image--align-left\"><div class=\"vce vce-single-image-wrapper\" id=\"el-48f1a218\" data-vce-do-apply=\"all el-48f1a218\"><figure><div class=\"vce-single-image-figure-inner\" style=\"width: 670px;\"><div class=\"vce-single-image-inner vce-single-image--absolute\" style=\"width: 100%; padding-bottom: 126.716%;\"><img loading=\"lazy\" decoding=\"async\" class=\"vce-single-image\"  width=\"670\" height=\"849\" src=\"https:\/\/storage-wp.naewna.com\/2026\/09\/104.jpg\" data-img-src=\"https:\/\/storage-wp.naewna.com\/2026\/09\/104.jpg\" data-attachment-id=\"39729\"  alt=\"\u0e19\u0e01\u0e40\u0e1b\u0e47\u0e14\u0e1c\u0e35\u0e2b\u0e07\u0e2d\u0e19\u0e02\u0e32\u0e27\" title=\"\u0e19\u0e01\u0e40\u0e1b\u0e47\u0e14\u0e1c\u0e35\u0e2b\u0e07\u0e2d\u0e19\u0e02\u0e32\u0e27\" \/><\/div><\/div><figcaption hidden=\"\"><\/figcaption><\/figure><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vce-row-container\" data-vce-boxed-width=\"true\"><div class=\"vce-row vce-row--col-gap-30 vce-row-equal-height vce-row-content--top\" id=\"el-8de023aa\" data-vce-do-apply=\"all el-8de023aa\"><div class=\"vce-row-content\" data-vce-element-content=\"true\"><div class=\"vce-col vce-col--md-auto vce-col--xs-1 vce-col--xs-last vce-col--xs-first vce-col--sm-last vce-col--sm-first vce-col--md-last vce-col--lg-last vce-col--xl-last vce-col--md-first vce-col--lg-first vce-col--xl-first\" id=\"el-67c1753b\"><div class=\"vce-col-inner\" data-vce-do-apply=\"border margin background  el-67c1753b\"><div class=\"vce-col-content\" data-vce-element-content=\"true\" data-vce-do-apply=\"padding el-67c1753b\"><div class=\"vce-text-block\"><div class=\"vce-text-block-wrapper vce\" id=\"el-446beb40\" data-vce-do-apply=\"all el-446beb40\"><p>\u0e42\u0e14\u0e22\u0e21\u0e31\u0e07\u0e07\u0e30\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e19\u0e32\u0e23\u0e39\u0e42\u0e15\u0e30 \u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e15\u0e33\u0e19\u0e32\u0e19\u0e02\u0e2d\u0e07 \u0e21\u0e32\u0e0b\u0e32\u0e0a\u0e34 \u0e04\u0e34\u0e0a\u0e34\u0e42\u0e21\u0e42\u0e15\u0e30 \u0e27\u0e48\u0e32\u0e14\u0e49\u0e27\u0e22\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e27\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e19\u0e34\u0e19\u0e08\u0e32 \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35\u0e01\u0e25\u0e38\u0e48\u0e21\u0e15\u0e31\u0e27\u0e25\u0e30\u0e04\u0e23\u0e43\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e42\u0e14\u0e14\u0e40\u0e14\u0e48\u0e19\u0e14\u0e49\u0e27\u0e22\u0e40\u0e2d\u0e01\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e17\u0e32\u0e07\u0e14\u0e27\u0e07\u0e15\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07 \u0e15\u0e23\u0e30\u0e01\u0e39\u0e25\u0e2d\u0e38\u0e08\u0e34\u0e27\u0e30 \u0e15\u0e23\u0e30\u0e01\u0e39\u0e25\u0e19\u0e34\u0e19\u0e08\u0e32\u0e1c\u0e39\u0e49\u0e17\u0e23\u0e07\u0e1e\u0e25\u0e31\u0e07\u0e41\u0e25\u0e30\u0e21\u0e35\u0e0a\u0e37\u0e48\u0e2d\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e43\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e40\u0e19\u0e15\u0e23\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e17\u0e35\u0e48\u0e40\u0e23\u0e35\u0e22\u0e01\u0e27\u0e48\u0e32 \u0e40\u0e19\u0e15\u0e23\u0e27\u0e07\u0e41\u0e2b\u0e27\u0e19 \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35\u0e25\u0e27\u0e14\u0e25\u0e32\u0e22\u0e41\u0e25\u0e30\u0e2a\u0e35\u0e41\u0e14\u0e07\u0e2d\u0e31\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e2d\u0e01\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e04\u0e25\u0e49\u0e32\u0e22\u0e01\u0e31\u0e1a\u0e14\u0e27\u0e07\u0e15\u0e32\u0e02\u0e2d\u0e07\u0e40\u0e08\u0e49\u0e32\u0e19\u0e01\u0e40\u0e1b\u0e47\u0e14\u0e1c\u0e35\u0e2b\u0e07\u0e2d\u0e19\u0e02\u0e32\u0e27\u0e15\u0e31\u0e27\u0e19\u0e35\u0e49 \u0e42\u0e14\u0e22\u0e15\u0e31\u0e27\u0e25\u0e30\u0e04\u0e23\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e08\u0e32\u0e01\u0e15\u0e23\u0e30\u0e01\u0e39\u0e25\u0e2d\u0e38\u0e08\u0e34\u0e27\u0e30\u0e17\u0e35\u0e48\u0e41\u0e1f\u0e19 \u0e46 \u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e01\u0e31\u0e19\u0e14\u0e35 \u0e40\u0e0a\u0e48\u0e19 \u0e2d\u0e38\u0e08\u0e34\u0e27\u0e30 \u0e2d\u0e34\u0e15\u0e32\u0e08\u0e34, \u0e2d\u0e38\u0e08\u0e34\u0e27\u0e30 \u0e0b\u0e32\u0e2a\u0e36\u0e40\u0e01\u0e30 \u0e41\u0e25\u0e30 \u0e2d\u0e38\u0e08\u0e34\u0e27\u0e30 \u0e21\u0e32\u0e14\u0e32\u0e23\u0e30<\/p>\n<p>\u0e41\u0e25\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e17\u0e35\u0e48\u0e20\u0e32\u0e1e\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e25\u0e07\u0e21\u0e32\u0e1a\u0e19 Reddit \u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e19\u0e32\u0e19 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e0a\u0e32\u0e27\u0e40\u0e19\u0e47\u0e15\u0e08\u0e33\u0e19\u0e27\u0e19\u0e21\u0e32\u0e01\u0e1e\u0e32\u0e01\u0e31\u0e19\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e41\u0e0b\u0e27\u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e02\u0e1a\u0e02\u0e31\u0e19\u0e27\u0e48\u0e32 \u0e21\u0e35\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e25\u0e30\u0e21\u0e49\u0e32\u0e22\u0e04\u0e25\u0e49\u0e32\u0e22\u0e04\u0e25\u0e36\u0e07\u0e01\u0e31\u0e1a \u0e40\u0e19\u0e15\u0e23\u0e27\u0e07\u0e41\u0e2b\u0e27\u0e19 \u0e02\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e25\u0e30\u0e04\u0e23\u0e15\u0e23\u0e30\u0e01\u0e39\u0e25\u0e2d\u0e38\u0e08\u0e34\u0e27\u0e30\u0e08\u0e32\u0e01\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e32\u0e23\u0e39\u0e42\u0e15\u0e30 \u0e08\u0e19\u0e1a\u0e32\u0e07\u0e04\u0e19\u0e2d\u0e14\u0e41\u0e0b\u0e27\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e27\u0e48\u0e32\u0e40\u0e08\u0e49\u0e32\u0e19\u0e01\u0e15\u0e31\u0e27\u0e19\u0e35\u0e49\u0e01\u0e33\u0e25\u0e31\u0e07\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e40\u0e1b\u0e34\u0e14\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e40\u0e19\u0e15\u0e23\u0e02\u0e31\u0e49\u0e19\u0e2a\u0e39\u0e07 \u0e02\u0e13\u0e30\u0e17\u0e35\u0e48\u0e2d\u0e35\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19\u0e23\u0e48\u0e27\u0e21\u0e41\u0e2a\u0e14\u0e07\u0e04\u0e27\u0e32\u0e21\u0e17\u0e36\u0e48\u0e07\u0e41\u0e25\u0e30\u0e0a\u0e37\u0e48\u0e19\u0e0a\u0e21\u0e43\u0e19\u0e04\u0e27\u0e32\u0e21\u0e21\u0e2b\u0e31\u0e28\u0e08\u0e23\u0e23\u0e22\u0e4c\u0e02\u0e2d\u0e07\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e17\u0e35\u0e48\u0e23\u0e31\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e07\u0e14\u0e07\u0e32\u0e21\u0e15\u0e23\u0e30\u0e01\u0e32\u0e23\u0e15\u0e32\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e19\u0e48\u0e32\u0e1b\u0e23\u0e30\u0e17\u0e31\u0e1a\u0e43\u0e08 \u0e40\u0e0a\u0e48\u0e19<\/p>\n<p><strong>\"\u0e40\u0e02\u0e32\u0e04\u0e37\u0e2d Juan Alonso Guti\u00e9rrez \u0e1a\u0e19 Instagram \u0e09\u0e31\u0e19\u0e02\u0e2d\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e40\u0e02\u0e32\u0e42\u0e1e\u0e2a\u0e15\u0e4c\u0e21\u0e31\u0e19\"<\/strong><\/p>\n<p><strong>\"55\"<\/strong><\/p>\n<p><strong>\"\u0e08\u0e48\u0e32\u0e01\u0e23\u0e35\u0e1a\u0e2a\u0e4c \u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e1d\u0e39\u0e07\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\u0e43\u0e2b\u0e49\u0e1e\u0e23\u0e49\u0e2d\u0e21\"<\/strong><\/p>\n<p><strong>\"\u0e40\u0e02\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e06\u0e48\u0e32\u0e04\u0e19\u0e43\u0e01\u0e25\u0e49\u0e0a\u0e34\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e15\u0e32\u0e21\u0e2d\u0e07\u0e19\u0e31\u0e48\u0e19\"<\/strong><\/p>\n<p><strong>\"\u0e2b\u0e21\u0e32\u0e22\u0e16\u0e36\u0e07 \u0e21\u0e31\u0e07\u0e40\u0e04\u0e35\u0e22\u0e27 \u0e0a\u0e32\u0e23\u0e34\u0e07\u0e01\u0e31\u0e19 \u0e43\u0e0a\u0e48\u0e44\u0e2b\u0e21? \u0e04\u0e34\u0e14\u0e27\u0e48\u0e32\u0e2d\u0e38\u0e08\u0e34\u0e27\u0e30\u0e17\u0e38\u0e01\u0e04\u0e19\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e0a\u0e32\u0e23\u0e34\u0e07\u0e01\u0e31\u0e19\u0e18\u0e23\u0e23\u0e21\u0e14\u0e32\u0e44\u0e14\u0e49 \u0e41\u0e15\u0e48\u0e01\u0e47\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32\u0e19\u0e32\u0e19\u0e41\u0e25\u0e49\u0e27\u0e17\u0e35\u0e48\u0e14\u0e39\u0e19\u0e32\u0e23\u0e39\u0e42\u0e15\u0e30\"<\/strong><\/p>\n<p><strong>\"\u0e01\u0e32\u0e23\u0e41\u0e0a\u0e23\u0e4c\u0e40\u0e23\u0e01\u0e39\u0e25\u0e32\u0e23\u0e4c\u0e41\u0e0a\u0e23\u0e4c\u0e23\u0e34\u0e07\u0e01\u0e47\u0e19\u0e31\u0e49\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e1a\u0e1a\u0e01\u0e23\u0e30\u0e15\u0e38\u0e49\u0e19\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e01\u0e31\u0e19\u0e19\u0e30 \u0e40\u0e04\u0e23\u0e35\u0e22\u0e14\u0e2a\u0e39\u0e07\u0e41\u0e25\u0e30\u0e1a\u0e32\u0e14\u0e41\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e08\u0e34\u0e15\u0e43\u0e08\"<\/strong><\/p>\n<p><strong>\"\u0e21\u0e31\u0e07\u0e40\u0e01\u0e01\u0e34\u0e42\u0e22\u0e30\u0e01\u0e47\u0e16\u0e39\u0e01\u0e01\u0e23\u0e30\u0e15\u0e38\u0e49\u0e19\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e01\u0e31\u0e19 \u0e41\u0e15\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e1c\u0e48\u0e32\u0e19\u0e42\u0e28\u0e01\u0e19\u0e32\u0e0f\u0e01\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e2a\u0e19\u0e34\u0e17\u0e2a\u0e19\u0e21\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32\"<\/strong><\/p>\n<p><strong>\"\u0e41\u0e0a\u0e23\u0e4c\u0e23\u0e34\u0e07\u0e01\u0e31\u0e19\u0e15\u0e49\u0e2d\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e02\u0e49\u0e32\u0e07\u0e1a\u0e19\u0e40\u0e25\u0e22 \u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e40\u0e2b\u0e23\u0e2d!\"<\/strong><\/p>\n<p><strong>\"\u0e09\u0e31\u0e19\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e27\u0e48\u0e32\u0e09\u0e31\u0e19\u0e40\u0e04\u0e22\u0e40\u0e2b\u0e47\u0e19\u0e21\u0e31\u0e19\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e19\"<\/strong><\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vce-row-container\" data-vce-boxed-width=\"true\"><div class=\"vce-row vce-row--col-gap-30 vce-row-equal-height vce-row-content--top\" id=\"el-cc251a4a\" data-vce-do-apply=\"all el-cc251a4a\"><div class=\"vce-row-content\" data-vce-element-content=\"true\"><div class=\"vce-col vce-col--md-auto vce-col--xs-1 vce-col--xs-last vce-col--xs-first vce-col--sm-last vce-col--sm-first vce-col--md-last vce-col--lg-last vce-col--xl-last vce-col--md-first vce-col--lg-first vce-col--xl-first\" id=\"el-756c970a\"><div class=\"vce-col-inner\" data-vce-do-apply=\"border margin background  el-756c970a\"><div class=\"vce-col-content\" data-vce-element-content=\"true\" data-vce-do-apply=\"padding el-756c970a\"><div class=\"vce-single-image-container vce-single-image--align-left\"><div class=\"vce vce-single-image-wrapper\" id=\"el-7417f734\" data-vce-do-apply=\"all el-7417f734\"><figure><div class=\"vce-single-image-figure-inner\" style=\"width: 600px;\"><div class=\"vce-single-image-inner vce-single-image--absolute\" style=\"width: 100%; padding-bottom: 110.167%;\"><img loading=\"lazy\" decoding=\"async\" class=\"vce-single-image\"  width=\"600\" height=\"661\" src=\"https:\/\/storage-wp.naewna.com\/2026\/09\/106-1.jpg\" data-img-src=\"https:\/\/storage-wp.naewna.com\/2026\/09\/106-1.jpg\" data-attachment-id=\"39749\"  alt=\"\u0e19\u0e01\u0e40\u0e1b\u0e47\u0e14\u0e1c\u0e35\u0e2b\u0e07\u0e2d\u0e19\u0e02\u0e32\u0e27\" title=\"\u0e19\u0e01\u0e40\u0e1b\u0e47\u0e14\u0e1c\u0e35\u0e2b\u0e07\u0e2d\u0e19\u0e02\u0e32\u0e27\" \/><\/div><\/div><figcaption hidden=\"\"><\/figcaption><\/figure><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vce-row-container\" data-vce-boxed-width=\"true\"><div class=\"vce-row vce-row--col-gap-30 vce-row-equal-height vce-row-content--top\" id=\"el-3d955e55\" data-vce-do-apply=\"all el-3d955e55\"><div class=\"vce-row-content\" data-vce-element-content=\"true\"><div class=\"vce-col vce-col--md-auto vce-col--xs-1 vce-col--xs-last vce-col--xs-first vce-col--sm-last vce-col--sm-first vce-col--md-last vce-col--lg-last vce-col--xl-last vce-col--md-first vce-col--lg-first vce-col--xl-first\" id=\"el-e0f3c917\"><div class=\"vce-col-inner\" data-vce-do-apply=\"border margin background  el-e0f3c917\"><div class=\"vce-col-content\" data-vce-element-content=\"true\" data-vce-do-apply=\"padding el-e0f3c917\"><div class=\"vce-single-image-container vce-single-image--align-left\"><div class=\"vce vce-single-image-wrapper\" id=\"el-4dd55c98\" data-vce-do-apply=\"all el-4dd55c98\"><figure><div class=\"vce-single-image-figure-inner\" style=\"width: 600px;\"><div class=\"vce-single-image-inner vce-single-image--absolute\" style=\"width: 100%; padding-bottom: 117.167%;\"><img loading=\"lazy\" decoding=\"async\" class=\"vce-single-image\"  width=\"600\" height=\"703\" src=\"https:\/\/storage-wp.naewna.com\/2026\/09\/107-1.jpg\" data-img-src=\"https:\/\/storage-wp.naewna.com\/2026\/09\/107-1.jpg\" data-attachment-id=\"39750\"  alt=\"\u0e19\u0e01\u0e40\u0e1b\u0e47\u0e14\u0e1c\u0e35\u0e2b\u0e07\u0e2d\u0e19\u0e02\u0e32\u0e27\" title=\"\u0e19\u0e01\u0e40\u0e1b\u0e47\u0e14\u0e1c\u0e35\u0e2b\u0e07\u0e2d\u0e19\u0e02\u0e32\u0e27\" \/><\/div><\/div><figcaption hidden=\"\"><\/figcaption><\/figure><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vce-row-container\" data-vce-boxed-width=\"true\"><div class=\"vce-row vce-row--col-gap-30 vce-row-equal-height vce-row-content--top\" id=\"el-41442fbd\" data-vce-do-apply=\"all el-41442fbd\"><div class=\"vce-row-content\" data-vce-element-content=\"true\"><div class=\"vce-col vce-col--md-auto vce-col--xs-1 vce-col--xs-last vce-col--xs-first vce-col--sm-last vce-col--sm-first vce-col--md-last vce-col--lg-last vce-col--xl-last vce-col--md-first vce-col--lg-first vce-col--xl-first\" id=\"el-e28dc999\"><div class=\"vce-col-inner\" data-vce-do-apply=\"border margin background  el-e28dc999\"><div class=\"vce-col-content\" data-vce-element-content=\"true\" data-vce-do-apply=\"padding el-e28dc999\"><div class=\"vce-single-image-container vce-single-image--align-left\"><div class=\"vce vce-single-image-wrapper\" id=\"el-a188ee34\" data-vce-do-apply=\"all el-a188ee34\"><figure><div class=\"vce-single-image-figure-inner\" style=\"width: 600px;\"><div class=\"vce-single-image-inner vce-single-image--absolute\" style=\"width: 100%; padding-bottom: 107.833%;\"><img loading=\"lazy\" decoding=\"async\" class=\"vce-single-image\"  width=\"600\" height=\"647\" src=\"https:\/\/storage-wp.naewna.com\/2026\/09\/108-1.jpg\" data-img-src=\"https:\/\/storage-wp.naewna.com\/2026\/09\/108-1.jpg\" data-attachment-id=\"39751\"  alt=\"\u0e19\u0e01\u0e40\u0e1b\u0e47\u0e14\u0e1c\u0e35\u0e2b\u0e07\u0e2d\u0e19\u0e02\u0e32\u0e27\" title=\"\u0e19\u0e01\u0e40\u0e1b\u0e47\u0e14\u0e1c\u0e35\u0e2b\u0e07\u0e2d\u0e19\u0e02\u0e32\u0e27\" \/><\/div><\/div><figcaption hidden=\"\"><\/figcaption><\/figure><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vce-row-container\" data-vce-boxed-width=\"true\"><div class=\"vce-row vce-row--col-gap-30 vce-row-equal-height vce-row-content--top\" id=\"el-53b6a1fe\" data-vce-do-apply=\"all el-53b6a1fe\"><div class=\"vce-row-content\" data-vce-element-content=\"true\"><div class=\"vce-col vce-col--md-auto vce-col--xs-1 vce-col--xs-last vce-col--xs-first vce-col--sm-last vce-col--sm-first vce-col--md-last vce-col--lg-last vce-col--xl-last vce-col--md-first vce-col--lg-first vce-col--xl-first\" id=\"el-8f10ff18\"><div class=\"vce-col-inner\" data-vce-do-apply=\"border margin background  el-8f10ff18\"><div class=\"vce-col-content\" data-vce-element-content=\"true\" data-vce-do-apply=\"padding el-8f10ff18\"><div class=\"vce-single-image-container vce-single-image--align-left\"><div class=\"vce vce-single-image-wrapper\" id=\"el-a838fdfa\" data-vce-do-apply=\"all el-a838fdfa\"><figure><div class=\"vce-single-image-figure-inner\" style=\"width: 815px;\"><div class=\"vce-single-image-inner vce-single-image--absolute\" style=\"width: 100%; padding-bottom: 86.6258%;\"><img loading=\"lazy\" decoding=\"async\" class=\"vce-single-image\"  width=\"815\" height=\"706\" src=\"https:\/\/storage-wp.naewna.com\/2026\/09\/105.jpg\" data-img-src=\"https:\/\/storage-wp.naewna.com\/2026\/09\/105.jpg\" data-attachment-id=\"39745\"  alt=\"\u0e19\u0e01\u0e40\u0e1b\u0e47\u0e14\u0e1c\u0e35\u0e2b\u0e07\u0e2d\u0e19\u0e02\u0e32\u0e27\" title=\"\u0e19\u0e01\u0e40\u0e1b\u0e47\u0e14\u0e1c\u0e35\u0e2b\u0e07\u0e2d\u0e19\u0e02\u0e32\u0e27\" \/><\/div><\/div><figcaption hidden=\"\"><\/figcaption><\/figure><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vce-row-container\" data-vce-boxed-width=\"true\"><div class=\"vce-row vce-row--col-gap-30 vce-row-equal-height vce-row-content--top\" id=\"el-5fd0a1dd\" data-vce-do-apply=\"all el-5fd0a1dd\"><div class=\"vce-row-content\" data-vce-element-content=\"true\"><div class=\"vce-col vce-col--md-auto vce-col--xs-1 vce-col--xs-last vce-col--xs-first vce-col--sm-last vce-col--sm-first vce-col--md-last vce-col--lg-last vce-col--xl-last vce-col--md-first vce-col--lg-first vce-col--xl-first\" id=\"el-2cc6bd56\"><div class=\"vce-col-inner\" data-vce-do-apply=\"border margin background  el-2cc6bd56\"><div class=\"vce-col-content\" data-vce-element-content=\"true\" data-vce-do-apply=\"padding el-2cc6bd56\"><div class=\"vce-single-image-container vce-single-image--align-left\"><div class=\"vce vce-single-image-wrapper\" id=\"el-a4559d60\" data-vce-do-apply=\"all el-a4559d60\"><figure><div class=\"vce-single-image-figure-inner\" style=\"width: 678px;\"><div class=\"vce-single-image-inner vce-single-image--absolute\" style=\"width: 100%; padding-bottom: 127.286%;\"><img loading=\"lazy\" decoding=\"async\" class=\"vce-single-image\"  width=\"678\" height=\"863\" src=\"https:\/\/storage-wp.naewna.com\/2026\/09\/103.jpg\" data-img-src=\"https:\/\/storage-wp.naewna.com\/2026\/09\/103.jpg\" data-attachment-id=\"39728\"  alt=\"\u0e19\u0e01\u0e40\u0e1b\u0e47\u0e14\u0e1c\u0e35\u0e2b\u0e07\u0e2d\u0e19\u0e02\u0e32\u0e27\" title=\"\u0e19\u0e01\u0e40\u0e1b\u0e47\u0e14\u0e1c\u0e35\u0e2b\u0e07\u0e2d\u0e19\u0e02\u0e32\u0e27\" \/><\/div><\/div><figcaption hidden=\"\"><\/figcaption><\/figure><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vce-row-container\" data-vce-boxed-width=\"true\"><div class=\"vce-row vce-row--col-gap-30 vce-row-equal-height vce-row-content--top\" id=\"el-9d90e711\" data-vce-do-apply=\"all el-9d90e711\"><div class=\"vce-row-content\" data-vce-element-content=\"true\"><div class=\"vce-col vce-col--md-auto vce-col--xs-1 vce-col--xs-last vce-col--xs-first vce-col--sm-last vce-col--sm-first vce-col--md-last vce-col--lg-last vce-col--xl-last vce-col--md-first vce-col--lg-first vce-col--xl-first\" id=\"el-f5227e4e\"><div class=\"vce-col-inner\" data-vce-do-apply=\"border margin background  el-f5227e4e\"><div class=\"vce-col-content\" data-vce-element-content=\"true\" data-vce-do-apply=\"padding el-f5227e4e\"><div class=\"vce-single-image-container vce-single-image--align-left\"><div class=\"vce vce-single-image-wrapper\" id=\"el-394f39a6\" data-vce-do-apply=\"all el-394f39a6\"><figure><div class=\"vce-single-image-figure-inner\" style=\"width: 675px;\"><div class=\"vce-single-image-inner vce-single-image--absolute\" style=\"width: 100%; padding-bottom: 125.185%;\"><img loading=\"lazy\" decoding=\"async\" class=\"vce-single-image\"  width=\"675\" height=\"845\" src=\"https:\/\/storage-wp.naewna.com\/2026\/09\/102.jpg\" data-img-src=\"https:\/\/storage-wp.naewna.com\/2026\/09\/102.jpg\" data-attachment-id=\"39727\"  alt=\"\u0e19\u0e01\u0e40\u0e1b\u0e47\u0e14\u0e1c\u0e35\u0e2b\u0e07\u0e2d\u0e19\u0e02\u0e32\u0e27\" title=\"\u0e19\u0e01\u0e40\u0e1b\u0e47\u0e14\u0e1c\u0e35\u0e2b\u0e07\u0e2d\u0e19\u0e02\u0e32\u0e27\" \/><\/div><\/div><figcaption hidden=\"\"><\/figcaption><\/figure><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vce-row-container\" data-vce-boxed-width=\"true\"><div class=\"vce-row vce-row--col-gap-30 vce-row-equal-height vce-row-content--top\" id=\"el-13feaa01\" data-vce-do-apply=\"all el-13feaa01\"><div class=\"vce-row-content\" data-vce-element-content=\"true\"><div class=\"vce-col vce-col--md-auto vce-col--xs-1 vce-col--xs-last vce-col--xs-first vce-col--sm-last vce-col--sm-first vce-col--md-last vce-col--lg-last vce-col--xl-last vce-col--md-first vce-col--lg-first vce-col--xl-first\" id=\"el-6afa21c2\"><div class=\"vce-col-inner\" data-vce-do-apply=\"border margin background  el-6afa21c2\"><div class=\"vce-col-content\" data-vce-element-content=\"true\" data-vce-do-apply=\"padding el-6afa21c2\"><div class=\"vce-image-gallery vce-image-gallery--gap-10 vce-image-gallery--columns-3\"><div class=\"vce-image-gallery-wrapper vce\" id=\"el-77794db3\" data-vce-do-apply=\"all el-77794db3\"><div class=\"vce-image-gallery-list\"><div class=\"vce-image-gallery-item\"><figure class=\"vce-image-gallery-item-inner-wrapper\"><a href=\"https:\/\/storage-wp.naewna.com\/2026\/09\/100.jpg\" data-lightbox=\"lightbox-77794db3\" class=\"vce-image-gallery-item-inner\"><img decoding=\"async\" class=\"vce-image-gallery-img vce-image-gallery-img--orientation-portrait\" src=\"https:\/\/storage-wp.naewna.com\/2026\/09\/100.jpg\" alt=\"\u0e19\u0e01\u0e40\u0e1b\u0e47\u0e14\u0e1c\u0e35\u0e2b\u0e07\u0e2d\u0e19\u0e02\u0e32\u0e27\" title=\"\u0e19\u0e01\u0e40\u0e1b\u0e47\u0e14\u0e1c\u0e35\u0e2b\u0e07\u0e2d\u0e19\u0e02\u0e32\u0e27\"><\/a><\/figure><\/div><div class=\"vce-image-gallery-item\"><figure class=\"vce-image-gallery-item-inner-wrapper\"><a href=\"https:\/\/storage-wp.naewna.com\/2026\/09\/101.jpg\" data-lightbox=\"lightbox-77794db3\" class=\"vce-image-gallery-item-inner\"><img decoding=\"async\" class=\"vce-image-gallery-img vce-image-gallery-img--orientation-portrait\" src=\"https:\/\/storage-wp.naewna.com\/2026\/09\/101.jpg\" alt=\"\u0e19\u0e01\u0e40\u0e1b\u0e47\u0e14\u0e1c\u0e35\u0e2b\u0e07\u0e2d\u0e19\u0e02\u0e32\u0e27\" title=\"\u0e19\u0e01\u0e40\u0e1b\u0e47\u0e14\u0e1c\u0e35\u0e2b\u0e07\u0e2d\u0e19\u0e02\u0e32\u0e27\"><\/a><\/figure><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vce-row-container\" data-vce-boxed-width=\"true\"><div class=\"vce-row vce-row--col-gap-30 vce-row-equal-height vce-row-content--top\" id=\"el-5ed9be44\" data-vce-do-apply=\"all el-5ed9be44\"><div class=\"vce-row-content\" data-vce-element-content=\"true\"><div class=\"vce-col vce-col--md-auto vce-col--xs-1 vce-col--xs-last vce-col--xs-first vce-col--sm-last vce-col--sm-first vce-col--md-last vce-col--lg-last vce-col--xl-last vce-col--md-first vce-col--lg-first vce-col--xl-first\" id=\"el-83f827e8\"><div class=\"vce-col-inner\" data-vce-do-apply=\"border margin background  el-83f827e8\"><div class=\"vce-col-content\" data-vce-element-content=\"true\" data-vce-do-apply=\"padding el-83f827e8\"><div class=\"vce-text-block\"><div class=\"vce-text-block-wrapper vce\" id=\"el-a97a70fa\" data-vce-do-apply=\"all el-a97a70fa\"><blockquote class=\"instagram-media\" style=\"background: #FFF; border: 0; border-radius: 3px; box-shadow: 0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width: 540px; min-width: 326px; padding: 0; width: calc(100% - 2px);\" data-instgrm-captioned=\"\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/DaUCqSajL2k\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\">\n<div style=\"padding: 16px;\">\n<div style=\"display: flex; flex-direction: row; align-items: center;\">\n<div style=\"background-color: #f4f4f4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\">&nbsp;<\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\">\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\">&nbsp;<\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\">&nbsp;<\/div>\n<\/div>\n<\/div>\n<div style=\"padding: 19% 0;\">&nbsp;<\/div>\n<div style=\"display: block; height: 50px; margin: 0 auto 12px; width: 50px;\">&nbsp;<\/div>\n<div style=\"padding-top: 8px;\">\n<div style=\"color: #3897f0; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: 550; line-height: 18px;\">\u0e14\u0e39\u0e42\u0e1e\u0e2a\u0e15\u0e4c\u0e19\u0e35\u0e49\u0e1a\u0e19 Instagram<\/div>\n<\/div>\n<div style=\"padding: 12.5% 0;\">&nbsp;<\/div>\n<div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\">\n<div>\n<div style=\"background-color: #f4f4f4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\">&nbsp;<\/div>\n<div style=\"background-color: #f4f4f4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\">&nbsp;<\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\">&nbsp;<\/div>\n<\/div>\n<div style=\"margin-left: 8px;\">\n<div style=\"background-color: #f4f4f4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\">&nbsp;<\/div>\n<div style=\"width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg);\">&nbsp;<\/div>\n<\/div>\n<div style=\"margin-left: auto;\">\n<div style=\"width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\">&nbsp;<\/div>\n<div style=\"background-color: #f4f4f4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\">&nbsp;<\/div>\n<div style=\"width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\">&nbsp;<\/div>\n<\/div>\n<\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\">\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\">&nbsp;<\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\">&nbsp;<\/div>\n<\/div>\n<p style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; line-height: 17px; margin-bottom: 0; margin-top: 8px; overflow: hidden; padding: 8px 0 7px; text-align: center; text-overflow: ellipsis; white-space: nowrap;\"><a style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: normal; line-height: 17px; text-decoration: none;\" href=\"https:\/\/www.instagram.com\/p\/DaUCqSajL2k\/?utm_source=ig_embed&amp;utm_campaign=loading\" target=\"_blank\" rel=\"noopener\">\u0e42\u0e1e\u0e2a\u0e15\u0e4c\u0e17\u0e35\u0e48\u0e41\u0e0a\u0e23\u0e4c\u0e42\u0e14\u0e22 Juan Alonso Guti\u00e9rrez (@jagsantander)<\/a><\/p>\n<\/div>\n<\/blockquote>\n<p><script async=\"\" src=\"\/\/www.instagram.com\/embed.js\"><\/script><\/p>\n<p>&nbsp;<\/p>\n<p>\u0e02\u0e2d\u0e02\u0e2d\u0e1a\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e08\u0e32\u0e01 \u0e2d\u0e34\u0e19\u0e2a\u0e15\u0e32\u0e41\u0e01\u0e23\u0e21 jagsantander,reddit.com<\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 31 \u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21 2569 \u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e01\u0e31\u0e19\u0e2e\u0e37\u0e2d\u0e2e\u0e32\u0e01\u0e31\u0e19\u0e1a\u0e19\u0e42\u0e25\u0e01 [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":39797,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[241,16,342],"tags":[2767,6105,6104,6106,5736],"class_list":["post-39692","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking","category-like-learn","category-social-n-share-news","tag-2767","tag-6105","tag-6104","tag-6106","tag-5736"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u0e42\u0e0b\u0e40\u0e0a\u0e35\u0e22\u0e25\u0e2e\u0e37\u0e2d\u0e2e\u0e32 \u0e21\u0e2b\u0e31\u0e28\u0e08\u0e23\u0e23\u0e22\u0e4c\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 \u0e19\u0e01\u0e08\u0e23\u0e34\u0e07 \u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48 AI \u0e0a\u0e32\u0e27\u0e40\u0e19\u0e47\u0e15\u0e41\u0e2b\u0e48\u0e41\u0e0b\u0e27\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e15\u0e31\u0e27\u0e25\u0e30\u0e04\u0e23\u0e21\u0e31\u0e07\u0e07\u0e30\u0e0a\u0e37\u0e48\u0e2d\u0e14\u0e31\u0e07 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.naewna.com\/n\/like-learn\/39692\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e42\u0e0b\u0e40\u0e0a\u0e35\u0e22\u0e25\u0e2e\u0e37\u0e2d\u0e2e\u0e32 \u0e21\u0e2b\u0e31\u0e28\u0e08\u0e23\u0e23\u0e22\u0e4c\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 \u0e19\u0e01\u0e08\u0e23\u0e34\u0e07 \u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48 AI \u0e0a\u0e32\u0e27\u0e40\u0e19\u0e47\u0e15\u0e41\u0e2b\u0e48\u0e41\u0e0b\u0e27\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e15\u0e31\u0e27\u0e25\u0e30\u0e04\u0e23\u0e21\u0e31\u0e07\u0e07\u0e30\u0e0a\u0e37\u0e48\u0e2d\u0e14\u0e31\u0e07\" \/>\n<meta property=\"og:description\" content=\"\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 31 \u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21 2569 \u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e01\u0e31\u0e19\u0e2e\u0e37\u0e2d\u0e2e\u0e32\u0e01\u0e31\u0e19\u0e1a\u0e19\u0e42\u0e25\u0e01 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.naewna.com\/n\/like-learn\/39692\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NaewnaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2026-09-02T10:46:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-02T10:51:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/storage-wp.naewna.com\/2026\/09\/%E0%B8%95%E0%B9%89%E0%B8%99%E0%B9%81%E0%B8%9A%E0%B8%9A-7.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"607\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"\u0e2a\u0e38\u0e23\u0e31\u0e0a (\u0e41\u0e21\u0e47\u0e04) \u0e1e\u0e34\u0e21\u0e43\u0e08\u0e43\u0e2a\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@naewna_news\" \/>\n<meta name=\"twitter:site\" content=\"@naewna_news\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u0e2a\u0e38\u0e23\u0e31\u0e0a (\u0e41\u0e21\u0e47\u0e04) \u0e1e\u0e34\u0e21\u0e43\u0e08\u0e43\u0e2a\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/like-learn\\\/39692\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/like-learn\\\/39692\\\/\"},\"author\":{\"name\":\"\u0e2a\u0e38\u0e23\u0e31\u0e0a (\u0e41\u0e21\u0e47\u0e04) \u0e1e\u0e34\u0e21\u0e43\u0e08\u0e43\u0e2a\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#\\\/schema\\\/person\\\/f8879586f5c1fd64b3b8854b6c19f0bf\"},\"headline\":\"\u0e42\u0e0b\u0e40\u0e0a\u0e35\u0e22\u0e25\u0e2e\u0e37\u0e2d\u0e2e\u0e32 \u0e21\u0e2b\u0e31\u0e28\u0e08\u0e23\u0e23\u0e22\u0e4c\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 \u0e19\u0e01\u0e08\u0e23\u0e34\u0e07 \u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48 AI \u0e0a\u0e32\u0e27\u0e40\u0e19\u0e47\u0e15\u0e41\u0e2b\u0e48\u0e41\u0e0b\u0e27\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e15\u0e31\u0e27\u0e25\u0e30\u0e04\u0e23\u0e21\u0e31\u0e07\u0e07\u0e30\u0e0a\u0e37\u0e48\u0e2d\u0e14\u0e31\u0e07\",\"datePublished\":\"2026-09-02T10:46:23+00:00\",\"dateModified\":\"2026-09-02T10:51:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/like-learn\\\/39692\\\/\"},\"wordCount\":40,\"image\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/like-learn\\\/39692\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/storage-wp.naewna.com\\\/2026\\\/09\\\/\u0e15\u0e49\u0e19\u0e41\u0e1a\u0e1a-7.jpg\",\"keywords\":[\"\u0e14\u0e27\u0e07\u0e15\u0e32\",\"\u0e19\u0e01\",\"\u0e19\u0e01\u0e40\u0e1b\u0e47\u0e14\u0e1c\u0e35\u0e2b\u0e07\u0e2d\u0e19\u0e02\u0e32\u0e27\",\"\u0e20\u0e32\u0e1e\u0e44\u0e27\u0e23\u0e31\u0e25\",\"\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1b\u0e48\u0e32\"],\"articleSection\":[\"Breaking News\",\"Like \u0e2a\u0e32\u0e23\u0e30\",\"Social &amp; share\"],\"inLanguage\":\"th\",\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/like-learn\\\/39692\\\/\",\"url\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/like-learn\\\/39692\\\/\",\"name\":\"\u0e42\u0e0b\u0e40\u0e0a\u0e35\u0e22\u0e25\u0e2e\u0e37\u0e2d\u0e2e\u0e32 \u0e21\u0e2b\u0e31\u0e28\u0e08\u0e23\u0e23\u0e22\u0e4c\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 \u0e19\u0e01\u0e08\u0e23\u0e34\u0e07 \u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48 AI \u0e0a\u0e32\u0e27\u0e40\u0e19\u0e47\u0e15\u0e41\u0e2b\u0e48\u0e41\u0e0b\u0e27\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e15\u0e31\u0e27\u0e25\u0e30\u0e04\u0e23\u0e21\u0e31\u0e07\u0e07\u0e30\u0e0a\u0e37\u0e48\u0e2d\u0e14\u0e31\u0e07 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/like-learn\\\/39692\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/like-learn\\\/39692\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/storage-wp.naewna.com\\\/2026\\\/09\\\/\u0e15\u0e49\u0e19\u0e41\u0e1a\u0e1a-7.jpg\",\"datePublished\":\"2026-09-02T10:46:23+00:00\",\"dateModified\":\"2026-09-02T10:51:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#\\\/schema\\\/person\\\/f8879586f5c1fd64b3b8854b6c19f0bf\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/like-learn\\\/39692\\\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.naewna.com\\\/n\\\/like-learn\\\/39692\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/like-learn\\\/39692\\\/#primaryimage\",\"url\":\"https:\\\/\\\/storage-wp.naewna.com\\\/2026\\\/09\\\/\u0e15\u0e49\u0e19\u0e41\u0e1a\u0e1a-7.jpg\",\"contentUrl\":\"https:\\\/\\\/storage-wp.naewna.com\\\/2026\\\/09\\\/\u0e15\u0e49\u0e19\u0e41\u0e1a\u0e1a-7.jpg\",\"width\":1080,\"height\":607,\"caption\":\"\u0e19\u0e01\u0e40\u0e1b\u0e47\u0e14\u0e1c\u0e35\u0e2b\u0e07\u0e2d\u0e19\u0e02\u0e32\u0e27\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/like-learn\\\/39692\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e42\u0e0b\u0e40\u0e0a\u0e35\u0e22\u0e25\u0e2e\u0e37\u0e2d\u0e2e\u0e32 \u0e21\u0e2b\u0e31\u0e28\u0e08\u0e23\u0e23\u0e22\u0e4c\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 \u0e19\u0e01\u0e08\u0e23\u0e34\u0e07 \u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48 AI \u0e0a\u0e32\u0e27\u0e40\u0e19\u0e47\u0e15\u0e41\u0e2b\u0e48\u0e41\u0e0b\u0e27\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e15\u0e31\u0e27\u0e25\u0e30\u0e04\u0e23\u0e21\u0e31\u0e07\u0e07\u0e30\u0e0a\u0e37\u0e48\u0e2d\u0e14\u0e31\u0e07\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#website\",\"url\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/\",\"name\":\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#\\\/schema\\\/person\\\/f8879586f5c1fd64b3b8854b6c19f0bf\",\"name\":\"\u0e2a\u0e38\u0e23\u0e31\u0e0a (\u0e41\u0e21\u0e47\u0e04) \u0e1e\u0e34\u0e21\u0e43\u0e08\u0e43\u0e2a\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/baca03c08e42acabe4e38e3821f997afc3e0581bf23f5829f09a5405e86d29a8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/baca03c08e42acabe4e38e3821f997afc3e0581bf23f5829f09a5405e86d29a8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/baca03c08e42acabe4e38e3821f997afc3e0581bf23f5829f09a5405e86d29a8?s=96&d=mm&r=g\",\"caption\":\"\u0e2a\u0e38\u0e23\u0e31\u0e0a (\u0e41\u0e21\u0e47\u0e04) \u0e1e\u0e34\u0e21\u0e43\u0e08\u0e43\u0e2a\"},\"url\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/author\\\/pafrank\\\/\"}]}<\/script>\n<meta property=\"article:section\" content=\"Breaking News\" \/>\n<meta property=\"article:section\" content=\"Like \u0e2a\u0e32\u0e23\u0e30\" \/>\n<meta property=\"article:section\" content=\"Social &amp; share\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u0e42\u0e0b\u0e40\u0e0a\u0e35\u0e22\u0e25\u0e2e\u0e37\u0e2d\u0e2e\u0e32 \u0e21\u0e2b\u0e31\u0e28\u0e08\u0e23\u0e23\u0e22\u0e4c\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 \u0e19\u0e01\u0e08\u0e23\u0e34\u0e07 \u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48 AI \u0e0a\u0e32\u0e27\u0e40\u0e19\u0e47\u0e15\u0e41\u0e2b\u0e48\u0e41\u0e0b\u0e27\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e15\u0e31\u0e27\u0e25\u0e30\u0e04\u0e23\u0e21\u0e31\u0e07\u0e07\u0e30\u0e0a\u0e37\u0e48\u0e2d\u0e14\u0e31\u0e07 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.naewna.com\/n\/like-learn\/39692\/","og_locale":"th_TH","og_type":"article","og_title":"\u0e42\u0e0b\u0e40\u0e0a\u0e35\u0e22\u0e25\u0e2e\u0e37\u0e2d\u0e2e\u0e32 \u0e21\u0e2b\u0e31\u0e28\u0e08\u0e23\u0e23\u0e22\u0e4c\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 \u0e19\u0e01\u0e08\u0e23\u0e34\u0e07 \u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48 AI \u0e0a\u0e32\u0e27\u0e40\u0e19\u0e47\u0e15\u0e41\u0e2b\u0e48\u0e41\u0e0b\u0e27\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e15\u0e31\u0e27\u0e25\u0e30\u0e04\u0e23\u0e21\u0e31\u0e07\u0e07\u0e30\u0e0a\u0e37\u0e48\u0e2d\u0e14\u0e31\u0e07","og_description":"\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 31 \u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21 2569 \u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e01\u0e31\u0e19\u0e2e\u0e37\u0e2d\u0e2e\u0e32\u0e01\u0e31\u0e19\u0e1a\u0e19\u0e42\u0e25\u0e01 [&hellip;]","og_url":"https:\/\/www.naewna.com\/n\/like-learn\/39692\/","og_site_name":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32","article_publisher":"https:\/\/www.facebook.com\/NaewnaOnline","article_published_time":"2026-09-02T10:46:23+00:00","article_modified_time":"2026-09-02T10:51:40+00:00","og_image":[{"width":1080,"height":607,"url":"https:\/\/storage-wp.naewna.com\/2026\/09\/%E0%B8%95%E0%B9%89%E0%B8%99%E0%B9%81%E0%B8%9A%E0%B8%9A-7.jpg","type":"image\/jpeg"}],"author":"\u0e2a\u0e38\u0e23\u0e31\u0e0a (\u0e41\u0e21\u0e47\u0e04) \u0e1e\u0e34\u0e21\u0e43\u0e08\u0e43\u0e2a","twitter_card":"summary_large_image","twitter_creator":"@naewna_news","twitter_site":"@naewna_news","twitter_misc":{"Written by":"\u0e2a\u0e38\u0e23\u0e31\u0e0a (\u0e41\u0e21\u0e47\u0e04) \u0e1e\u0e34\u0e21\u0e43\u0e08\u0e43\u0e2a"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.naewna.com\/n\/like-learn\/39692\/#article","isPartOf":{"@id":"https:\/\/www.naewna.com\/n\/like-learn\/39692\/"},"author":{"name":"\u0e2a\u0e38\u0e23\u0e31\u0e0a (\u0e41\u0e21\u0e47\u0e04) \u0e1e\u0e34\u0e21\u0e43\u0e08\u0e43\u0e2a","@id":"https:\/\/www.naewna.com\/n\/#\/schema\/person\/f8879586f5c1fd64b3b8854b6c19f0bf"},"headline":"\u0e42\u0e0b\u0e40\u0e0a\u0e35\u0e22\u0e25\u0e2e\u0e37\u0e2d\u0e2e\u0e32 \u0e21\u0e2b\u0e31\u0e28\u0e08\u0e23\u0e23\u0e22\u0e4c\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 \u0e19\u0e01\u0e08\u0e23\u0e34\u0e07 \u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48 AI \u0e0a\u0e32\u0e27\u0e40\u0e19\u0e47\u0e15\u0e41\u0e2b\u0e48\u0e41\u0e0b\u0e27\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e15\u0e31\u0e27\u0e25\u0e30\u0e04\u0e23\u0e21\u0e31\u0e07\u0e07\u0e30\u0e0a\u0e37\u0e48\u0e2d\u0e14\u0e31\u0e07","datePublished":"2026-09-02T10:46:23+00:00","dateModified":"2026-09-02T10:51:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.naewna.com\/n\/like-learn\/39692\/"},"wordCount":40,"image":{"@id":"https:\/\/www.naewna.com\/n\/like-learn\/39692\/#primaryimage"},"thumbnailUrl":"https:\/\/storage-wp.naewna.com\/2026\/09\/\u0e15\u0e49\u0e19\u0e41\u0e1a\u0e1a-7.jpg","keywords":["\u0e14\u0e27\u0e07\u0e15\u0e32","\u0e19\u0e01","\u0e19\u0e01\u0e40\u0e1b\u0e47\u0e14\u0e1c\u0e35\u0e2b\u0e07\u0e2d\u0e19\u0e02\u0e32\u0e27","\u0e20\u0e32\u0e1e\u0e44\u0e27\u0e23\u0e31\u0e25","\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1b\u0e48\u0e32"],"articleSection":["Breaking News","Like \u0e2a\u0e32\u0e23\u0e30","Social &amp; share"],"inLanguage":"th","copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/www.naewna.com\/n\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.naewna.com\/n\/like-learn\/39692\/","url":"https:\/\/www.naewna.com\/n\/like-learn\/39692\/","name":"\u0e42\u0e0b\u0e40\u0e0a\u0e35\u0e22\u0e25\u0e2e\u0e37\u0e2d\u0e2e\u0e32 \u0e21\u0e2b\u0e31\u0e28\u0e08\u0e23\u0e23\u0e22\u0e4c\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 \u0e19\u0e01\u0e08\u0e23\u0e34\u0e07 \u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48 AI \u0e0a\u0e32\u0e27\u0e40\u0e19\u0e47\u0e15\u0e41\u0e2b\u0e48\u0e41\u0e0b\u0e27\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e15\u0e31\u0e27\u0e25\u0e30\u0e04\u0e23\u0e21\u0e31\u0e07\u0e07\u0e30\u0e0a\u0e37\u0e48\u0e2d\u0e14\u0e31\u0e07 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32","isPartOf":{"@id":"https:\/\/www.naewna.com\/n\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.naewna.com\/n\/like-learn\/39692\/#primaryimage"},"image":{"@id":"https:\/\/www.naewna.com\/n\/like-learn\/39692\/#primaryimage"},"thumbnailUrl":"https:\/\/storage-wp.naewna.com\/2026\/09\/\u0e15\u0e49\u0e19\u0e41\u0e1a\u0e1a-7.jpg","datePublished":"2026-09-02T10:46:23+00:00","dateModified":"2026-09-02T10:51:40+00:00","author":{"@id":"https:\/\/www.naewna.com\/n\/#\/schema\/person\/f8879586f5c1fd64b3b8854b6c19f0bf"},"breadcrumb":{"@id":"https:\/\/www.naewna.com\/n\/like-learn\/39692\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.naewna.com\/n\/like-learn\/39692\/"]}]},{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.naewna.com\/n\/like-learn\/39692\/#primaryimage","url":"https:\/\/storage-wp.naewna.com\/2026\/09\/\u0e15\u0e49\u0e19\u0e41\u0e1a\u0e1a-7.jpg","contentUrl":"https:\/\/storage-wp.naewna.com\/2026\/09\/\u0e15\u0e49\u0e19\u0e41\u0e1a\u0e1a-7.jpg","width":1080,"height":607,"caption":"\u0e19\u0e01\u0e40\u0e1b\u0e47\u0e14\u0e1c\u0e35\u0e2b\u0e07\u0e2d\u0e19\u0e02\u0e32\u0e27"},{"@type":"BreadcrumbList","@id":"https:\/\/www.naewna.com\/n\/like-learn\/39692\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.naewna.com\/n\/"},{"@type":"ListItem","position":2,"name":"\u0e42\u0e0b\u0e40\u0e0a\u0e35\u0e22\u0e25\u0e2e\u0e37\u0e2d\u0e2e\u0e32 \u0e21\u0e2b\u0e31\u0e28\u0e08\u0e23\u0e23\u0e22\u0e4c\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 \u0e19\u0e01\u0e08\u0e23\u0e34\u0e07 \u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48 AI \u0e0a\u0e32\u0e27\u0e40\u0e19\u0e47\u0e15\u0e41\u0e2b\u0e48\u0e41\u0e0b\u0e27\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e15\u0e31\u0e27\u0e25\u0e30\u0e04\u0e23\u0e21\u0e31\u0e07\u0e07\u0e30\u0e0a\u0e37\u0e48\u0e2d\u0e14\u0e31\u0e07"}]},{"@type":"WebSite","@id":"https:\/\/www.naewna.com\/n\/#website","url":"https:\/\/www.naewna.com\/n\/","name":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.naewna.com\/n\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"},{"@type":"Person","@id":"https:\/\/www.naewna.com\/n\/#\/schema\/person\/f8879586f5c1fd64b3b8854b6c19f0bf","name":"\u0e2a\u0e38\u0e23\u0e31\u0e0a (\u0e41\u0e21\u0e47\u0e04) \u0e1e\u0e34\u0e21\u0e43\u0e08\u0e43\u0e2a","image":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/secure.gravatar.com\/avatar\/baca03c08e42acabe4e38e3821f997afc3e0581bf23f5829f09a5405e86d29a8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/baca03c08e42acabe4e38e3821f997afc3e0581bf23f5829f09a5405e86d29a8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/baca03c08e42acabe4e38e3821f997afc3e0581bf23f5829f09a5405e86d29a8?s=96&d=mm&r=g","caption":"\u0e2a\u0e38\u0e23\u0e31\u0e0a (\u0e41\u0e21\u0e47\u0e04) \u0e1e\u0e34\u0e21\u0e43\u0e08\u0e43\u0e2a"},"url":"https:\/\/www.naewna.com\/n\/author\/pafrank\/"}]}},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/storage-wp.naewna.com\/2026\/09\/\u0e15\u0e49\u0e19\u0e41\u0e1a\u0e1a-7.jpg","_links":{"self":[{"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/posts\/39692","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/comments?post=39692"}],"version-history":[{"count":3,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/posts\/39692\/revisions"}],"predecessor-version":[{"id":39810,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/posts\/39692\/revisions\/39810"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/media\/39797"}],"wp:attachment":[{"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/media?parent=39692"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/categories?post=39692"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/tags?post=39692"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}