{"id":39870,"date":"2026-09-02T18:29:08","date_gmt":"2026-09-02T11:29:08","guid":{"rendered":"https:\/\/www.naewna.com\/n\/?p=39870"},"modified":"2026-09-02T18:29:19","modified_gmt":"2026-09-02T11:29:19","slug":"%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%8a%e0%b8%b2%e0%b8%94%e0%b8%aa%e0%b8%94%e0%b8%b8%e0%b8%94%e0%b8%b5-%e0%b8%99%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%81%e0%b8%a3%e0%b8%b4%e0%b9%8a%e0%b8%87","status":"publish","type":"post","link":"https:\/\/www.naewna.com\/n\/top-stories\/39870\/","title":{"rendered":"\u0e2a\u0e20\u0e32\u0e01\u0e32\u0e0a\u0e32\u0e14\u0e2a\u0e14\u0e38\u0e14\u0e35 \u0e19\u0e49\u0e2d\u0e07\u0e01\u0e23\u0e34\u0e4a\u0e07 \u0e19\u0e31\u0e01\u0e1f\u0e38\u0e15\u0e0b\u0e2d\u0e25\u0e2b\u0e0d\u0e34\u0e07\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e2d\u0e38\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e2b\u0e15\u0e38 \u0e01\u0e48\u0e2d\u0e19\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e31\u0e27\u0e15\u0e31\u0e14\u0e2a\u0e34\u0e19\u0e43\u0e08\u0e1a\u0e23\u0e34\u0e08\u0e32\u0e04\u0e2d\u0e27\u0e31\u0e22\u0e27\u0e30 \u0e15\u0e48\u0e2d\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22"},"content":{"rendered":"<div class=\"vce-row-container\" data-vce-boxed-width=\"true\"><div class=\"vce-row vce-row--col-gap-30 vce-row-equal-height vce-row-content--top\" id=\"el-1fe8a39a\" data-vce-do-apply=\"all el-1fe8a39a\"><div class=\"vce-row-content\" data-vce-element-content=\"true\"><div class=\"vce-col vce-col--md-auto vce-col--xs-1 vce-col--xs-last vce-col--xs-first vce-col--sm-last vce-col--sm-first vce-col--md-last vce-col--lg-last vce-col--xl-last vce-col--md-first vce-col--lg-first vce-col--xl-first\" id=\"el-301a6c09\"><div class=\"vce-col-inner\" data-vce-do-apply=\"border margin background  el-301a6c09\"><div class=\"vce-col-content\" data-vce-element-content=\"true\" data-vce-do-apply=\"padding el-301a6c09\"><div class=\"vce-text-block\"><div class=\"vce-text-block-wrapper vce\" id=\"el-ad322871\" data-vce-do-apply=\"all el-ad322871\"><p><strong>\u0e2a\u0e20\u0e32\u0e01\u0e32\u0e0a\u0e32\u0e14\u0e2a\u0e14\u0e38\u0e14\u0e35 \u0e19\u0e49\u0e2d\u0e07\u0e01\u0e23\u0e34\u0e4a\u0e07 \u0e19\u0e31\u0e01\u0e1f\u0e38\u0e15\u0e0b\u0e2d\u0e25\u0e2b\u0e0d\u0e34\u0e07\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e2d\u0e38\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e2b\u0e15\u0e38 \u0e01\u0e48\u0e2d\u0e19\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e31\u0e27\u0e15\u0e31\u0e14\u0e2a\u0e34\u0e19\u0e43\u0e08\u0e1a\u0e23\u0e34\u0e08\u0e32\u0e04\u0e2d\u0e27\u0e31\u0e22\u0e27\u0e30 \u0e15\u0e48\u0e2d\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22<\/strong><\/p>\n<p>\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 2 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2569 \u0e40\u0e1e\u0e08\u0e40\u0e1f\u0e0b\u0e1a\u0e38\u0e4a\u0e01 \u201c\u0e2a\u0e20\u0e32\u0e01\u0e32\u0e0a\u0e32\u0e14\u0e44\u0e17\u0e22 Thai Red Cross Society\u201d \u0e44\u0e14\u0e49\u0e40\u0e1b\u0e34\u0e14\u0e40\u0e1c\u0e22\u0e16\u0e36\u0e07\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e27 \u0e02\u0e2d\u0e07 \u0e19\u0e49\u0e2d\u0e07\u0e01\u0e23\u0e34\u0e4a\u0e07 - \u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e40\u0e02\u0e21\u0e34\u0e01\u0e32 \u0e04\u0e38\u0e49\u0e21\u0e16\u0e19\u0e2d\u0e21 \u0e27\u0e31\u0e22 21 \u0e1b\u0e35 \u0e19\u0e31\u0e01\u0e1f\u0e38\u0e15\u0e0b\u0e2d\u0e25\u0e2b\u0e0d\u0e34\u0e07\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e01\u0e32\u0e23\u0e01\u0e35\u0e2c\u0e32\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u0e2b\u0e25\u0e31\u0e07\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e2d\u0e38\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e2b\u0e15\u0e38\u0e08\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e20\u0e32\u0e27\u0e30\u0e2a\u0e21\u0e2d\u0e07\u0e15\u0e32\u0e22 \u0e17\u0e48\u0e32\u0e21\u0e01\u0e25\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e42\u0e28\u0e01\u0e40\u0e28\u0e23\u0e49\u0e32 \u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e31\u0e27\u0e44\u0e14\u0e49\u0e15\u0e31\u0e14\u0e2a\u0e34\u0e19\u0e43\u0e08\u0e04\u0e23\u0e31\u0e49\u0e07\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e01\u0e38\u0e28\u0e25\u0e2d\u0e31\u0e19\u0e22\u0e34\u0e48\u0e07\u0e43\u0e2b\u0e0d\u0e48 \u0e42\u0e14\u0e22\u0e41\u0e2a\u0e14\u0e07\u0e04\u0e27\u0e32\u0e21\u0e08\u0e33\u0e19\u0e07\u0e1a\u0e23\u0e34\u0e08\u0e32\u0e04\u0e2d\u0e27\u0e31\u0e22\u0e27\u0e30\u0e17\u0e38\u0e01\u0e2a\u0e48\u0e27\u0e19\u0e41\u0e25\u0e30\u0e14\u0e27\u0e07\u0e15\u0e32\u0e02\u0e2d\u0e07\u0e19\u0e49\u0e2d\u0e07\u0e01\u0e23\u0e34\u0e4a\u0e07 \u0e2b\u0e27\u0e31\u0e07\u0e2a\u0e48\u0e07\u0e15\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e27\u0e31\u0e07\u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e2d\u0e37\u0e48\u0e19<\/p>\n<p>\u0e42\u0e14\u0e22\u0e43\u0e19\u0e42\u0e1e\u0e2a\u0e15\u0e4c\u0e23\u0e30\u0e1a\u0e38\u0e27\u0e48\u0e32 \u0e01\u0e38\u0e28\u0e25\u0e2d\u0e31\u0e19\u0e22\u0e34\u0e48\u0e07\u0e43\u0e2b\u0e0d\u0e48 \u0e19\u0e31\u0e01\u0e01\u0e35\u0e2c\u0e32\u0e1f\u0e38\u0e15\u0e0b\u0e2d\u0e25\u0e27\u0e31\u0e22 21 \u0e1b\u0e35 #\u0e1a\u0e23\u0e34\u0e08\u0e32\u0e04\u0e2d\u0e27\u0e31\u0e22\u0e27\u0e30 \u0e15\u0e48\u0e2d\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22<\/p>\n<p>\u0e19\u0e49\u0e2d\u0e07\u0e01\u0e23\u0e34\u0e4a\u0e07 - \u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e40\u0e02\u0e21\u0e34\u0e01\u0e32 \u0e04\u0e38\u0e49\u0e21\u0e16\u0e19\u0e2d\u0e21 \u0e27\u0e31\u0e22 21 \u0e1b\u0e35 \u0e19\u0e31\u0e01\u0e1f\u0e38\u0e15\u0e0b\u0e2d\u0e25\u0e2b\u0e0d\u0e34\u0e07 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e01\u0e32\u0e23\u0e01\u0e35\u0e2c\u0e32\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e2d\u0e38\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e2b\u0e15\u0e38\u0e1a\u0e19\u0e16\u0e19\u0e19 \u0e2b\u0e25\u0e31\u0e07\u0e40\u0e25\u0e34\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e02\u0e13\u0e30\u0e01\u0e33\u0e25\u0e31\u0e07\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e44\u0e1b\u0e17\u0e33\u0e07\u0e32\u0e19\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2b\u0e32\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e40\u0e1e\u0e34\u0e48\u0e21<\/p>\n<p>\u0e2d\u0e38\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e2b\u0e15\u0e38\u0e44\u0e14\u0e49\u0e1e\u0e23\u0e32\u0e01\u0e04\u0e27\u0e32\u0e21\u0e1d\u0e31\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e02\u0e2d\u0e07\u0e19\u0e49\u0e2d\u0e07\u0e01\u0e23\u0e34\u0e4a\u0e07\u0e44\u0e1b \u0e19\u0e33\u0e21\u0e32\u0e0b\u0e36\u0e48\u0e07\u0e20\u0e32\u0e27\u0e30\u0e2a\u0e21\u0e2d\u0e07\u0e15\u0e32\u0e22 \u0e17\u0e48\u0e32\u0e21\u0e01\u0e25\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e42\u0e28\u0e01\u0e40\u0e28\u0e23\u0e49\u0e32 \u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e31\u0e27\u0e44\u0e14\u0e49\u0e15\u0e31\u0e14\u0e2a\u0e34\u0e19\u0e43\u0e08\u0e04\u0e23\u0e31\u0e49\u0e07\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e01\u0e38\u0e28\u0e25\u0e2d\u0e31\u0e19\u0e22\u0e34\u0e48\u0e07\u0e43\u0e2b\u0e0d\u0e48 \u0e42\u0e14\u0e22\u0e41\u0e2a\u0e14\u0e07\u0e04\u0e27\u0e32\u0e21\u0e08\u0e33\u0e19\u0e07\u0e1a\u0e23\u0e34\u0e08\u0e32\u0e04\u0e2d\u0e27\u0e31\u0e22\u0e27\u0e30\u0e17\u0e38\u0e01\u0e2a\u0e48\u0e27\u0e19\u0e41\u0e25\u0e30\u0e14\u0e27\u0e07\u0e15\u0e32\u0e02\u0e2d\u0e07\u0e19\u0e49\u0e2d\u0e07\u0e01\u0e23\u0e34\u0e4a\u0e07 \u0e2b\u0e27\u0e31\u0e07\u0e2a\u0e48\u0e07\u0e15\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e27\u0e31\u0e07\u0e43\u0e2b\u0e49\u0e1c\u0e38\u0e49\u0e2d\u0e37\u0e48\u0e19<\/p>\n<p>\u0e41\u0e21\u0e49\u0e20\u0e32\u0e22\u0e2b\u0e25\u0e31\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e08\u0e30\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e19\u0e33\u0e44\u0e1b\u0e43\u0e0a\u0e49\u0e15\u0e48\u0e2d\u0e25\u0e21\u0e2b\u0e32\u0e22\u0e43\u0e08\u0e44\u0e14\u0e49\u0e40\u0e1e\u0e35\u0e22\u0e07 \"\u0e15\u0e31\u0e1a\" \u0e41\u0e25\u0e30 \"\u0e44\u0e15\" \u0e41\u0e15\u0e48\u0e04\u0e27\u0e32\u0e21\u0e15\u0e31\u0e49\u0e07\u0e43\u0e08\u0e2d\u0e31\u0e19\u0e41\u0e19\u0e48\u0e27\u0e41\u0e19\u0e48\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2a\u0e38\u0e17\u0e18\u0e34\u0e4c\u0e02\u0e2d\u0e07\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e31\u0e27 \u0e01\u0e47\u0e44\u0e14\u0e49\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1b\u0e32\u0e0f\u0e34\u0e2b\u0e32\u0e23\u0e34\u0e22\u0e4c\u0e0a\u0e38\u0e1a\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e43\u0e2b\u0e21\u0e48\u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e17\u0e35\u0e48\u0e01\u0e33\u0e25\u0e31\u0e07\u0e23\u0e2d\u0e04\u0e2d\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e27\u0e31\u0e07 \u0e44\u0e14\u0e49\u0e01\u0e25\u0e31\u0e1a\u0e21\u0e32\u0e21\u0e35\u0e25\u0e21\u0e2b\u0e32\u0e22\u0e43\u0e08\u0e2d\u0e35\u0e01\u0e04\u0e23\u0e31\u0e49\u0e07<\/p>\n<p>\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e31\u0e27\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e31\u0e48\u0e19\u0e27\u0e48\u0e32 \u0e01\u0e38\u0e28\u0e25\u0e17\u0e32\u0e19\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19 \"\u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e49\" \u0e08\u0e27\u0e1a\u0e08\u0e19\u0e27\u0e34\u0e19\u0e32\u0e17\u0e35\u0e2a\u0e38\u0e14\u0e17\u0e49\u0e32\u0e22 \u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e2a\u0e07\u0e2a\u0e27\u0e48\u0e32\u0e07\u0e19\u0e33\u0e1e\u0e32\u0e14\u0e27\u0e07\u0e27\u0e34\u0e0d\u0e0d\u0e32\u0e13\u0e02\u0e2d\u0e07\u0e19\u0e49\u0e2d\u0e07\u0e01\u0e23\u0e34\u0e4a\u0e07\u0e44\u0e1b\u0e2a\u0e39\u0e48\u0e2a\u0e31\u0e21\u0e1b\u0e23\u0e32\u0e22\u0e20\u0e1e \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e04\u0e27\u0e32\u0e21\u0e20\u0e32\u0e04\u0e20\u0e39\u0e21\u0e34\u0e43\u0e08\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14\u0e02\u0e2d\u0e07\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e31\u0e27\u0e17\u0e35\u0e48\u0e19\u0e49\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e14\u0e35\u0e17\u0e34\u0e49\u0e07\u0e44\u0e27\u0e49\u0e40\u0e1a\u0e37\u0e49\u0e2d\u0e07\u0e2b\u0e25\u0e31\u0e07<\/p>\n<p>#\u0e2a\u0e20\u0e32\u0e01\u0e32\u0e0a\u0e32\u0e14\u0e44\u0e17\u0e22 \u0e02\u0e2d\u0e41\u0e2a\u0e14\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e22\u0e43\u0e08\u0e01\u0e31\u0e1a\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e31\u0e27\u0e04\u0e38\u0e49\u0e21\u0e16\u0e19\u0e2d\u0e21 \u0e41\u0e25\u0e30\u0e02\u0e2d\u0e2a\u0e14\u0e38\u0e14\u0e35\u0e43\u0e19\u0e04\u0e27\u0e32\u0e21\u0e14\u0e35\u0e02\u0e2d\u0e07\u0e19\u0e49\u0e2d\u0e07\u0e01\u0e23\u0e34\u0e4a\u0e07 \u0e02\u0e2d\u0e43\u0e2b\u0e49\u0e1c\u0e25\u0e1a\u0e38\u0e0d\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e15\u0e48\u0e2d\u0e25\u0e21\u0e2b\u0e32\u0e22\u0e43\u0e08\u0e43\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e19\u0e33\u0e1e\u0e32\u0e14\u0e27\u0e07\u0e27\u0e34\u0e0d\u0e0d\u0e32\u0e13\u0e02\u0e2d\u0e07\u0e19\u0e49\u0e2d\u0e07\u0e44\u0e1b\u0e2a\u0e39\u0e48\u0e2a\u0e23\u0e27\u0e07\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c<\/p>\n<p><iframe loading=\"lazy\" style=\"border: none; overflow: hidden;\" src=\"https:\/\/www.facebook.com\/plugins\/post.php?href=https%3A%2F%2Fwww.facebook.com%2FThaiRedCrossSociety%2Fposts%2Fpfbid02znWCLE1saLruFwknXJQ5fF76WdwMxZKmpge46YMxC2e4HCMUxeGDH2psw8FjpFCql&amp;show_text=true&amp;width=500\" width=\"500\" height=\"747\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe> <iframe loading=\"lazy\" style=\"border: none; overflow: hidden;\" src=\"https:\/\/www.facebook.com\/plugins\/post.php?href=https%3A%2F%2Fwww.facebook.com%2Fpermalink.php%3Fstory_fbid%3Dpfbid02p7B2StuxnqvXki5J6dG7WDci5dSBUb3yHgrRCtWKKW1fEAZvUB3rkprRxJPsvbWql%26id%3D100019188494738&amp;show_text=true&amp;width=500\" width=\"500\" height=\"736\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u0e2a\u0e20\u0e32\u0e01\u0e32\u0e0a\u0e32\u0e14\u0e2a\u0e14\u0e38\u0e14\u0e35 \u0e19\u0e49\u0e2d\u0e07\u0e01\u0e23\u0e34\u0e4a\u0e07 \u0e19\u0e31\u0e01\u0e1f\u0e38\u0e15\u0e0b\u0e2d\u0e25\u0e2b\u0e0d\u0e34\u0e07\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e2d\u0e38\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e2b\u0e15\u0e38 \u0e01\u0e48 [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":39874,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3,339,9],"tags":[6113,6112],"class_list":["post-39870","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-top-stories","category-quality-of-life-news","category-national-news","tag-6113","tag-6112"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u0e2a\u0e20\u0e32\u0e01\u0e32\u0e0a\u0e32\u0e14\u0e2a\u0e14\u0e38\u0e14\u0e35 \u0e19\u0e49\u0e2d\u0e07\u0e01\u0e23\u0e34\u0e4a\u0e07 \u0e19\u0e31\u0e01\u0e1f\u0e38\u0e15\u0e0b\u0e2d\u0e25\u0e2b\u0e0d\u0e34\u0e07\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e2d\u0e38\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e2b\u0e15\u0e38 \u0e01\u0e48\u0e2d\u0e19\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e31\u0e27\u0e15\u0e31\u0e14\u0e2a\u0e34\u0e19\u0e43\u0e08\u0e1a\u0e23\u0e34\u0e08\u0e32\u0e04\u0e2d\u0e27\u0e31\u0e22\u0e27\u0e30 \u0e15\u0e48\u0e2d\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.naewna.com\/n\/top-stories\/39870\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e2a\u0e20\u0e32\u0e01\u0e32\u0e0a\u0e32\u0e14\u0e2a\u0e14\u0e38\u0e14\u0e35 \u0e19\u0e49\u0e2d\u0e07\u0e01\u0e23\u0e34\u0e4a\u0e07 \u0e19\u0e31\u0e01\u0e1f\u0e38\u0e15\u0e0b\u0e2d\u0e25\u0e2b\u0e0d\u0e34\u0e07\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e2d\u0e38\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e2b\u0e15\u0e38 \u0e01\u0e48\u0e2d\u0e19\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e31\u0e27\u0e15\u0e31\u0e14\u0e2a\u0e34\u0e19\u0e43\u0e08\u0e1a\u0e23\u0e34\u0e08\u0e32\u0e04\u0e2d\u0e27\u0e31\u0e22\u0e27\u0e30 \u0e15\u0e48\u0e2d\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\" \/>\n<meta property=\"og:description\" content=\"\u0e2a\u0e20\u0e32\u0e01\u0e32\u0e0a\u0e32\u0e14\u0e2a\u0e14\u0e38\u0e14\u0e35 \u0e19\u0e49\u0e2d\u0e07\u0e01\u0e23\u0e34\u0e4a\u0e07 \u0e19\u0e31\u0e01\u0e1f\u0e38\u0e15\u0e0b\u0e2d\u0e25\u0e2b\u0e0d\u0e34\u0e07\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e2d\u0e38\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e2b\u0e15\u0e38 \u0e01\u0e48 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.naewna.com\/n\/top-stories\/39870\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NaewnaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2026-09-02T11:29:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-02T11:29:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/storage-wp.naewna.com\/2026\/09\/7-7.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"\u0e0a\u0e32\u0e04\u0e23\u0e34\u0e15\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@naewna_news\" \/>\n<meta name=\"twitter:site\" content=\"@naewna_news\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u0e0a\u0e32\u0e04\u0e23\u0e34\u0e15\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/top-stories\\\/39870\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/top-stories\\\/39870\\\/\"},\"author\":{\"name\":\"\u0e0a\u0e32\u0e04\u0e23\u0e34\u0e15\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#\\\/schema\\\/person\\\/a330cecd5b69512db05357f516e57414\"},\"headline\":\"\u0e2a\u0e20\u0e32\u0e01\u0e32\u0e0a\u0e32\u0e14\u0e2a\u0e14\u0e38\u0e14\u0e35 \u0e19\u0e49\u0e2d\u0e07\u0e01\u0e23\u0e34\u0e4a\u0e07 \u0e19\u0e31\u0e01\u0e1f\u0e38\u0e15\u0e0b\u0e2d\u0e25\u0e2b\u0e0d\u0e34\u0e07\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e2d\u0e38\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e2b\u0e15\u0e38 \u0e01\u0e48\u0e2d\u0e19\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e31\u0e27\u0e15\u0e31\u0e14\u0e2a\u0e34\u0e19\u0e43\u0e08\u0e1a\u0e23\u0e34\u0e08\u0e32\u0e04\u0e2d\u0e27\u0e31\u0e22\u0e27\u0e30 \u0e15\u0e48\u0e2d\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\",\"datePublished\":\"2026-09-02T11:29:08+00:00\",\"dateModified\":\"2026-09-02T11:29:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/top-stories\\\/39870\\\/\"},\"wordCount\":6,\"image\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/top-stories\\\/39870\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/storage-wp.naewna.com\\\/2026\\\/09\\\/7-7.jpg\",\"keywords\":[\"\u0e19\u0e49\u0e2d\u0e07\u0e01\u0e23\u0e34\u0e4a\u0e07\",\"\u0e2a\u0e20\u0e32\u0e01\u0e32\u0e0a\u0e32\u0e14\"],\"articleSection\":[\"\u0e02\u0e48\u0e32\u0e27\u0e40\u0e14\u0e48\u0e19\",\"\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e0a\u0e35\u0e27\u0e34\u0e15\",\"\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\"],\"inLanguage\":\"th\",\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/top-stories\\\/39870\\\/\",\"url\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/top-stories\\\/39870\\\/\",\"name\":\"\u0e2a\u0e20\u0e32\u0e01\u0e32\u0e0a\u0e32\u0e14\u0e2a\u0e14\u0e38\u0e14\u0e35 \u0e19\u0e49\u0e2d\u0e07\u0e01\u0e23\u0e34\u0e4a\u0e07 \u0e19\u0e31\u0e01\u0e1f\u0e38\u0e15\u0e0b\u0e2d\u0e25\u0e2b\u0e0d\u0e34\u0e07\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e2d\u0e38\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e2b\u0e15\u0e38 \u0e01\u0e48\u0e2d\u0e19\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e31\u0e27\u0e15\u0e31\u0e14\u0e2a\u0e34\u0e19\u0e43\u0e08\u0e1a\u0e23\u0e34\u0e08\u0e32\u0e04\u0e2d\u0e27\u0e31\u0e22\u0e27\u0e30 \u0e15\u0e48\u0e2d\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/top-stories\\\/39870\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/top-stories\\\/39870\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/storage-wp.naewna.com\\\/2026\\\/09\\\/7-7.jpg\",\"datePublished\":\"2026-09-02T11:29:08+00:00\",\"dateModified\":\"2026-09-02T11:29:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#\\\/schema\\\/person\\\/a330cecd5b69512db05357f516e57414\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/top-stories\\\/39870\\\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.naewna.com\\\/n\\\/top-stories\\\/39870\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/top-stories\\\/39870\\\/#primaryimage\",\"url\":\"https:\\\/\\\/storage-wp.naewna.com\\\/2026\\\/09\\\/7-7.jpg\",\"contentUrl\":\"https:\\\/\\\/storage-wp.naewna.com\\\/2026\\\/09\\\/7-7.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/top-stories\\\/39870\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e2a\u0e20\u0e32\u0e01\u0e32\u0e0a\u0e32\u0e14\u0e2a\u0e14\u0e38\u0e14\u0e35 \u0e19\u0e49\u0e2d\u0e07\u0e01\u0e23\u0e34\u0e4a\u0e07 \u0e19\u0e31\u0e01\u0e1f\u0e38\u0e15\u0e0b\u0e2d\u0e25\u0e2b\u0e0d\u0e34\u0e07\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e2d\u0e38\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e2b\u0e15\u0e38 \u0e01\u0e48\u0e2d\u0e19\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e31\u0e27\u0e15\u0e31\u0e14\u0e2a\u0e34\u0e19\u0e43\u0e08\u0e1a\u0e23\u0e34\u0e08\u0e32\u0e04\u0e2d\u0e27\u0e31\u0e22\u0e27\u0e30 \u0e15\u0e48\u0e2d\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#website\",\"url\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/\",\"name\":\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#\\\/schema\\\/person\\\/a330cecd5b69512db05357f516e57414\",\"name\":\"\u0e0a\u0e32\u0e04\u0e23\u0e34\u0e15\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc06501e1f1b9ef51d6836eeb0fc0930cd60f773d28dac939321b0f42c5eef44?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc06501e1f1b9ef51d6836eeb0fc0930cd60f773d28dac939321b0f42c5eef44?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc06501e1f1b9ef51d6836eeb0fc0930cd60f773d28dac939321b0f42c5eef44?s=96&d=mm&r=g\",\"caption\":\"\u0e0a\u0e32\u0e04\u0e23\u0e34\u0e15\"},\"url\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/author\\\/miceboy2\\\/\"}]}<\/script>\n<meta property=\"article:section\" content=\"\u0e02\u0e48\u0e32\u0e27\u0e40\u0e14\u0e48\u0e19\" \/>\n<meta property=\"article:section\" content=\"\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e0a\u0e35\u0e27\u0e34\u0e15\" \/>\n<meta property=\"article:section\" content=\"\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u0e2a\u0e20\u0e32\u0e01\u0e32\u0e0a\u0e32\u0e14\u0e2a\u0e14\u0e38\u0e14\u0e35 \u0e19\u0e49\u0e2d\u0e07\u0e01\u0e23\u0e34\u0e4a\u0e07 \u0e19\u0e31\u0e01\u0e1f\u0e38\u0e15\u0e0b\u0e2d\u0e25\u0e2b\u0e0d\u0e34\u0e07\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e2d\u0e38\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e2b\u0e15\u0e38 \u0e01\u0e48\u0e2d\u0e19\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e31\u0e27\u0e15\u0e31\u0e14\u0e2a\u0e34\u0e19\u0e43\u0e08\u0e1a\u0e23\u0e34\u0e08\u0e32\u0e04\u0e2d\u0e27\u0e31\u0e22\u0e27\u0e30 \u0e15\u0e48\u0e2d\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.naewna.com\/n\/top-stories\/39870\/","og_locale":"th_TH","og_type":"article","og_title":"\u0e2a\u0e20\u0e32\u0e01\u0e32\u0e0a\u0e32\u0e14\u0e2a\u0e14\u0e38\u0e14\u0e35 \u0e19\u0e49\u0e2d\u0e07\u0e01\u0e23\u0e34\u0e4a\u0e07 \u0e19\u0e31\u0e01\u0e1f\u0e38\u0e15\u0e0b\u0e2d\u0e25\u0e2b\u0e0d\u0e34\u0e07\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e2d\u0e38\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e2b\u0e15\u0e38 \u0e01\u0e48\u0e2d\u0e19\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e31\u0e27\u0e15\u0e31\u0e14\u0e2a\u0e34\u0e19\u0e43\u0e08\u0e1a\u0e23\u0e34\u0e08\u0e32\u0e04\u0e2d\u0e27\u0e31\u0e22\u0e27\u0e30 \u0e15\u0e48\u0e2d\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22","og_description":"\u0e2a\u0e20\u0e32\u0e01\u0e32\u0e0a\u0e32\u0e14\u0e2a\u0e14\u0e38\u0e14\u0e35 \u0e19\u0e49\u0e2d\u0e07\u0e01\u0e23\u0e34\u0e4a\u0e07 \u0e19\u0e31\u0e01\u0e1f\u0e38\u0e15\u0e0b\u0e2d\u0e25\u0e2b\u0e0d\u0e34\u0e07\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e2d\u0e38\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e2b\u0e15\u0e38 \u0e01\u0e48 [&hellip;]","og_url":"https:\/\/www.naewna.com\/n\/top-stories\/39870\/","og_site_name":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32","article_publisher":"https:\/\/www.facebook.com\/NaewnaOnline","article_published_time":"2026-09-02T11:29:08+00:00","article_modified_time":"2026-09-02T11:29:19+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/storage-wp.naewna.com\/2026\/09\/7-7.jpg","type":"image\/jpeg"}],"author":"\u0e0a\u0e32\u0e04\u0e23\u0e34\u0e15","twitter_card":"summary_large_image","twitter_creator":"@naewna_news","twitter_site":"@naewna_news","twitter_misc":{"Written by":"\u0e0a\u0e32\u0e04\u0e23\u0e34\u0e15"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.naewna.com\/n\/top-stories\/39870\/#article","isPartOf":{"@id":"https:\/\/www.naewna.com\/n\/top-stories\/39870\/"},"author":{"name":"\u0e0a\u0e32\u0e04\u0e23\u0e34\u0e15","@id":"https:\/\/www.naewna.com\/n\/#\/schema\/person\/a330cecd5b69512db05357f516e57414"},"headline":"\u0e2a\u0e20\u0e32\u0e01\u0e32\u0e0a\u0e32\u0e14\u0e2a\u0e14\u0e38\u0e14\u0e35 \u0e19\u0e49\u0e2d\u0e07\u0e01\u0e23\u0e34\u0e4a\u0e07 \u0e19\u0e31\u0e01\u0e1f\u0e38\u0e15\u0e0b\u0e2d\u0e25\u0e2b\u0e0d\u0e34\u0e07\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e2d\u0e38\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e2b\u0e15\u0e38 \u0e01\u0e48\u0e2d\u0e19\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e31\u0e27\u0e15\u0e31\u0e14\u0e2a\u0e34\u0e19\u0e43\u0e08\u0e1a\u0e23\u0e34\u0e08\u0e32\u0e04\u0e2d\u0e27\u0e31\u0e22\u0e27\u0e30 \u0e15\u0e48\u0e2d\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22","datePublished":"2026-09-02T11:29:08+00:00","dateModified":"2026-09-02T11:29:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.naewna.com\/n\/top-stories\/39870\/"},"wordCount":6,"image":{"@id":"https:\/\/www.naewna.com\/n\/top-stories\/39870\/#primaryimage"},"thumbnailUrl":"https:\/\/storage-wp.naewna.com\/2026\/09\/7-7.jpg","keywords":["\u0e19\u0e49\u0e2d\u0e07\u0e01\u0e23\u0e34\u0e4a\u0e07","\u0e2a\u0e20\u0e32\u0e01\u0e32\u0e0a\u0e32\u0e14"],"articleSection":["\u0e02\u0e48\u0e32\u0e27\u0e40\u0e14\u0e48\u0e19","\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e0a\u0e35\u0e27\u0e34\u0e15","\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28"],"inLanguage":"th","copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/www.naewna.com\/n\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.naewna.com\/n\/top-stories\/39870\/","url":"https:\/\/www.naewna.com\/n\/top-stories\/39870\/","name":"\u0e2a\u0e20\u0e32\u0e01\u0e32\u0e0a\u0e32\u0e14\u0e2a\u0e14\u0e38\u0e14\u0e35 \u0e19\u0e49\u0e2d\u0e07\u0e01\u0e23\u0e34\u0e4a\u0e07 \u0e19\u0e31\u0e01\u0e1f\u0e38\u0e15\u0e0b\u0e2d\u0e25\u0e2b\u0e0d\u0e34\u0e07\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e2d\u0e38\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e2b\u0e15\u0e38 \u0e01\u0e48\u0e2d\u0e19\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e31\u0e27\u0e15\u0e31\u0e14\u0e2a\u0e34\u0e19\u0e43\u0e08\u0e1a\u0e23\u0e34\u0e08\u0e32\u0e04\u0e2d\u0e27\u0e31\u0e22\u0e27\u0e30 \u0e15\u0e48\u0e2d\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32","isPartOf":{"@id":"https:\/\/www.naewna.com\/n\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.naewna.com\/n\/top-stories\/39870\/#primaryimage"},"image":{"@id":"https:\/\/www.naewna.com\/n\/top-stories\/39870\/#primaryimage"},"thumbnailUrl":"https:\/\/storage-wp.naewna.com\/2026\/09\/7-7.jpg","datePublished":"2026-09-02T11:29:08+00:00","dateModified":"2026-09-02T11:29:19+00:00","author":{"@id":"https:\/\/www.naewna.com\/n\/#\/schema\/person\/a330cecd5b69512db05357f516e57414"},"breadcrumb":{"@id":"https:\/\/www.naewna.com\/n\/top-stories\/39870\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.naewna.com\/n\/top-stories\/39870\/"]}]},{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.naewna.com\/n\/top-stories\/39870\/#primaryimage","url":"https:\/\/storage-wp.naewna.com\/2026\/09\/7-7.jpg","contentUrl":"https:\/\/storage-wp.naewna.com\/2026\/09\/7-7.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.naewna.com\/n\/top-stories\/39870\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.naewna.com\/n\/"},{"@type":"ListItem","position":2,"name":"\u0e2a\u0e20\u0e32\u0e01\u0e32\u0e0a\u0e32\u0e14\u0e2a\u0e14\u0e38\u0e14\u0e35 \u0e19\u0e49\u0e2d\u0e07\u0e01\u0e23\u0e34\u0e4a\u0e07 \u0e19\u0e31\u0e01\u0e1f\u0e38\u0e15\u0e0b\u0e2d\u0e25\u0e2b\u0e0d\u0e34\u0e07\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e2d\u0e38\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e2b\u0e15\u0e38 \u0e01\u0e48\u0e2d\u0e19\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e31\u0e27\u0e15\u0e31\u0e14\u0e2a\u0e34\u0e19\u0e43\u0e08\u0e1a\u0e23\u0e34\u0e08\u0e32\u0e04\u0e2d\u0e27\u0e31\u0e22\u0e27\u0e30 \u0e15\u0e48\u0e2d\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22"}]},{"@type":"WebSite","@id":"https:\/\/www.naewna.com\/n\/#website","url":"https:\/\/www.naewna.com\/n\/","name":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.naewna.com\/n\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"},{"@type":"Person","@id":"https:\/\/www.naewna.com\/n\/#\/schema\/person\/a330cecd5b69512db05357f516e57414","name":"\u0e0a\u0e32\u0e04\u0e23\u0e34\u0e15","image":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/secure.gravatar.com\/avatar\/cc06501e1f1b9ef51d6836eeb0fc0930cd60f773d28dac939321b0f42c5eef44?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cc06501e1f1b9ef51d6836eeb0fc0930cd60f773d28dac939321b0f42c5eef44?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cc06501e1f1b9ef51d6836eeb0fc0930cd60f773d28dac939321b0f42c5eef44?s=96&d=mm&r=g","caption":"\u0e0a\u0e32\u0e04\u0e23\u0e34\u0e15"},"url":"https:\/\/www.naewna.com\/n\/author\/miceboy2\/"}]}},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/storage-wp.naewna.com\/2026\/09\/7-7.jpg","_links":{"self":[{"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/posts\/39870","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/comments?post=39870"}],"version-history":[{"count":2,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/posts\/39870\/revisions"}],"predecessor-version":[{"id":39879,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/posts\/39870\/revisions\/39879"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/media\/39874"}],"wp:attachment":[{"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/media?parent=39870"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/categories?post=39870"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/tags?post=39870"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}