{"id":40121,"date":"2026-09-02T21:03:55","date_gmt":"2026-09-02T14:03:55","guid":{"rendered":"https:\/\/www.naewna.com\/n\/?p=40121"},"modified":"2026-09-02T21:03:55","modified_gmt":"2026-09-02T14:03:55","slug":"%e0%b8%a2%e0%b8%b9%e0%b9%80%e0%b8%ad%e0%b9%87%e0%b8%99%e0%b8%8a%e0%b8%b5%e0%b9%89%e0%b8%ad%e0%b8%99%e0%b8%b2%e0%b8%84%e0%b8%95-%e0%b8%a3%e0%b8%b0%e0%b9%80%e0%b8%9a%e0%b8%b4%e0%b8%94%e0%b9%80%e0%b8%a7","status":"publish","type":"post","link":"https:\/\/www.naewna.com\/n\/top-stories\/40121\/","title":{"rendered":"\u0e22\u0e39\u0e40\u0e2d\u0e47\u0e19\u0e0a\u0e35\u0e49\u0e2d\u0e19\u0e32\u0e04\u0e15 \u0e23\u0e30\u0e40\u0e1a\u0e34\u0e14\u0e40\u0e27\u0e25\u0e32\u0e18\u0e32\u0e23\u0e19\u0e49\u0e33\u0e41\u0e02\u0e47\u0e07\u0e40\u0e17\u0e37\u0e2d\u0e01\u0e40\u0e02\u0e32\u0e2b\u0e34\u0e21\u0e32\u0e25\u0e31\u0e22 \u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e20\u0e31\u0e22\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e23\u0e38\u0e19\u0e41\u0e23\u0e07\u0e0b\u0e49\u0e33 \u0e01\u0e23\u0e30\u0e17\u0e1a\u0e25\u0e49\u0e32\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e44\u0e23\u0e49\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48"},"content":{"rendered":"<div class=\"vce-row-container\" data-vce-boxed-width=\"true\"><div class=\"vce-row vce-row--col-gap-30 vce-row-equal-height vce-row-content--top\" id=\"el-310ee39e\" data-vce-do-apply=\"all el-310ee39e\"><div class=\"vce-row-content\" data-vce-element-content=\"true\"><div class=\"vce-col vce-col--md-auto vce-col--xs-1 vce-col--xs-last vce-col--xs-first vce-col--sm-last vce-col--sm-first vce-col--md-last vce-col--lg-last vce-col--xl-last vce-col--md-first vce-col--lg-first vce-col--xl-first\" id=\"el-e17c39da\"><div class=\"vce-col-inner\" data-vce-do-apply=\"border margin background  el-e17c39da\"><div class=\"vce-col-content\" data-vce-element-content=\"true\" data-vce-do-apply=\"padding el-e17c39da\"><div class=\"vce-text-block\"><div class=\"vce-text-block-wrapper vce\" id=\"el-dedda3cf\" data-vce-do-apply=\"all el-dedda3cf\"><p>2 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2569 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e23\u0e2d\u0e22\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e2a \u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e27\u0e48\u0e32\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e39\u0e07\u0e02\u0e2d\u0e07\u0e2a\u0e2b\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e32\u0e15\u0e34 \u0e40\u0e15\u0e37\u0e2d\u0e19\u0e27\u0e48\u0e32 \u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e40\u0e17\u0e37\u0e2d\u0e01\u0e40\u0e02\u0e32\u0e2b\u0e34\u0e21\u0e32\u0e25\u0e31\u0e22\u0e01\u0e33\u0e25\u0e31\u0e07\u0e40\u0e1c\u0e0a\u0e34\u0e0d\u0e01\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e23\u0e49\u0e32\u0e22\u0e41\u0e23\u0e07\u0e08\u0e32\u0e01\u0e19\u0e49\u0e33\u0e17\u0e48\u0e27\u0e21\u0e08\u0e32\u0e01\u0e18\u0e32\u0e23\u0e19\u0e49\u0e33\u0e41\u0e02\u0e47\u0e07\u0e43\u0e19\u0e2d\u0e19\u0e32\u0e04\u0e15 \u0e02\u0e13\u0e30\u0e17\u0e35\u0e48\u0e22\u0e2d\u0e14\u0e1c\u0e39\u0e49\u0e40\u0e2a\u0e35\u0e22\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e08\u0e32\u0e01\u0e19\u0e49\u0e33\u0e17\u0e48\u0e27\u0e21\u0e43\u0e19\u0e40\u0e19\u0e1b\u0e32\u0e25\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e2a\u0e31\u0e1b\u0e14\u0e32\u0e2b\u0e4c\u0e17\u0e35\u0e48\u0e41\u0e25\u0e49\u0e27 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e01\u0e34\u0e14\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e16\u0e25\u0e48\u0e21\u0e02\u0e2d\u0e07\u0e18\u0e32\u0e23\u0e19\u0e49\u0e33\u0e41\u0e02\u0e47\u0e07 \u0e1e\u0e38\u0e48\u0e07\u0e2a\u0e39\u0e07\u0e40\u0e01\u0e34\u0e19 1,000 \u0e23\u0e32\u0e22\u0e41\u0e25\u0e49\u0e27 \u0e44\u0e21\u0e48\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e41\u0e15\u0e48\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e1e\u0e25\u0e31\u0e07\u0e19\u0e49\u0e33\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19\u0e1e\u0e36\u0e48\u0e07\u0e1e\u0e32\u0e08\u0e30\u0e15\u0e01\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e41\u0e15\u0e48\u0e23\u0e34\u0e21\u0e1d\u0e31\u0e48\u0e07\u0e41\u0e21\u0e48\u0e19\u0e49\u0e33\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\u0e17\u0e35\u0e48\u0e1c\u0e39\u0e49\u0e04\u0e19\u0e19\u0e31\u0e1a\u0e25\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e08\u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e44\u0e14\u0e49\u0e2d\u0e35\u0e01\u0e15\u0e48\u0e2d\u0e44\u0e1b<\/p>\n<p>\u0e19\u0e32\u0e07\u0e04\u0e32\u0e19\u0e19\u0e35 \u0e27\u0e34\u0e01\u0e19\u0e23\u0e32\u0e0a\u0e32 \u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e25\u0e02\u0e32\u0e18\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e2b\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e32\u0e15\u0e34 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e44\u0e21\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e44\u0e14\u0e49\u0e40\u0e23\u0e47\u0e27\u0e1e\u0e2d\u0e17\u0e35\u0e48\u0e08\u0e30\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e22\u0e2b\u0e32\u0e22\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e15\u0e32\u0e21\u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e21\u0e48\u0e19\u0e49\u0e33\u0e02\u0e19\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e35\u0e49 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e19\u0e49\u0e33\u0e25\u0e49\u0e19\u0e08\u0e32\u0e01\u0e17\u0e30\u0e40\u0e25\u0e2a\u0e32\u0e1a\u0e18\u0e32\u0e23\u0e19\u0e49\u0e33\u0e41\u0e02\u0e47\u0e07 \u0e43\u0e19\u0e1b\u0e35 2020 \u0e19\u0e31\u0e01\u0e27\u0e34\u0e08\u0e31\u0e22\u0e44\u0e14\u0e49\u0e23\u0e30\u0e1a\u0e38 \u0e17\u0e30\u0e40\u0e25\u0e2a\u0e32\u0e1a\u0e18\u0e32\u0e23\u0e19\u0e49\u0e33\u0e41\u0e02\u0e47\u0e07\u0e17\u0e35\u0e48\u0e2d\u0e32\u0e08\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e31\u0e19\u0e15\u0e23\u0e32\u0e22\u0e08\u0e33\u0e19\u0e27\u0e19 47 \u0e41\u0e2b\u0e48\u0e07\u0e43\u0e19\u0e40\u0e19\u0e1b\u0e32\u0e25 \u0e08\u0e35\u0e19 \u0e41\u0e25\u0e30\u0e2d\u0e34\u0e19\u0e40\u0e14\u0e35\u0e22 \u0e41\u0e15\u0e48\u0e15\u0e48\u0e2d\u0e21\u0e32\u0e21\u0e35\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e27\u0e48\u0e32\u0e08\u0e33\u0e19\u0e27\u0e19\u0e17\u0e35\u0e48\u0e41\u0e17\u0e49\u0e08\u0e23\u0e34\u0e07\u0e19\u0e31\u0e49\u0e19\u0e2a\u0e39\u0e07\u0e01\u0e27\u0e48\u0e32\u0e19\u0e35\u0e49\u0e21\u0e32\u0e01 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e01\u0e23\u0e17\u0e35\u0e48\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e20\u0e31\u0e22 \"\u0e21\u0e35\u0e08\u0e33\u0e19\u0e27\u0e19\u0e19\u0e31\u0e1a\u0e25\u0e49\u0e32\u0e19\u0e04\u0e19\" \u0e2d\u0e49\u0e32\u0e07\u0e2d\u0e34\u0e07\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14\u0e17\u0e35\u0e48\u0e23\u0e27\u0e1a\u0e23\u0e27\u0e21\u0e42\u0e14\u0e22 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e41\u0e2b\u0e48\u0e07\u0e2a\u0e2b\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e32\u0e15\u0e34 (UNDP) \u0e41\u0e25\u0e30 \u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e1e\u0e31\u0e19\u0e18\u0e21\u0e34\u0e15\u0e23 \u0e43\u0e19\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e21\u0e34\u0e16\u0e38\u0e19\u0e32\u0e22\u0e19<\/p>\n<p>\u0e0b\u0e36\u0e48\u0e07\u0e40\u0e2b\u0e15\u0e38\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e19\u0e49\u0e33\u0e17\u0e48\u0e27\u0e21\u0e04\u0e23\u0e31\u0e49\u0e07\u0e23\u0e49\u0e32\u0e22\u0e41\u0e23\u0e07\u0e43\u0e19\u0e40\u0e19\u0e1b\u0e32\u0e25\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e2a\u0e31\u0e1b\u0e14\u0e32\u0e2b\u0e4c\u0e17\u0e35\u0e48\u0e41\u0e25\u0e49\u0e27\u0e21\u0e35\u0e2a\u0e32\u0e40\u0e2b\u0e15\u0e38\u0e21\u0e32\u0e08\u0e32\u0e01\u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e18\u0e32\u0e23\u0e19\u0e49\u0e33\u0e41\u0e02\u0e47\u0e07\u0e43\u0e01\u0e25\u0e49\u0e01\u0e31\u0e1a\u0e22\u0e2d\u0e14\u0e40\u0e02\u0e32\u0e25\u0e31\u0e07\u0e15\u0e31\u0e07 \u0e25\u0e35\u0e23\u0e38\u0e07 (Langtang Lirung peak) \u0e1e\u0e31\u0e07\u0e17\u0e25\u0e32\u0e22\u0e25\u0e07\u0e2a\u0e39\u0e48\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e38\u0e1a\u0e40\u0e02\u0e32 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e14\u0e34\u0e19\u0e16\u0e25\u0e48\u0e21\u0e41\u0e25\u0e30\u0e04\u0e25\u0e37\u0e48\u0e19\u0e19\u0e49\u0e33\u0e17\u0e48\u0e27\u0e21\u0e44\u0e2b\u0e25\u0e1a\u0e48\u0e32\u0e25\u0e07\u0e21\u0e32\u0e15\u0e32\u0e21\u0e41\u0e21\u0e48\u0e19\u0e49\u0e33\u0e15\u0e23\u0e35\u0e28\u0e38\u0e25\u0e35<\/p>\n<figure id=\"attachment_40140\" aria-describedby=\"caption-attachment-40140\" style=\"width: 1000px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-40140\" src=\"https:\/\/storage-wp.naewna.com\/2026\/09\/2026-09-02T092714Z_699627505_RC2XANA9P5NW_RTRMADP_3_NEPAL-FLOODS-CHINA.jpg\" alt=\"\" width=\"1000\" height=\"667\"><figcaption id=\"caption-attachment-40140\" class=\"wp-caption-text\">Photo : Reuters<\/figcaption><\/figure>\n<p>\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e07\u0e17\u0e25\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e17\u0e30\u0e40\u0e25\u0e2a\u0e32\u0e1a\u0e18\u0e32\u0e23\u0e19\u0e49\u0e33\u0e41\u0e02\u0e47\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e32\u0e01\u0e0f\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e41\u0e15\u0e01\u0e15\u0e48\u0e32\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e40\u0e25\u0e47\u0e01\u0e19\u0e49\u0e2d\u0e22 \u0e42\u0e14\u0e22\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e19\u0e49\u0e33\u0e08\u0e32\u0e01\u0e18\u0e32\u0e23\u0e19\u0e49\u0e33\u0e41\u0e02\u0e47\u0e07\u0e17\u0e35\u0e48\u0e25\u0e30\u0e25\u0e32\u0e22\u0e2a\u0e30\u0e2a\u0e21\u0e2d\u0e22\u0e39\u0e48\u0e14\u0e49\u0e32\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e2a\u0e34\u0e48\u0e07\u0e01\u0e35\u0e14\u0e02\u0e27\u0e32\u0e07\u0e17\u0e32\u0e07\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 \u0e41\u0e25\u0e30\u0e43\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e41\u0e23\u0e07\u0e14\u0e31\u0e19\u0e08\u0e30\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e01\u0e32\u0e23\u0e41\u0e15\u0e01\u0e2b\u0e23\u0e37\u0e2d \u0e25\u0e49\u0e19 \u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e19\u0e49\u0e33\u0e17\u0e48\u0e27\u0e21\u0e09\u0e31\u0e1a\u0e1e\u0e25\u0e31\u0e19\u0e44\u0e2b\u0e25\u0e14\u0e34\u0e48\u0e07\u0e25\u0e07\u0e2a\u0e39\u0e48\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e15\u0e48\u0e33<\/p>\n<p>\u0e42\u0e14\u0e22\u0e20\u0e31\u0e22\u0e04\u0e38\u0e01\u0e04\u0e32\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e2d\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e01\u0e33\u0e25\u0e31\u0e07\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19 \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e20\u0e32\u0e27\u0e30\u0e42\u0e25\u0e01\u0e23\u0e49\u0e2d\u0e19\u0e40\u0e23\u0e48\u0e07\u0e43\u0e2b\u0e49\u0e18\u0e32\u0e23\u0e19\u0e49\u0e33\u0e41\u0e02\u0e47\u0e07\u0e43\u0e19\u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04\u0e25\u0e30\u0e25\u0e32\u0e22 \u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e43\u0e2b\u0e49\u0e2b\u0e34\u0e19\u0e2b\u0e25\u0e27\u0e21\u0e41\u0e25\u0e30\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e23\u0e07\u0e01\u0e14\u0e14\u0e31\u0e19\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19\u0e15\u0e48\u0e2d\u0e41\u0e19\u0e27\u0e01\u0e31\u0e49\u0e19\u0e17\u0e30\u0e40\u0e25\u0e2a\u0e32\u0e1a\u0e18\u0e32\u0e23\u0e19\u0e49\u0e33\u0e41\u0e02\u0e47\u0e07 \u0e0b\u0e36\u0e48\u0e07 \u0e20\u0e39\u0e40\u0e02\u0e32\u0e43\u0e19\u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04\u0e19\u0e35\u0e49\u0e04\u0e48\u0e2d\u0e19\u0e02\u0e49\u0e32\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e08\u0e36\u0e07\u0e21\u0e35\u0e41\u0e19\u0e27\u0e42\u0e19\u0e49\u0e21\u0e17\u0e35\u0e48\u0e08\u0e30\u0e40\u0e01\u0e34\u0e14\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e17\u0e32\u0e07\u0e18\u0e23\u0e13\u0e35\u0e27\u0e34\u0e17\u0e22\u0e32\u0e44\u0e14\u0e49\u0e07\u0e48\u0e32\u0e22\u0e01\u0e27\u0e48\u0e32 \u0e0b\u0e36\u0e48\u0e07\u0e2d\u0e32\u0e08\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e18\u0e32\u0e23\u0e19\u0e49\u0e33\u0e41\u0e02\u0e47\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e19\u0e27\u0e01\u0e31\u0e49\u0e19\u0e17\u0e30\u0e40\u0e25\u0e2a\u0e32\u0e1a\u0e1e\u0e31\u0e07\u0e17\u0e25\u0e32\u0e22\u0e25\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e09\u0e31\u0e1a\u0e1e\u0e25\u0e31\u0e19\u0e44\u0e14\u0e49<\/p>\n<p>\u0e0b\u0e36\u0e48\u0e07\u0e19\u0e31\u0e01\u0e27\u0e34\u0e08\u0e31\u0e22\u0e04\u0e49\u0e19\u0e1e\u0e1a\u0e17\u0e30\u0e40\u0e25\u0e2a\u0e32\u0e1a\u0e18\u0e32\u0e23\u0e19\u0e49\u0e33\u0e41\u0e02\u0e47\u0e07\u0e17\u0e35\u0e48\u0e2d\u0e32\u0e08\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e31\u0e19\u0e15\u0e23\u0e32\u0e22\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e27\u0e49\u0e32\u0e07\u0e43\u0e2b\u0e0d\u0e48\u0e02\u0e2d\u0e07\u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04\u0e40\u0e17\u0e37\u0e2d\u0e01\u0e40\u0e02\u0e32\u0e2e\u0e34\u0e19\u0e14\u0e39\u0e01\u0e38\u0e0a \u0e0b\u0e36\u0e48\u0e07 '\u0e19\u0e32\u0e07\u0e04\u0e32\u0e19\u0e19\u0e35 \u0e27\u0e34\u0e01\u0e19\u0e23\u0e32\u0e0a\u0e32' \u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32 \u0e44\u0e21\u0e48\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e43\u0e14\u0e43\u0e19\u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04\u0e19\u0e35\u0e49\u0e17\u0e35\u0e48\u0e1e\u0e36\u0e48\u0e07\u0e1e\u0e32\u0e18\u0e32\u0e23\u0e19\u0e49\u0e33\u0e41\u0e02\u0e47\u0e07\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e14\u0e49\u0e32\u0e19\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e19\u0e49\u0e33\u0e41\u0e25\u0e30\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e21\u0e32\u0e01\u0e44\u0e1b\u0e01\u0e27\u0e48\u0e32\u0e40\u0e19\u0e1b\u0e32\u0e25 \u0e02\u0e13\u0e30\u0e19\u0e35\u0e49\u0e01\u0e33\u0e25\u0e31\u0e07\u0e40\u0e1c\u0e0a\u0e34\u0e0d\u0e01\u0e31\u0e1a \"\u0e17\u0e32\u0e07\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e17\u0e35\u0e48\u0e22\u0e32\u0e01\u0e25\u0e33\u0e1a\u0e32\u0e01\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e34\u0e48\u0e07\" \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e2d\u0e22\u0e39\u0e48\u0e23\u0e34\u0e21\u0e41\u0e21\u0e48\u0e19\u0e49\u0e33 \u0e01\u0e32\u0e23\u0e22\u0e49\u0e32\u0e22\u0e44\u0e1b\u0e22\u0e31\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e39\u0e07\u0e01\u0e27\u0e48\u0e32\u0e2d\u0e32\u0e08\u0e44\u0e21\u0e48\u0e04\u0e38\u0e49\u0e21\u0e04\u0e48\u0e32\u0e43\u0e19\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08<\/p>\n<figure id=\"attachment_40141\" aria-describedby=\"caption-attachment-40141\" style=\"width: 1000px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-40141\" src=\"https:\/\/storage-wp.naewna.com\/2026\/09\/2026-09-02T094010Z_1342754754_RC2K9NAIVTIY_RTRMADP_3_NEPAL-FLOODS.jpg\" alt=\"\" width=\"1000\" height=\"667\"><figcaption id=\"caption-attachment-40141\" class=\"wp-caption-text\">Photo : Reuters<\/figcaption><\/figure>\n<p>\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e01\u0e47\u0e08\u0e30\u0e22\u0e31\u0e07\u0e04\u0e07\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e23\u0e32\u0e30\u0e1a\u0e32\u0e07 \u0e40\u0e0a\u0e48\u0e19\u0e01\u0e31\u0e19 \u0e01\u0e32\u0e23\u0e2a\u0e39\u0e0d\u0e40\u0e2a\u0e35\u0e22\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e40\u0e19\u0e1b\u0e32\u0e25\u0e2d\u0e32\u0e08\u0e23\u0e38\u0e19\u0e41\u0e23\u0e07\u0e01\u0e27\u0e48\u0e32\u0e17\u0e35\u0e48\u0e1a\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e23\u0e30\u0e1a\u0e38\u0e44\u0e27\u0e49 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e41\u0e2b\u0e48\u0e07\u0e2a\u0e2b\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e32\u0e15\u0e34 (UNDP) \u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32 \u0e19\u0e49\u0e33\u0e17\u0e48\u0e27\u0e21\u0e44\u0e14\u0e49\u0e17\u0e33\u0e25\u0e32\u0e22\u0e42\u0e23\u0e07\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e02\u0e19\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 15 \u0e41\u0e2b\u0e48\u0e07 \u0e19\u0e2d\u0e01\u0e40\u0e2b\u0e19\u0e37\u0e2d\u0e08\u0e32\u0e01\u0e42\u0e23\u0e07\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e35\u0e48\u0e01\u0e33\u0e25\u0e31\u0e07\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e2d\u0e22\u0e39\u0e48<\/p>\n<p>\"\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e25\u0e30\u0e42\u0e23\u0e07\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e1e\u0e25\u0e31\u0e07\u0e19\u0e49\u0e33\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e17\u0e19\u0e17\u0e32\u0e19\u0e15\u0e48\u0e2d\u0e2d\u0e38\u0e17\u0e01\u0e20\u0e31\u0e22\u0e44\u0e14\u0e49\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19\u0e14\u0e49\u0e27\u0e22\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e43\u0e2b\u0e21\u0e48 \u0e41\u0e15\u0e48 \"\u0e04\u0e25\u0e37\u0e48\u0e19\u0e42\u0e04\u0e25\u0e19\u0e41\u0e25\u0e30\u0e19\u0e49\u0e33\u0e41\u0e02\u0e47\u0e07\u0e16\u0e25\u0e48\u0e21\" \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e2a\u0e31\u0e1b\u0e14\u0e32\u0e2b\u0e4c\u0e17\u0e35\u0e48\u0e41\u0e25\u0e49\u0e27\u0e04\u0e07\u0e08\u0e30\u0e40\u0e2d\u0e32\u0e0a\u0e19\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e2b\u0e0d\u0e48\u0e17\u0e35\u0e48\u0e21\u0e35\u0e2d\u0e22\u0e39\u0e48\u0e44\u0e14\u0e49\"\u0e44\u0e21\u0e48\u0e21\u0e35\u0e2a\u0e34\u0e48\u0e07\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e43\u0e14\u0e17\u0e35\u0e48\u0e08\u0e30\u0e2b\u0e22\u0e38\u0e14\u0e22\u0e31\u0e49\u0e07\u0e2a\u0e34\u0e48\u0e07\u0e19\u0e35\u0e49\u0e44\u0e14\u0e49\" \u0e19\u0e32\u0e07\u0e04\u0e32\u0e19\u0e19\u0e35 \u0e27\u0e34\u0e01\u0e19\u0e23\u0e32\u0e0a\u0e32 \u0e01\u0e25\u0e48\u0e32\u0e27<\/p>\n<p>\u0e42\u0e14\u0e22\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e14\u0e49\u0e32\u0e19\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e19\u0e49\u0e33\u0e02\u0e2d\u0e07\u0e40\u0e19\u0e1b\u0e32\u0e25\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e08\u0e32\u0e01\u0e19\u0e49\u0e33\u0e17\u0e48\u0e27\u0e21\u0e2b\u0e19\u0e31\u0e01\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14 \u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e1a\u0e31\u0e01\u0e21\u0e32\u0e15\u0e35 \u0e0b\u0e36\u0e48\u0e07\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e08\u0e32\u0e01\u0e19\u0e49\u0e33\u0e17\u0e48\u0e27\u0e21\u0e2b\u0e19\u0e31\u0e01\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14 \u0e21\u0e35\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e1e\u0e25\u0e31\u0e07\u0e19\u0e49\u0e33\u0e17\u0e35\u0e48\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e44\u0e27\u0e49 \u0e2b\u0e23\u0e37\u0e2d \u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e2d\u0e22\u0e39\u0e48\u0e01\u0e27\u0e48\u0e32\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19\u0e2a\u0e32\u0e21\u0e08\u0e32\u0e01\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 261 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u0e42\u0e14\u0e22\u0e43\u0e19\u0e08\u0e33\u0e19\u0e27\u0e19\u0e19\u0e35\u0e49\u0e21\u0e35 10 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e21\u0e35\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32 100 \u0e40\u0e21\u0e01\u0e30\u0e27\u0e31\u0e15\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e35\u0e01 6 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23<\/p>\n<p>&nbsp;<\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>2 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2569 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e23\u0e2d\u0e22\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e2a \u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e27\u0e48\u0e32\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e23 [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":40137,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[241,3,11],"tags":[6167,4274,6166,6168],"class_list":["post-40121","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking","category-top-stories","category-international","tag-un","tag-4274","tag-6166","tag-6168"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u0e22\u0e39\u0e40\u0e2d\u0e47\u0e19\u0e0a\u0e35\u0e49\u0e2d\u0e19\u0e32\u0e04\u0e15 \u0e23\u0e30\u0e40\u0e1a\u0e34\u0e14\u0e40\u0e27\u0e25\u0e32\u0e18\u0e32\u0e23\u0e19\u0e49\u0e33\u0e41\u0e02\u0e47\u0e07\u0e40\u0e17\u0e37\u0e2d\u0e01\u0e40\u0e02\u0e32\u0e2b\u0e34\u0e21\u0e32\u0e25\u0e31\u0e22 \u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e20\u0e31\u0e22\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e23\u0e38\u0e19\u0e41\u0e23\u0e07\u0e0b\u0e49\u0e33 \u0e01\u0e23\u0e30\u0e17\u0e1a\u0e25\u0e49\u0e32\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e44\u0e23\u0e49\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.naewna.com\/n\/top-stories\/40121\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e22\u0e39\u0e40\u0e2d\u0e47\u0e19\u0e0a\u0e35\u0e49\u0e2d\u0e19\u0e32\u0e04\u0e15 \u0e23\u0e30\u0e40\u0e1a\u0e34\u0e14\u0e40\u0e27\u0e25\u0e32\u0e18\u0e32\u0e23\u0e19\u0e49\u0e33\u0e41\u0e02\u0e47\u0e07\u0e40\u0e17\u0e37\u0e2d\u0e01\u0e40\u0e02\u0e32\u0e2b\u0e34\u0e21\u0e32\u0e25\u0e31\u0e22 \u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e20\u0e31\u0e22\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e23\u0e38\u0e19\u0e41\u0e23\u0e07\u0e0b\u0e49\u0e33 \u0e01\u0e23\u0e30\u0e17\u0e1a\u0e25\u0e49\u0e32\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e44\u0e23\u0e49\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\" \/>\n<meta property=\"og:description\" content=\"2 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2569 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e23\u0e2d\u0e22\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e2a \u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e27\u0e48\u0e32\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e23 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.naewna.com\/n\/top-stories\/40121\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NaewnaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2026-09-02T14:03:55+00:00\" \/>\n<meta name=\"author\" content=\"\u0e41\u0e1b\u0e49\u0e07\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@naewna_news\" \/>\n<meta name=\"twitter:site\" content=\"@naewna_news\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u0e41\u0e1b\u0e49\u0e07\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/top-stories\\\/40121\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/top-stories\\\/40121\\\/\"},\"author\":{\"name\":\"\u0e41\u0e1b\u0e49\u0e07\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#\\\/schema\\\/person\\\/5362e0c26cf603386e05711b2c58b1fa\"},\"headline\":\"\u0e22\u0e39\u0e40\u0e2d\u0e47\u0e19\u0e0a\u0e35\u0e49\u0e2d\u0e19\u0e32\u0e04\u0e15 \u0e23\u0e30\u0e40\u0e1a\u0e34\u0e14\u0e40\u0e27\u0e25\u0e32\u0e18\u0e32\u0e23\u0e19\u0e49\u0e33\u0e41\u0e02\u0e47\u0e07\u0e40\u0e17\u0e37\u0e2d\u0e01\u0e40\u0e02\u0e32\u0e2b\u0e34\u0e21\u0e32\u0e25\u0e31\u0e22 \u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e20\u0e31\u0e22\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e23\u0e38\u0e19\u0e41\u0e23\u0e07\u0e0b\u0e49\u0e33 \u0e01\u0e23\u0e30\u0e17\u0e1a\u0e25\u0e49\u0e32\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e44\u0e23\u0e49\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\",\"datePublished\":\"2026-09-02T14:03:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/top-stories\\\/40121\\\/\"},\"wordCount\":24,\"image\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/top-stories\\\/40121\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/storage-wp.naewna.com\\\/2026\\\/09\\\/321-2.jpg\",\"keywords\":[\"UN\",\"\u0e18\u0e32\u0e23\u0e19\u0e49\u0e33\u0e41\u0e02\u0e47\u0e07\u0e2b\u0e34\u0e21\u0e32\u0e25\u0e31\u0e22\",\"\u0e22\u0e39\u0e40\u0e2d\u0e47\u0e19\",\"\u0e2a\u0e2b\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e32\u0e15\u0e34\"],\"articleSection\":[\"Breaking News\",\"\u0e02\u0e48\u0e32\u0e27\u0e40\u0e14\u0e48\u0e19\",\"\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\"],\"inLanguage\":\"th\",\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/top-stories\\\/40121\\\/\",\"url\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/top-stories\\\/40121\\\/\",\"name\":\"\u0e22\u0e39\u0e40\u0e2d\u0e47\u0e19\u0e0a\u0e35\u0e49\u0e2d\u0e19\u0e32\u0e04\u0e15 \u0e23\u0e30\u0e40\u0e1a\u0e34\u0e14\u0e40\u0e27\u0e25\u0e32\u0e18\u0e32\u0e23\u0e19\u0e49\u0e33\u0e41\u0e02\u0e47\u0e07\u0e40\u0e17\u0e37\u0e2d\u0e01\u0e40\u0e02\u0e32\u0e2b\u0e34\u0e21\u0e32\u0e25\u0e31\u0e22 \u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e20\u0e31\u0e22\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e23\u0e38\u0e19\u0e41\u0e23\u0e07\u0e0b\u0e49\u0e33 \u0e01\u0e23\u0e30\u0e17\u0e1a\u0e25\u0e49\u0e32\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e44\u0e23\u0e49\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/top-stories\\\/40121\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/top-stories\\\/40121\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/storage-wp.naewna.com\\\/2026\\\/09\\\/321-2.jpg\",\"datePublished\":\"2026-09-02T14:03:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#\\\/schema\\\/person\\\/5362e0c26cf603386e05711b2c58b1fa\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/top-stories\\\/40121\\\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.naewna.com\\\/n\\\/top-stories\\\/40121\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/top-stories\\\/40121\\\/#primaryimage\",\"url\":\"https:\\\/\\\/storage-wp.naewna.com\\\/2026\\\/09\\\/321-2.jpg\",\"contentUrl\":\"https:\\\/\\\/storage-wp.naewna.com\\\/2026\\\/09\\\/321-2.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/top-stories\\\/40121\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e22\u0e39\u0e40\u0e2d\u0e47\u0e19\u0e0a\u0e35\u0e49\u0e2d\u0e19\u0e32\u0e04\u0e15 \u0e23\u0e30\u0e40\u0e1a\u0e34\u0e14\u0e40\u0e27\u0e25\u0e32\u0e18\u0e32\u0e23\u0e19\u0e49\u0e33\u0e41\u0e02\u0e47\u0e07\u0e40\u0e17\u0e37\u0e2d\u0e01\u0e40\u0e02\u0e32\u0e2b\u0e34\u0e21\u0e32\u0e25\u0e31\u0e22 \u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e20\u0e31\u0e22\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e23\u0e38\u0e19\u0e41\u0e23\u0e07\u0e0b\u0e49\u0e33 \u0e01\u0e23\u0e30\u0e17\u0e1a\u0e25\u0e49\u0e32\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e44\u0e23\u0e49\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#website\",\"url\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/\",\"name\":\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#\\\/schema\\\/person\\\/5362e0c26cf603386e05711b2c58b1fa\",\"name\":\"\u0e41\u0e1b\u0e49\u0e07\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/788f5c47b15b2178e20f91823dd12ffc35bd54be3e53a39dc650a809efb20565?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/788f5c47b15b2178e20f91823dd12ffc35bd54be3e53a39dc650a809efb20565?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/788f5c47b15b2178e20f91823dd12ffc35bd54be3e53a39dc650a809efb20565?s=96&d=mm&r=g\",\"caption\":\"\u0e41\u0e1b\u0e49\u0e07\"},\"url\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/author\\\/ppmnt\\\/\"}]}<\/script>\n<meta property=\"article:section\" content=\"Breaking News\" \/>\n<meta property=\"article:section\" content=\"\u0e02\u0e48\u0e32\u0e27\u0e40\u0e14\u0e48\u0e19\" \/>\n<meta property=\"article:section\" content=\"\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u0e22\u0e39\u0e40\u0e2d\u0e47\u0e19\u0e0a\u0e35\u0e49\u0e2d\u0e19\u0e32\u0e04\u0e15 \u0e23\u0e30\u0e40\u0e1a\u0e34\u0e14\u0e40\u0e27\u0e25\u0e32\u0e18\u0e32\u0e23\u0e19\u0e49\u0e33\u0e41\u0e02\u0e47\u0e07\u0e40\u0e17\u0e37\u0e2d\u0e01\u0e40\u0e02\u0e32\u0e2b\u0e34\u0e21\u0e32\u0e25\u0e31\u0e22 \u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e20\u0e31\u0e22\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e23\u0e38\u0e19\u0e41\u0e23\u0e07\u0e0b\u0e49\u0e33 \u0e01\u0e23\u0e30\u0e17\u0e1a\u0e25\u0e49\u0e32\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e44\u0e23\u0e49\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.naewna.com\/n\/top-stories\/40121\/","og_locale":"th_TH","og_type":"article","og_title":"\u0e22\u0e39\u0e40\u0e2d\u0e47\u0e19\u0e0a\u0e35\u0e49\u0e2d\u0e19\u0e32\u0e04\u0e15 \u0e23\u0e30\u0e40\u0e1a\u0e34\u0e14\u0e40\u0e27\u0e25\u0e32\u0e18\u0e32\u0e23\u0e19\u0e49\u0e33\u0e41\u0e02\u0e47\u0e07\u0e40\u0e17\u0e37\u0e2d\u0e01\u0e40\u0e02\u0e32\u0e2b\u0e34\u0e21\u0e32\u0e25\u0e31\u0e22 \u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e20\u0e31\u0e22\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e23\u0e38\u0e19\u0e41\u0e23\u0e07\u0e0b\u0e49\u0e33 \u0e01\u0e23\u0e30\u0e17\u0e1a\u0e25\u0e49\u0e32\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e44\u0e23\u0e49\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48","og_description":"2 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2569 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e23\u0e2d\u0e22\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e2a \u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e27\u0e48\u0e32\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e23 [&hellip;]","og_url":"https:\/\/www.naewna.com\/n\/top-stories\/40121\/","og_site_name":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32","article_publisher":"https:\/\/www.facebook.com\/NaewnaOnline","article_published_time":"2026-09-02T14:03:55+00:00","author":"\u0e41\u0e1b\u0e49\u0e07","twitter_card":"summary_large_image","twitter_creator":"@naewna_news","twitter_site":"@naewna_news","twitter_misc":{"Written by":"\u0e41\u0e1b\u0e49\u0e07"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.naewna.com\/n\/top-stories\/40121\/#article","isPartOf":{"@id":"https:\/\/www.naewna.com\/n\/top-stories\/40121\/"},"author":{"name":"\u0e41\u0e1b\u0e49\u0e07","@id":"https:\/\/www.naewna.com\/n\/#\/schema\/person\/5362e0c26cf603386e05711b2c58b1fa"},"headline":"\u0e22\u0e39\u0e40\u0e2d\u0e47\u0e19\u0e0a\u0e35\u0e49\u0e2d\u0e19\u0e32\u0e04\u0e15 \u0e23\u0e30\u0e40\u0e1a\u0e34\u0e14\u0e40\u0e27\u0e25\u0e32\u0e18\u0e32\u0e23\u0e19\u0e49\u0e33\u0e41\u0e02\u0e47\u0e07\u0e40\u0e17\u0e37\u0e2d\u0e01\u0e40\u0e02\u0e32\u0e2b\u0e34\u0e21\u0e32\u0e25\u0e31\u0e22 \u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e20\u0e31\u0e22\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e23\u0e38\u0e19\u0e41\u0e23\u0e07\u0e0b\u0e49\u0e33 \u0e01\u0e23\u0e30\u0e17\u0e1a\u0e25\u0e49\u0e32\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e44\u0e23\u0e49\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48","datePublished":"2026-09-02T14:03:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.naewna.com\/n\/top-stories\/40121\/"},"wordCount":24,"image":{"@id":"https:\/\/www.naewna.com\/n\/top-stories\/40121\/#primaryimage"},"thumbnailUrl":"https:\/\/storage-wp.naewna.com\/2026\/09\/321-2.jpg","keywords":["UN","\u0e18\u0e32\u0e23\u0e19\u0e49\u0e33\u0e41\u0e02\u0e47\u0e07\u0e2b\u0e34\u0e21\u0e32\u0e25\u0e31\u0e22","\u0e22\u0e39\u0e40\u0e2d\u0e47\u0e19","\u0e2a\u0e2b\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e32\u0e15\u0e34"],"articleSection":["Breaking News","\u0e02\u0e48\u0e32\u0e27\u0e40\u0e14\u0e48\u0e19","\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28"],"inLanguage":"th","copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/www.naewna.com\/n\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.naewna.com\/n\/top-stories\/40121\/","url":"https:\/\/www.naewna.com\/n\/top-stories\/40121\/","name":"\u0e22\u0e39\u0e40\u0e2d\u0e47\u0e19\u0e0a\u0e35\u0e49\u0e2d\u0e19\u0e32\u0e04\u0e15 \u0e23\u0e30\u0e40\u0e1a\u0e34\u0e14\u0e40\u0e27\u0e25\u0e32\u0e18\u0e32\u0e23\u0e19\u0e49\u0e33\u0e41\u0e02\u0e47\u0e07\u0e40\u0e17\u0e37\u0e2d\u0e01\u0e40\u0e02\u0e32\u0e2b\u0e34\u0e21\u0e32\u0e25\u0e31\u0e22 \u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e20\u0e31\u0e22\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e23\u0e38\u0e19\u0e41\u0e23\u0e07\u0e0b\u0e49\u0e33 \u0e01\u0e23\u0e30\u0e17\u0e1a\u0e25\u0e49\u0e32\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e44\u0e23\u0e49\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32","isPartOf":{"@id":"https:\/\/www.naewna.com\/n\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.naewna.com\/n\/top-stories\/40121\/#primaryimage"},"image":{"@id":"https:\/\/www.naewna.com\/n\/top-stories\/40121\/#primaryimage"},"thumbnailUrl":"https:\/\/storage-wp.naewna.com\/2026\/09\/321-2.jpg","datePublished":"2026-09-02T14:03:55+00:00","author":{"@id":"https:\/\/www.naewna.com\/n\/#\/schema\/person\/5362e0c26cf603386e05711b2c58b1fa"},"breadcrumb":{"@id":"https:\/\/www.naewna.com\/n\/top-stories\/40121\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.naewna.com\/n\/top-stories\/40121\/"]}]},{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.naewna.com\/n\/top-stories\/40121\/#primaryimage","url":"https:\/\/storage-wp.naewna.com\/2026\/09\/321-2.jpg","contentUrl":"https:\/\/storage-wp.naewna.com\/2026\/09\/321-2.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.naewna.com\/n\/top-stories\/40121\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.naewna.com\/n\/"},{"@type":"ListItem","position":2,"name":"\u0e22\u0e39\u0e40\u0e2d\u0e47\u0e19\u0e0a\u0e35\u0e49\u0e2d\u0e19\u0e32\u0e04\u0e15 \u0e23\u0e30\u0e40\u0e1a\u0e34\u0e14\u0e40\u0e27\u0e25\u0e32\u0e18\u0e32\u0e23\u0e19\u0e49\u0e33\u0e41\u0e02\u0e47\u0e07\u0e40\u0e17\u0e37\u0e2d\u0e01\u0e40\u0e02\u0e32\u0e2b\u0e34\u0e21\u0e32\u0e25\u0e31\u0e22 \u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e20\u0e31\u0e22\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e23\u0e38\u0e19\u0e41\u0e23\u0e07\u0e0b\u0e49\u0e33 \u0e01\u0e23\u0e30\u0e17\u0e1a\u0e25\u0e49\u0e32\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e44\u0e23\u0e49\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48"}]},{"@type":"WebSite","@id":"https:\/\/www.naewna.com\/n\/#website","url":"https:\/\/www.naewna.com\/n\/","name":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.naewna.com\/n\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"},{"@type":"Person","@id":"https:\/\/www.naewna.com\/n\/#\/schema\/person\/5362e0c26cf603386e05711b2c58b1fa","name":"\u0e41\u0e1b\u0e49\u0e07","image":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/secure.gravatar.com\/avatar\/788f5c47b15b2178e20f91823dd12ffc35bd54be3e53a39dc650a809efb20565?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/788f5c47b15b2178e20f91823dd12ffc35bd54be3e53a39dc650a809efb20565?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/788f5c47b15b2178e20f91823dd12ffc35bd54be3e53a39dc650a809efb20565?s=96&d=mm&r=g","caption":"\u0e41\u0e1b\u0e49\u0e07"},"url":"https:\/\/www.naewna.com\/n\/author\/ppmnt\/"}]}},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/storage-wp.naewna.com\/2026\/09\/321-2.jpg","_links":{"self":[{"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/posts\/40121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/comments?post=40121"}],"version-history":[{"count":2,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/posts\/40121\/revisions"}],"predecessor-version":[{"id":40144,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/posts\/40121\/revisions\/40144"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/media\/40137"}],"wp:attachment":[{"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/media?parent=40121"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/categories?post=40121"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/tags?post=40121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}