{"id":5940,"count":1,"description":"","link":"https:\/\/www.naewna.com\/n\/tag\/%e0%b9%80%e0%b8%87%e0%b8%b4%e0%b8%99%e0%b8%9a%e0%b8%b2%e0%b8%97\/","name":"\u0e40\u0e07\u0e34\u0e19\u0e1a\u0e32\u0e17","slug":"%e0%b9%80%e0%b8%87%e0%b8%b4%e0%b8%99%e0%b8%9a%e0%b8%b2%e0%b8%97","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:site_name\" content=\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@naewna_news\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":false,\"url\":\"\",\"name\":\"\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#website\"},\"inLanguage\":\"th\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/#website\",\"url\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/\",\"name\":\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.naewna.com\\\/n\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32","robots":{"index":"noindex","follow":"follow"},"og_locale":"th_TH","og_type":"article","og_site_name":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32","twitter_card":"summary_large_image","twitter_site":"@naewna_news","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":false,"url":"","name":"","isPartOf":{"@id":"https:\/\/www.naewna.com\/n\/#website"},"inLanguage":"th"},{"@type":"WebSite","@id":"https:\/\/www.naewna.com\/n\/#website","url":"https:\/\/www.naewna.com\/n\/","name":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27\u0e41\u0e19\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e07\u0e44\u0e1b \u0e15\u0e23\u0e07\u0e21\u0e32","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.naewna.com\/n\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"}]}},"_links":{"self":[{"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/tags\/5940","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.naewna.com\/n\/wp-json\/wp\/v2\/posts?tags=5940"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}